{"id":31237,"date":"2014-03-13T08:35:53","date_gmt":"2014-03-13T07:35:53","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=31237"},"modified":"2016-07-26T16:58:23","modified_gmt":"2016-07-26T14:58:23","slug":"relaciones-con-el-islam-en-tiempos-de-san-vicente","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/","title":{"rendered":"Relaciones con el Islam en tiempos de san Vicente"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/03\/islam.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-31240\" title=\"islam\" alt=\"\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/03\/islam-300x300.jpg?resize=300%2C300\" width=\"300\" height=\"300\" \/><\/a>San Vicente se encontr\u00f3 muy pronto con el hecho del Islam. Nosotros no entraremos en la delicada cuesti\u00f3n de la historicidad integral de los hechos \u00abrelatados con un estilo fascinante\u00bb tales como son los referidos en las dos cartas del Padre Vicente al Sr. de Comet (1607 y 1608). El P. Dodin,<span id='easy-footnote-1-31237' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/#easy-footnote-bottom-1-31237' title='DODIN A.. \u00abDepaul a saint Vincent de Paul\u00bb, O.E.I.L. Histoire. Par\u00eds pp. 144-145.'><sup>1<\/sup><\/a><\/span> despu\u00e9s\u00a0 de Coste, da raz\u00f3n de eso. Sin embargo, una cosa es cierta. Esas cartas traducen una especie de obsesi\u00f3n por el Islam, que se le presenta bajo la cara de ciertas personas: los piratas, \u00absu amo,\u00bb \u00abturca de nacimiento\u00bb, tales como \u00e9l se las representaba. Habitado por la pasi\u00f3n del Evangelio, antes de que lo fuera m\u00e1s tarde, bajo la presi\u00f3n del Acontecimiento, por el \u00abCristo evangelizador de los pobres\u00bb, el joven sacerdote Vicente ten\u00eda que tropezarse con la incre\u00edble brecha del Islam. De tierras de presencia masiva cristiana, hab\u00eda hecho, en Oriente, t\u00ederras de presencia masiva musulmana. \u00bfC\u00f3mo de unas regiones, como el Maghreb, hab\u00edan podido extenderse, como impulsadas por un destino ineluctable y ciego? Sin embargo, aquellas tierras hab\u00edan sido ilustradas por grandes campeones de la fe, tales como Tertuliano (+155), Cipriano (+260), Agust\u00edn (+430). En frase de Tertuliano, unos m\u00e1rtires hab\u00edan derramado su sangre, que \u00abhab\u00eda sido semilla de cristianos\u00bb, tales como el di\u00e1cono Santiago, el lector Marciano, Nemesiano y Maximiliano, Crispina y Marciana, Priscila y Aquilea y sus compa\u00f1eros y tantos otros innumerables. Un n\u00famero considerable de obispados, que hab\u00edan llegado, a la muerte de Cipriano a cerca de 700, hab\u00edan florecido all\u00ed. El Maghreb hab\u00eda dado Papas a la Iglesia, tales como V\u00edctor (189-199), Milc\u00edades (311-314), Gelasio (492-496). Vicente no pod\u00eda menos de quedar \u00abtrastornado\u00bb igual que la tierra lo es por el arado. Los cristianos, all\u00ed abajo, en los \u00abba\u00f1os\u00bb, en tierras del Islam (\u00abdar el-Islam\u00bb) sufren y mueren. Pero vengamos a los hechos.<\/p>\n<p style=\"text-align: justify\">\n<h2 style=\"text-align: justify\"><strong>OJEADA HIST\u00d3RICA<\/strong><\/h2>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">El a\u00f1o 633 el Islam parte a la conquista de lo que se llama \u00abel creciente f\u00e9rtil\u00bb, y que en cuesti\u00f3n de 12 a\u00f1os, de 633 a 645, llega a ser tierra del \u00abCreciente\u00bb.<\/p>\n<p style=\"text-align: justify\">A partir de 647, los \u00e1rabes, en oleadas sucesivas, penetran en \u00c1frica del Norte. Ayudados, desde el siglo VIII por los ber\u00e9beres, van a conquistar, entre 695 y 708, todo el Maghreb, atraviesan el estrecho de Gibraltar (Jabal T\u00e1riq = la monta\u00f1a de T\u00e1riq) bajo el mando precisamente del ber\u00e9ber T\u00e1riq ibn Ziyad (711), ocupan C\u00f3rdoba, despu\u00e9s Toledo y llegan hasta el mismo Poitiers (732).<\/p>\n<p style=\"text-align: justify\">En el siglo XVII son los otomanos, descendientes de una peque\u00f1a tribu turca (\u00abbani Uthm\u00e0n\u00bb) los que extend\u00edan su supremac\u00eda sobre el Imperio musulm\u00e1n, tanto en Oriente como en Occidente. Estos, despu\u00e9s de haber derrotado, en el siglo XIV, a los Abasidas, hab\u00edan repetido la epopeya musulmana y se hab\u00edan hecho los campeones del Islam. Su hegemon\u00eda se extend\u00eda, en el Este, desde Arabia hasta China; en el Oeste, desde Egipto hasta el Oc\u00e9ano; en el Norte, sobre los Balkanes, desde donde amenazan a Europa. El Mediterr\u00e1neo se hab\u00eda hecho \u00ab<em>lago del Islam<\/em>\u00ab;<span id='easy-footnote-2-31237' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/#easy-footnote-bottom-2-31237' title='PIRENNE H., \u00abMahomet et Charlomagne,, P.U.F. Par\u00eds, 1970, p.215.'><sup>2<\/sup><\/a><\/span> aqu\u00ed los corsarios surcaban las aguas arrebatando bienes y personas como para demostrar, orgullosamente, la superioridad de la civilizaci\u00f3n musulmana sobre la civilizaci\u00f3n cristiana y, en primer lugar, sobre el Imperio espa\u00f1ol entonces en su apogeo. El fen\u00f3meno de su ascenso alcanzar\u00e1 su apogeo entre 1577 (despu\u00e9s de Lepanto) y 1713-1720 (despu\u00e9s del tratado de Utrecht), asegurando a las chusmas musulmanas metales preciosos y hombres y proporcionar rescates.<\/p>\n<p style=\"text-align: justify\">Conviene notar que la expansi\u00f3n otomana revisti\u00f3, desde sus comienzos, unos caracteres nuevos espec\u00edficos. Ante todo, la conquista se realiz\u00f3 en nombre de la propagaci\u00f3n del Islam en territorio infiel (dar el-darb). Para llevar a cabo esta conquista los otomanos dispusieron de un ej\u00e9rcito que estaba animado del esp\u00edritu de <em>ghazi<\/em> (conquista religiosa). Y que fue, en consecuencia, constitu\u00edda a base de la <em>devchirm\u00e9<\/em> (leva forzosa) de j\u00f3venes cristianos arrancados a sus familias, y despu\u00e9s islamizados y turquizados: \u00e9stos son los jen\u00edzaros (<em>j\u00e9ni tch\u00e9ri<\/em>: la nueva tropa), que aseguraron durante m\u00e1s de dos siglos la supremac\u00eda de los ej\u00e9rcitos otomanos.<\/p>\n<p style=\"text-align: justify\">En el siglo XVI, ocurren dos acontecimientos de la m\u00e1s alta categor\u00eda hist\u00f3rica. Uno se refiere al (sultan Selim (1512-1520), que conquista el t\u00edtulo de Califa (palabra derivada del \u00e1rabe <em>kh\u00e9lifa<\/em> = lugartenencia) sin titular desde la ca\u00edda de Granada en 1492; y el otro, la toma de Argel por el pirata turco Arudj, llamado Barbarroja, que le abre las puertas de Argelia toda entera (1516). Su sucesor, Kheyredin Barbarroja, extender\u00e1 la conquista hasta el Mediterr\u00e1neo Occidental y entregar\u00e1 este mar a las pirater\u00edas de los corsarios berberiscos.<\/p>\n<p style=\"text-align: justify\">A su llegada al poder, el sult\u00e1n Solim\u00e1n el Magn\u00edfico (1520-1566, hijo de Selim), se apodera de una parte de \u00c1frica del Norte, alcanza, en Europa, el Adri\u00e1tico, los arrabales de Viena y las fronteras de Polonia. Pero dos acontecimientos mayores, dos victorias, una mar\u00edtima, Lepanto (1571), es conseguida por las armadas aliadas del Papa, del rey de Espa\u00f1a y de Venecia. Lo cual lleva a los turcos a vengarse tomando T\u00fanez a los espa\u00f1oles (1574). Y el otro terrestre, que no ocurrir\u00e1 hasta 1683. Gracias a la intervenci\u00f3n de la caballer\u00eda polaca mandada por Juan Sobieski, se obligar\u00e1 a los turcos a levantar el sitio de Viena. Dos victorias que van a obstaculizar la marcha, hasta entonces triunfante, del Islam, y a expulsar a los turcos de Hungr\u00eda.<\/p>\n<p style=\"text-align: justify\">En el Maghreb, la presencia cristiana estaba reducida, desde el siglo XII, a los comerciantes, a los cautivos prisioneros del \u00abcorso\u00bb: genoveses, pisanos, florentinos, venecianos, franceses. Exist\u00edan en las costas establecimientos permanentes que pertenec\u00edan a las naciones cristianas. En ellas resid\u00edan representantes de comercio y c\u00f3nsules para proteger los intereses de dichas naciones y para dirigir sus asuntos. Hab\u00eda capellanes afectos a esas bases, al servicio de los c\u00f3nsules, de los comerciantes y tambi\u00e9n, eventualmente, cristianos cautivos en los \u00abba\u00f1os\u00bb de T\u00fanez y de Argel.<\/p>\n<p style=\"text-align: justify\">En el siglo XIII hab\u00edan llegado a T\u00fanez los primeros franciscanos (1219), seguidos por los dominicos (1234), a quienes se unieron los trinitarios de san Juan de Mata y los mercedarios de san Pedro Nolasco, fundados unos y otros expresamente para la \u00abredenci\u00f3n de los cautivos\u00bb.<\/p>\n<p style=\"text-align: justify\">En el siglo XVI los espa\u00f1oles se instalan en el Oranesado con la toma de Or\u00e1n (1509) y de Bug\u00eda (1510). Presencia que deb\u00eda perdurar en \u00c1frica del Norte hasta fines del siglo XVIII.<\/p>\n<p style=\"text-align: justify\">Como f\u00e1cilmente se puede pensar, las relaciones con el Islam variaban seg\u00fan las alternativas de los intereses econ\u00f3micos y de las versatilidades pol\u00edticas. En cuanto a la poblaci\u00f3n aut\u00f3ctona no ten\u00eda para los cristianos, a los que hab\u00eda clasificado en tres categorias: latinos, rum\u00edes (bizantinos) y afariqa (aut\u00f3ctonos), m\u00e1s que un soberano desprecio. La memoria colectiva guardaba anclada dentro de s\u00ed el recuerdo de las exacciones \u00abespantosas\u00bb cometidas por los \u00abfrancos\u00bb contra los musulmanes en tiempo de las cruzadas (1096-1270). Y tambi\u00e9n el recuerdo de la represi\u00f3n ejercida por la Reconquista, que expuls\u00f3 a los musulmanes fuera de Espa\u00f1a. A mediados del siglo XIII, los musulmanes no conservaban m\u00e1s que el reino de Granada que deb\u00eda resistir hasta fines del siglo XV. Como tambi\u00e9n recordaba con viveza la memoria de las empresas guerreras de los reyes normandos de Italia del Sur y de Sicilia, que hab\u00edan llevado la guerra al \u00c1frica, sin descontar los \u00e9xitos negociados, as\u00ed como de las empresas guerreras llevadas a cabo por el rey de Francia, san Luis, en Egipto y en T\u00fanez.<\/p>\n<p style=\"text-align: justify\">La imaginaci\u00f3n cristiana, tambi\u00e9n ella, estaba marcada por las persecuciones a las que hab\u00edan sido sometidas las poblaciones cristianas de Oriente. Selim I, en el siglo XVI, \u00bfno hab\u00eda ideado el plan de prohibir la religi\u00f3n cristiana y de condenar a muerte a los cristianos que se negaran a convertise? No lleg\u00f3 a eso. Pero decret\u00f3 que todas las iglesias que estuvieran entonces abiertas en Constantinopla deb\u00edan ser convertidas en mezquitas. Las iglesias nuevas que construyeran los cristianos deb\u00edan ser de madera. Ya un predecesor, Mohamet II, hab\u00eda transformado en mezquitas las principales iglesias de la ciudad, entre ellas la de Santa Sof\u00eda. En 1562, la bas\u00edlica de los Ap\u00f3stoles, en donde reposaban los restos de Constantino, fue destru\u00edda. Si se mantuvieron algunas iglesias, fue gracias a las ingentes cantidades de dinero que pagaron los cristianos. En 1595, les toc\u00f3 la vez a las iglesias de Qu\u00edo; lo cual provoc\u00f3 la intervenci\u00f3n de Francia.<\/p>\n<p style=\"text-align: justify\">No se pod\u00eda tampoco ignorar la condici\u00f3n de los cristianos de Oriente sometidos a la condici\u00f3n de <em>dhimmitud<\/em> (\u00abbajo tutela musulmana\u00bb). Los <em>dhimm\u00edes<\/em> <em> <\/em>estaban sometidos a la ley cor\u00e1nica. Considerados como ciudadanos de segunda clase, deb\u00edan pagar un impuesto especial, la <em>jizya<\/em> ; deb\u00edan llevar un turbante y un cintur\u00f3n distintivos, de color amarillo que los expon\u00eda a la irrisi\u00f3n de los transe\u00fantes; s\u00f3lo podian viajar montados en burro (el caballo era considerado como un animal noble reservado a los musulmanes); deb\u00edan ceder la acera ante un musulm\u00e1n; no pod\u00edan atestiguar contra un musulm\u00e1n ante un tribunal, ni pod\u00edan ser reclutados para los ej\u00e9rcitos&#8230;<\/p>\n<p style=\"text-align: justify\">A\u00f1\u00e1danse a esto las posiciones dogm\u00e1ticas bien tajantes de unos y otros. \u00ab<em>Fuera de la Iglesia no hay salvaci\u00f3n<\/em>\u00ab. A la cual respond\u00eda la afirmaci\u00f3n contraria: <em>\u00abNo hay salvaci\u00f3n fuera de la Umma\u00bb<\/em>.<\/p>\n<p style=\"text-align: justify\">Para juzgar acerca de las relaciones que exist\u00edan entre las dos comunidades, es necesario tener en consideraci\u00f3n las relaciones de interferencia y analizar los contenidos de la realidad humana. Es en el espesor de esos conflictos y de esas oposiciones hist\u00f3ricas donde se enraizan, en el siglo XVII, las relaciones interreligiosas. Realidades que gravan las relaciones de serenidad e imponen estrategias que se alimentan en las competiciones ideol\u00f3gicas y religiosas, econ\u00f3micas y pol\u00edticas. Era todav\u00eda muy largo el camino que conducir\u00eda hacia las nuevas orillas del Vaticano II.<\/p>\n<p style=\"text-align: justify\">\n<h2 style=\"text-align: justify\"><strong>ACTITUD DE SAN VICENTE Y DE LOS MISIONEROS PARA CON LOS MUSULMANES<\/strong><\/h2>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Es pues en este contexto, bien delimitado, donde se le va a plantear a san Vicente el problema de la presencia misionera en tierras del Islam. Cierto, no, expresamente, para rescatar cautivos. Otros hab\u00edan hecho de eso su carisma propio. Ni tampoco con la preocupaci\u00f3n de convertir a los musulmanes. Otros, tambi\u00e9n, lo hab\u00edan intentado en vano. San Vicente ten\u00eda en su mente el recuerdo de san Francisco de As\u00eds (1182-1226) y su ida abortada donde el sult\u00e1n de Egipto, Aladino (1199-1220). La ambici\u00f3n de san Vicente era llevar el apoyo material, moral y espiritual a los cautivos en los \u00abba\u00f1os\u00bb de las ciudades y del campo, asegurarles una presencia permanente de aliento en el coraz\u00f3n de la ciudadela del Islam.<\/p>\n<p style=\"text-align: justify\">En determinada ocasi\u00f3n, a petici\u00f3n de la Propaganda, hab\u00eda concebido el proyecto misionero de ayudar a los cristianos del L\u00edbano. Ese proyecto no llegar\u00e1 a concretarse durante su vida. No deb\u00eda llevarse a cabo sino despu\u00e9s de la supresi\u00f3n de la Compa\u00f1\u00eda de Jes\u00fas por Clemente XIV, en 1773.<\/p>\n<p style=\"text-align: justify\">Por el contrario, en la otra orilla del Mediterr\u00e1neo, en el Maghreb, hay poblaciones cristianas amontonadas en los \u00abba\u00f1os\u00bb de las ciudades, y tambi\u00e9n condenadas a galeras. Otros cautivos estaban condenados al servicio de amos en las ciudades de Argel, Bona, T\u00fanez&#8230;y en el campo. El servicio de esas poblaciones estaba asegurado, para el culto, por los sacerdotes esclavos y, en visitas espor\u00e1dicas, por los religiosos&#8230;<\/p>\n<p style=\"text-align: justify\">La mirada de san Vicente descubre la gran miseria de esos cristianos y deplora <em>\u00abel gran libertinaje que reinaba entre las personas de Iglesia<\/em>\u00ab&#8230;Se impon\u00eda una presencia permanente, que asegurara la ayuda material, moral y espiritual tan ansiada. Ser\u00e1 sostenido en eso por el Papa Urbano VIII (1623-1644) y por la duquesa de Aiguillon.<\/p>\n<p style=\"text-align: justify\">El 25\u00a0 de enero de 1643 se firma un contrato de fundaci\u00f3n de una casa en Marsella. Desde ella partir\u00e1n los sacerdotes y hermanos de la Misi\u00f3n \u00ab<em>para consolar, instruir a los pobres cristianos cautivos por la fe, en el amor y en el temor de Dios, y para dar las misiones y los catecismos, las instrucciones y las exhortaciones, que acostumbran dar<\/em>\u00ab.<\/p>\n<p style=\"text-align: justify\">Pero los turcos no aceptan otros capellanes fuera de los sacerdotes esclavos. S\u00f3lo se atienen a eso. La duquesa de Aiguillon compra, en 1646, los consulados de T\u00fanez y de Argel y los regala al Sr. Vicente. De este modo, gracias a este rodeo, podr\u00e1 ser asegurada una permanente presencia misionera.<\/p>\n<p style=\"text-align: justify\">As\u00ed, el Sr. Vicente, en 1646, se decide a enviar a T\u00fanez al Hermano Barreau, un antiguo abogado del Parlamento, acompa\u00f1ado del P. Nou\u00eblly. Marchan provistos de una especie de carta, de las que tendremos el gusto de presentar un r\u00e1pido an\u00e1lisis, pues revela de modo extraordinario una actitud sacada de la misma fuente del Evangelio. Un texto que lo podemos ver en Coste XIII.306\/X.372.<\/p>\n<p style=\"text-align: justify\">Dice: \u00ab<em>Tienen que tener una devoci\u00f3n especial al misterio de la Encarnaci\u00f3n, por el que Nuestro Se\u00f1or baj\u00f3 a la tierra para asistirnos en nuestra esclavitud\u00bb<\/em>. La <strong>Encarnaci\u00f3n<\/strong>, punto nodal a partir del cual el pensamiento, la acci\u00f3n y la contemplaci\u00f3n ir\u00e1n a sacar su motivaci\u00f3n profunda, a encontrar su orientaci\u00f3n espec\u00edfica, a asegurar su dotaci\u00f3n al servicio de un amor <em>creativo hasta el infinito<\/em>, a la escuela de Quien se hizo <em>esclavo con los esclavos<\/em> para liberarlos de la <em>esclavitud<\/em>. De ah\u00ed la importancia decisiva de la contemplaci\u00f3n que permite, como escribir\u00e1 un d\u00eda al P. Le Vacher, estar en simbiosis con Dios. Porque, \u00ab<em>el bien que Dios quiere que se haga como por s\u00ed mismo sin pensar en ello&#8230;<\/em>As\u00ed, cara a cara con \u00c9l, se podr\u00e1 f\u00e1cilmente <em>pesar con ponderaci\u00f3n las cosas en el peso del santuario antes de resolverlas. Ser m\u00e1s bien paciente que activo\u00bb<\/em>(Coste IV.12)<\/p>\n<p style=\"text-align: justify\">Alrededor de ese n\u00facleo van a dibujarse los contornos del primer c\u00edrculo, el de la espiritualidad misionera impregnada del Esp\u00edritu del Evangelio: <em>\u00abSer exactos en las Reglas de la Compa\u00f1\u00eda&#8230;que son las del Evangelio<\/em>\u00bb y cuyos criterios de autenticidad se han de buscar en lo que \u00e9l llama, seg\u00fan la sensibilidad del siglo XVII, <strong>\u00ablas Virtudes que hacen al verdadero misionero: el celo, la humildad, la mortificaci\u00f3n, y la santa obediencia\u00bb. <\/strong>Especie de res\u00famen de las <strong>Bienaventuranzas <\/strong>por las cuales se tratar\u00e1 de anunciar abiertamente a Jesucristo a los Cristianos y a los no cristianos, a los musulmanes puestos en el caso, de llevar su anuncio por el testimonio silencioso de una vida consumida en el ardor del \u00ab<strong>celo<\/strong>\u00bb que es <em>la llama del fuego del amor<\/em>. Espiritualidad que se ha de vivir no en plan solitario, sino en solidaridad con los hermanos, en comunidad, <em>\u00abcuyo director ser\u00e1 el P. Nou\u00eblly<\/em>\u00ab.<\/p>\n<p style=\"text-align: justify\">Esta comunidad tendr\u00e1 por misi\u00f3n asegurar la visibilidad de la Encarnaci\u00f3n en una dimensi\u00f3n espacio-temporal. Se se\u00f1alar\u00e1 entonces el c\u00edrculo geogr\u00e1fico, lugar de inserci\u00f3n del Evangelio: Argel y, en el coraz\u00f3n de Argel, <em>una casa de alquiler con la capilla<\/em>, <strong>coraz\u00f3n de la comunidad<\/strong>, signo de la presencia sacramental, en el centro. Y en el interior del c\u00edrculo geogr\u00e1fico, la lista de las relaciones. En primer lugar los responsables civiles: <em>el virrey, el pach\u00e1, el div\u00e1n (la administraci\u00f3n), el pueblo<\/em>. Relaciones que supondr\u00e1n un infinito discernimiento que permitir\u00e1 <em>vivir con todas las precauciones imaginables<\/em>. Sab\u00eda de qu\u00e9 hablaba san Vicente, \u00e9l que hab\u00eda frecuentado <em>\u00ablos grandes<\/em>\u00bb para sensibilizarlos para la causa de <em>los peque\u00f1os<\/em>. Los grandes, \u00a1tan susceptibles! \u00bfQu\u00e9 no se podr\u00eda decir, cuando se tratara de personas de otra cultura, de otra religi\u00f3n y, adem\u00e1s, extranjeras? Aceptar vivir esa \u00abextranjeridad\u00bb con una actitud de profunda <strong>humildad, <\/strong>y<em> de sufrir de buena gana las injurias que les har\u00e1 el pueblo<\/em><strong>.<\/strong><\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">En el coraz\u00f3n del c\u00edrculo de las relaciones hay un grupo privilegiado, el de <em>los esclavos<\/em> y, en cabeza, los \u00ab<em>sacerdotes y religiosos esclavos: velar por el honor que les es debido<\/em>; despu\u00e9s, <em>los comerciantes<\/em>, ser en medio de ellos artesano de paz, esforzarse en <em>mantenerlos en la mayor uni\u00f3n posible<\/em>\u00ab.<\/p>\n<p style=\"text-align: justify\">All\u00ed se detienen los circulos conc\u00e9ntricos. San Vicente va a comprometer al misionero a no olvidar los lazos que le atan a su familia m\u00e1s all\u00e1 de los mares. \u00ab<em>Procurar\u00e1 dar noticias, no del estado de los asuntos del pa\u00eds, sino de las de 1os pobres esclavos y de la obra que Nuestro Se\u00f1or les conf\u00eda<\/em>\u00ab, con vistas a hacer una obra de edificaci\u00f3n all\u00ed donde unos hermanos les acompa\u00f1an con su constante e intensa oraci\u00f3n.<\/p>\n<p style=\"text-align: justify\">Y para acabar, dos consignas. Una tocante al celo que no sabr\u00edan circunscribir a los l\u00edmites de una ciudad: <em>\u00abIr a visitar a los pobres esclavos que est\u00e1n en el campo para fortalecerlos, consolarlos, darles limosnas<\/em>\u00ab. La otra que se refiere al discernimiento que quiere que <em>se sometan a las leyes del pa\u00eds<\/em>, y que se d\u00e9 muestras de circunspecci\u00f3n en la discusi\u00f3n con otro diferente: <em>\u00abNo disputar nunca de religi\u00f3n, ni decir nada en plan de desprecio\u00bb<\/em>. Y finalmente, tener la mente abierta con vistas a lograr adaptarse: <em>\u00abAprender de los que viven mucho tiempo en aquella tierra\u00bb.<\/em><\/p>\n<p style=\"text-align: justify\"><strong>Celo ardiente, discreci\u00f3n prudente, paciencia long\u00e1nima, disponibilidad alegre, interioridad activa, humildad confiada, respeto infinito al otro, tanto si es cristiano como musulm\u00e1n, circunspecci\u00f3n y anchura de miras, inteligencia del esp\u00edritu y del coraz\u00f3n.<\/strong>..tantas cualidades que hacen del misionero el lugar por donde pasa el Espiritu para el Reino que viene. Tal es, resumiendo, la gesti\u00f3n misionera vicenciana al servicio del hombre y del Evangelio en tierras del Islam.<\/p>\n<p style=\"text-align: justify\">Faltaba a esas consignas sufrir la prueba del tiempo y de la vida. \u00bfC\u00f3mo se las arreglar\u00e1n los misioneros en sus relaciones con los musulmanes?<\/p>\n<p style=\"text-align: justify\"><strong>Celo ardiente; <\/strong>\u00e9sta era la palabra clave.<\/p>\n<p style=\"text-align: justify\">Consta en las M\u00e9moires de la Misi\u00f3n que <em>\u00abel ejemplo de los sacerdotes fervorosos y abnegados, la irradiaci\u00f3n \u00edntima de\u00a0 su caridad, pod\u00edan dar a los musulmanes una idea m\u00e1s justa del cristianismo\u00bb.<\/em> Y por otra parte: <em>\u00abLos turcos cambiaron su desprecio inicial en admiraci\u00f3n\u00bb (II.144).<\/em><\/p>\n<p style=\"text-align: justify\"><strong>Un celo seguramente de alto riesgo<\/strong>.<\/p>\n<p style=\"text-align: justify\">La tarea asignada a los misioneros no era f\u00e1cil. Un camino sembrado de emboscadas. \u00ab<em>La funci\u00f3n de los sacerdotes de san Vicente era peligrosa. Estaban all\u00ed para impedir que los cristianos abandonaran su fe. Porque la tentaci\u00f3n era viva, pues los renegados ten\u00edan situaciones con frecuencia brillantes\u00bb<\/em> (II.289). Estaban fatalmente expuestos a los sentimientos de animosidad de odio, que animaban a ciertos responsables musulmanes, como un tal Aga Mahomet que un d\u00eda declar\u00f3 sin rodeos: <em>\u00abCortemos, hagamos pedazos a esos perros cristianos que viven entre nosotros. Empecemos por esos perros sacerdotes que obligan a los musulmanes a hacerse cristianos e impiden a los cristianos hacerse musulmanes\u00bb<\/em> (II.283). Lo cual, a pesar de todo, no ten\u00eda la suerte de intimidar a los misioneros. Se habr\u00eda podido aplicarles lo que san Vicente dijo de Felipe Le Vacher: <em>\u00abEs un hombre que es todo fuego;\u00a0 necesita brida m\u00e1s que espuela\u00bb.<\/em><\/p>\n<p style=\"text-align: justify\"><em>\u00abEl P. Gu\u00e9rin trabaj\u00f3 en rescatar muchachos y muchachas en peligro de renegar de su fe o de servir a infames caprichos\u00bb (II.26). Felipe Le Vacher \u00abrescata a un ni\u00f1o de 8 a\u00f1os al precio de 1000 libras y lo devuelve a sus padres en Marsella&#8230;Rescat\u00f3 a tres hermanas j\u00f3venes, devolvi\u00f3 a la libertad a una madre, a una joven y a un adolescente de C\u00f3rcega\u00bb (II,161,162). El P. Gu\u00e9rin se entera de que \u00abun ni\u00f1o de 13 a\u00f1os hab\u00eda recibido 1000 bastonazos, porque no quer\u00eda renunciar a Jesucristo, y que le hab\u00edan despedazado un brazo. Inmediatamente, interviene, se pone de rodillas y termina por rescatar al ni\u00f1o al precio de 200 piastras\u00bb<\/em> (II.26).<\/p>\n<p style=\"text-align: justify\"><strong>Un celo que llevar\u00e1 al exilio, a la c\u00e1rcel, al martirio<\/strong>.<\/p>\n<p style=\"text-align: justify\"><em>\u00abEn dos ocasiones, Juan Le Vacher es desterrado de T\u00fanez a Bizerta por haber disuadido a unos cristianos, que quer\u00edan hacerse turcos&#8230;Lo meten en la c\u00e1rcel por haber animado al Sr. Husson, c\u00f3nsul, a que impediera que ning\u00fan comerciante franc\u00e9s consintiera suministrar lona para las velas de los barcos de los corsarios del Islam<\/em>\u00bb (II.20). Despu\u00e9s del bombardeo de Argel por Duquesne, \u00e9ste le dijo a Juan Le Vacher que le reprochaba el bombardeo: \u00ab<em>Usted es m\u00e1s turco que cristiano\u00bb. \u00abYo soy sacerdote\u00bb, le replic\u00f3<\/em>. Duquesne escribi\u00f3 el 15 de julio de 1691: \u00ab<em>Le Vacher no se ten\u00eda de pie. Ten\u00eda que llev\u00e1rsele en camilla. Medio muerto, lo mand\u00f3 poner a la boca del ca\u00f1\u00f3n, igual que a 22 cristianos franceses\u00bb.<\/em><\/p>\n<p style=\"text-align: justify\">Otros conocer\u00e1n la c\u00e1rcel y la tortura. As\u00ed el H. Barreau al que san Vicente le escribe: \u00ab<em>He sentido un consuelo que sobrepasa todo consuelo de la dulzura del esp\u00edritu con el que usted ha recibido esa prueba y del santo uso que ha hecho de su encarcelamiento\u00bb <\/em>(II.202). Y la nota contin\u00faa: <em>\u00abEs derribado a tierra por el pach\u00e1, quien manda a sus verdugos que descarguen sobre \u00e9l centenares de bastonazos&#8230;Pierde el conocimiento&#8230;Le meten debajo de las u\u00f1as leznas puntiagudas<\/em> (II.202). Tambi\u00e9n el P. Montmasson es encarcelado: <em>\u00abUn moro le pincha varias veces con una larga aguja de la que se sirven los guarnicioneros&#8230;Le cortan la nariz y una oreja. Le revientan un ojo. Le dan una cuchillada en la garganta<\/em>\u00bb (II.464). En cuanto al P. Piloni, \u00ab<em>le llevan casi muerto a la calle despu\u00e9s de los bastonazos\u00bb.<\/em><\/p>\n<p style=\"text-align: justify\"><strong>Un celo que acepta \u00absufrir con gusto las injurias que le hace el pueblo<\/strong>\u00ab.<\/p>\n<p style=\"text-align: justify\">Efectivamente, cuando el P. Poissant es encadenado junto con sus cohermanos, ocurre lo siguiente: <em>\u00abFuimos conducidos con la cabeza descubierta y como criminales de lesa majestad por la calle principal de la ciudad. Serv\u00edamos de espect\u00e1culo y de diversi\u00f3n al populacho que nos abrumaba con injurias. Las cadenas eran tan pesadas y tan onerosas, que no pod\u00edamos ni avanzar ni recular sin sufrir mucho\u00bb <\/em>(III.101).<\/p>\n<p style=\"text-align: justify\"><strong>Un celo, con todo, lleno de amenidad<\/strong>.<\/p>\n<p style=\"text-align: justify\">En dichas M\u00e9moires se entera uno de que <em>\u00abel P. Gu\u00e9rin, por la dulzura de sus palabras, la afabilidad de sus maneras&#8230;se gan\u00f3 a todos los corazones<\/em>\u00ab. Con toda seguridad, los de los esclavos, pero tambi\u00e9n los de los musulmanes, porque logr\u00f3 conseguir del rey que la pr\u00e1ctica del culto se pudiera hacer, no ya en secreto, sino abiertamente y <em>\u00abque da a la religi\u00f3n su aparato externo con sus cantos y sus ceremonias&#8230;Hasta el punto de que los \u00abba\u00f1os\u00bb se transformaron en otros tantos peque\u00f1os templos, donde los esclavos pod\u00edan libre y p\u00fablicamente oir la Santa Misa y participar en los divinos misterios<\/em>\u00bb (II.18). A\u00fan m\u00e1s, al cabo de dos a\u00f1os, agotado \u00ab<em>pidi\u00f3 permiso al rey para pedir otro misionero en su ayuda. Y el rey le respondi\u00f3: Dos o tres, si quieres. Yo los proteger\u00e9 como a t\u00ed en todas las ocasiones y no os negar\u00e9 nunca nada, porque s\u00e9 que no haces da\u00f1o a nadie y que, por el contrario, haces el bien a todo el mundo<\/em>\u00ab<\/p>\n<p style=\"text-align: justify\"><strong>Un celo que hac\u00eda poco caso de los peligros y causaba la admiraci\u00f3n de los musulmanes<\/strong><\/p>\n<p style=\"text-align: justify\">Los primeros misioneros fueron, casi todos, arrebatados por la peste. Es el caso del P. Noel (22 de julio de 1647), muerto a los 33 a\u00f1os; el P. Gu\u00e9rin (13 de mayo de 1648), quien <em>\u00abs\u00f3lo se lamentaba de una cosa, la de morir en su cama, \u00e9l que contaba con la dicha de ser empalado o quemado vivo por su Divino Maestro\u00bb<\/em> (II.37); el P. Le Sage (12 de mayo de 1648); el P. Dieppe (2 de mayo de 1649) que muere <em>con los ojos unidos al crucifijo que ten\u00eda entre las manos, repitiendo: \u00abno hay amor m\u00e1s grande que el de dar la vida por los que se ama<\/em>\u00bb el P. Huguier (abril 1663); el P. Laurence (1704); el P. Faroux (15 de julio 1740), \u00ab<em>que se hab\u00eda presentado como voluntario, siendo superior, para ir a cuidar de los apestados, a pesar de las protestas de sus compa\u00f1eros que se hab\u00edan ofrecido voluntarios a porf\u00eda<\/em>; el Hno. Guesdon (1740).<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>Un celo discreto hecho a base de un testimonio sin relieve y silencioso<\/strong>.<\/p>\n<p style=\"text-align: justify\">Pues, no se trataba de dar con la forma de convertir a los musulmanes. Felipe Le Vacher escribir\u00e1: \u00ab<em>Es m\u00e1s f\u00e1cil y m\u00e1s importante impedir que varios esclavos se perviertan que convertir un solo renegado\u00bb<\/em> (II.163). San Vicente hab\u00eda sido claro a este prop\u00f3sito. \u00ab<em>Ustedes no son los encargados de los turcos ni de los renegados\u00bb<\/em>. Sin embargo, Felipe Le Vacher ir\u00eda m\u00e1s all\u00e1. Escribir\u00e1: \u00ab<em>Dios me ha hecho la gracia de encontrar dos piedras preciosas que estaban perdidas; son de mucho precio y emiten un reflejo celestial\u00bb<\/em> (II.166). El P. Gu\u00e9rin tambi\u00e9n hab\u00eda ido m\u00e1s lejos: \u00ab<em>Secretamente se ve\u00eda con turcos, incluso frecuentaba al mayor de los hijos del rey Admed Khodja, Mohamed Chebli, quien, en 1646, huy\u00f3 a Sicilia para convertirse\u00bb<\/em>.<span id='easy-footnote-3-31237' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/#easy-footnote-bottom-3-31237' title='VAUMAS G. \u00abL&amp;#8217;\u00e9veil de La France au 17\u00bas\u00bb'><sup>3<\/sup><\/a><\/span> El P. Duchesne \u00ab<em>se dedicar\u00e1 a aprender el \u00e1rabe con un morabito&#8230;Y llegar\u00e1 hasta a dialogar con \u00e9l sobre Jes\u00fas\u00bb.<\/em> (II.525).<\/p>\n<p style=\"text-align: justify\">Basta con este florilegio. Nos muestra qu\u00e9 formas de fidelidad inspir\u00f3 el celo ardiente de los misioneros y el impacto que el celo produjo en las mentes y en los corazones tanto de los cristianos, como de los musulmanes. Resumiremos todo esto, para acabar, con estas palabras: Valor intr\u00e9pido por la defensa y la salvaci\u00f3n de los cristianos hundidos en la miseria; silencio respetuoso ante quien opina de otra forma; generosidad her\u00f3ica frente a la peste, la tortura y el martirio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Vicente se encontr\u00f3 muy pronto con el hecho del Islam. Nosotros no entraremos en la delicada cuesti\u00f3n de la historicidad integral de los hechos \u00abrelatados con un estilo fascinante\u00bb tales como son los referidos &#8230; <a href=\"http:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":31240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[17],"tags":[168,152,116,129],"class_list":["post-31237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-tiempos-de-vicente-de-paul","tag-argel","tag-duquesa-de-aiguillon","tag-tunez","tag-urbano-viii"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Relaciones con el Islam en tiempos de san Vicente - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Relaciones con el Islam en tiempos de san Vicente - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"San Vicente se encontr\u00f3 muy pronto con el hecho del Islam. Nosotros no entraremos en la delicada cuesti\u00f3n de la historicidad integral de los hechos \u00abrelatados con un estilo fascinante\u00bb tales como son los referidos ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-13T07:35:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T14:58:23+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"22 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Relaciones con el Islam en tiempos de san Vicente\",\"datePublished\":\"2014-03-13T07:35:53+00:00\",\"dateModified\":\"2016-07-26T14:58:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/\"},\"wordCount\":4505,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Argel\",\"Duquesa de Aiguillon\",\"T\u00fanez\",\"Urbano VIII\"],\"articleSection\":[\"En tiempos de Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/\",\"name\":\"Relaciones con el Islam en tiempos de san Vicente - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2014-03-13T07:35:53+00:00\",\"dateModified\":\"2016-07-26T14:58:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/relaciones-con-el-islam-en-tiempos-de-san-vicente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Relaciones con el Islam en tiempos de san Vicente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Relaciones con el Islam en tiempos de san Vicente - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/","og_locale":"es_ES","og_type":"article","og_title":"Relaciones con el Islam en tiempos de san Vicente - Somos Vicencianos","og_description":"San Vicente se encontr\u00f3 muy pronto con el hecho del Islam. Nosotros no entraremos en la delicada cuesti\u00f3n de la historicidad integral de los hechos \u00abrelatados con un estilo fascinante\u00bb tales como son los referidos ... Read More","og_url":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2014-03-13T07:35:53+00:00","article_modified_time":"2016-07-26T14:58:23+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"22 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Relaciones con el Islam en tiempos de san Vicente","datePublished":"2014-03-13T07:35:53+00:00","dateModified":"2016-07-26T14:58:23+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/"},"wordCount":4505,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/#primaryimage"},"thumbnailUrl":"","keywords":["Argel","Duquesa de Aiguillon","T\u00fanez","Urbano VIII"],"articleSection":["En tiempos de Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/","url":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/","name":"Relaciones con el Islam en tiempos de san Vicente - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/#primaryimage"},"thumbnailUrl":"","datePublished":"2014-03-13T07:35:53+00:00","dateModified":"2016-07-26T14:58:23+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/relaciones-con-el-islam-en-tiempos-de-san-vicente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Relaciones con el Islam en tiempos de san Vicente"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-87P","jetpack-related-posts":[{"id":398641,"url":"http:\/\/vincentians.com\/es\/aportacion-del-carisma-vicenciano-la-mision-la-iglesia-4\/","url_meta":{"origin":31237,"position":0},"title":"Aportaci\u00f3n del carisma vicenciano a la Misi\u00f3n de la Iglesia (4)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"07\/08\/2016","format":false,"excerpt":"4.- La salvaci\u00f3n de los pobres en el centro de la Misi\u00f3n de la Iglesia. San Vicente de Pa\u00fal y Santa Luisa de Marillac compartieron la misma experiencia: los pobres son los miembros de Cristo y, por tanto, de la Iglesia. En la Iglesia, Cuerpo de Cristo, los pobres ocupan\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":119696,"url":"http:\/\/vincentians.com\/es\/el-senor-vicente-relee-su-vida-en-casa-de-la-reina-margot\/","url_meta":{"origin":31237,"position":1},"title":"El Se\u00f1or Vicente relee su vida: En Casa de la Reina Margot","author":"Francisco Javier Fern\u00e1ndez Chento","date":"07\/02\/2022","format":false,"excerpt":"Por casualidad, era \"cerca del hotel de la reina Margarita\", la famosa Reina Margot, cuyo matrimonio con Enrique IV hab\u00eda sido declarado nulo, pero que conservaba un palacio en el que llevaba un gran tren de vida. Yo no ten\u00eda m\u00e1s que atravesar la calle para mezclarme con gentes de\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-1-scaled.jpg?fit=1200%2C570&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-1-scaled.jpg?fit=1200%2C570&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-1-scaled.jpg?fit=1200%2C570&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-1-scaled.jpg?fit=1200%2C570&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-1-scaled.jpg?fit=1200%2C570&resize=1050%2C600 3x"},"classes":[]},{"id":129046,"url":"http:\/\/vincentians.com\/es\/las-fuentes-de-la-oracion-vicenciana\/","url_meta":{"origin":31237,"position":2},"title":"Las fuentes de la oraci\u00f3n vicenciana","author":"Francisco Javier Fern\u00e1ndez Chento","date":"09\/07\/2016","format":false,"excerpt":"1. Panor\u00e1mica sobre los estudios vicencianos Si confrontamos la bibliograf\u00eda vicenciana con la de otros fundadores, nos damos cuenta que nuestro fundador ha sido estudiado muy poco, y que las aportaciones sobre su pensa\u00admiento son escasas. Somos una comunidad m\u00e1s bien grande. Sin embargo, no tenemos una revista de car\u00e1cter\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"orando","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/01\/orando.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":118520,"url":"http:\/\/vincentians.com\/es\/bibliografia-basica-sobre-san-vicente-de-paul\/","url_meta":{"origin":31237,"position":3},"title":"Bibliograf\u00eda b\u00e1sica sobre san Vicente de Pa\u00fal","author":"Francisco Javier Fern\u00e1ndez Chento","date":"14\/03\/2015","format":false,"excerpt":"ABELLY Louis: Vida del Venerable Siervo de Dios Vicente de Pa\u00fal, Fundador y primer Superior General de la Congregaci\u00f3n de la Misi\u00f3n. Salamanca: CEME. 1994. 814p 25cm. Abelly public\u00f3 esta obra s\u00f3lo cuatro a\u00f1os despu\u00e9s de la muerte de San Vicente, a quien conoci\u00f3 durante m\u00e1s de veinte a\u00f1os. Ha\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"vicentepaul","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/12\/vicentepaul-235x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":118570,"url":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1109-edmundo-dwyer-obispo-de-limerick-a-san-vicente\/","url_meta":{"origin":31237,"position":4},"title":"Vicente de Pa\u00fal, Carta 1109: Edmundo Dwyer, Obispo De Limerick, A San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/04\/2013","format":false,"excerpt":"[Por agosto de 1648] Es justo, padre, que le escriba para agradecerle con todo mi coraz\u00f3n el favor que de usted he recibido por sus sacerdotes y que le exponga la gran necesidad que de ellos tenemos en este pa\u00eds. Puedo asegurarle con confianza que sus trabajos han hecho m\u00e1s\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":398639,"url":"http:\/\/vincentians.com\/es\/aportacion-del-carisma-vicenciano-la-mision-la-iglesia-3\/","url_meta":{"origin":31237,"position":5},"title":"Aportaci\u00f3n del carisma vicenciano a la Misi\u00f3n de la Iglesia (3)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"06\/08\/2016","format":false,"excerpt":"3.- La participaci\u00f3n de los laicos, y particularmente de la mujer, en la Misi\u00f3n de los ap\u00f3stoles. Los bi\u00f3grafos de San Vicente de Pa\u00fal y de Santa Luisa de Marillac destacan su importante contribuci\u00f3n a la promoci\u00f3n de los laicos, y particularmente de la mujer, al apostolado en la Iglesia.\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/contributions-charism.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/31237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=31237"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/31237\/revisions"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=31237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=31237"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=31237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}