{"id":17795,"date":"2015-02-03T02:54:17","date_gmt":"2015-02-03T01:54:17","guid":{"rendered":"http:\/\/somos.vicencianos.org\/vicencianos\/2010\/05\/03\/san-vicente-de-paul-maynard-libro-9-capitulo-1\/"},"modified":"2016-07-26T17:21:47","modified_gmt":"2016-07-26T15:21:47","slug":"san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/","title":{"rendered":"San Vicente de Pa\u00fal. Su vida, su tiempo; sus obras, su influencia. Libro 9, cap\u00edtulo 1"},"content":{"rendered":"<h2><strong>Libro IX: Muerte de san Vicente de Pa\u00fal<\/strong><\/h2>\n<h2><strong>Cap\u00edtulo I: Retrato y Jornada.<\/strong><\/h2>\n<h3>I. <em>Retrato.<\/em><\/h3>\n<p>Antes de que san Vicente de Pa\u00fal nos sea robado por la muerte, contemplemos por \u00faltima vez sus rasgos, esbocemos su fisonom\u00eda f\u00edsica y moral, y sig\u00e1mosle en el empleo de una de sus jornadas, todas uniformemente llenas de piadosos ejercicios y de obras de caridad.<\/p>\n<p>Vicente de Pa\u00fal era de una talla un poco por encima de la media, bien sentada y proporcionada, Su cabeza, calva muy temprano, era grande, pero en relaci\u00f3n justa con el resto del cuerpo. Ten\u00eda una frente hermosa, ancha y majestuosa, nariz gorda, ojos vivos y penetrantes, los labios finos y sonrientes, el o\u00eddo sutil, el rostro ni demasiado lleno ni demasiado flaco, los rasgos fuertemente acentuados y componiendo un conjunto que impresionaba a la mirada y quedaba impreso en la memoria. Era una de esas fisonom\u00edas que no est\u00e1 en el poder, ni siquiera del l\u00e1piz m\u00e1s torpe, de hacer desconocidos, como no se puede juzgar por tantos retratos, que en su diversidad con frecuencia a la ligera, guardan sin embargo del original una huella indefinible, haciendo in\u00fatil toda <em>letra<\/em> in\u00fatil. Delante de cada uno de estos retratos, hasta de los peores, toda mirada que ha visto tan s\u00f3lo otro nombre inmediatamente a Vicente de Pa\u00fal. La mayor parte se equivocan sin embargo en cuanto a la resultante de esta fisonom\u00eda, a la que dan un aire de bonhom\u00eda que un respeto religioso impide solo decir un tanto tontuelo. Esto se inspira menos en la verdad que en el deseo de pintar en este rostro esa tierna bondad\u00a0 cuya expresi\u00f3n llega hasta la mueca y la caricatura. No era \u00e9se, ciertamente, el aire de san Vicente de Pa\u00fal. De un temperamento sangu\u00edneo y sobre todo bilioso, era por naturaleza triste y melanc\u00f3lico, y necesitaba todos los esfuerzos de la virtud para quitar a sus rasgos un no s\u00e9 que de duro y de arisco<span id='easy-footnote-1-17795' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#easy-footnote-bottom-1-17795' title='Yo me dirig\u00ed a Nuestro Se\u00f1or, dec\u00eda \u00e9l en 1621 y le ped\u00ed con insistencia que me cambiara este humor seco y desabrido, y me diera un esp\u00edritu dulce y benigno. Y, por la gracia de nuestro Se\u00f1or, con un poco de atenci\u00f3n que he puesto en reprimir los borbotones de la naturaleza, he perdido un poco de mi humor negro.\u00bb'><sup>1<\/sup><\/a><\/span>. Si acab\u00f3 por impregnarlos de bondad, como asunto principal y conjunto de su persona, les dej\u00f3 siempre, igual que a su actitud, a su porte, a su talante,\u00a0 gravedad y nobleza.<\/p>\n<p>Por lo dem\u00e1s, es a pesar suyo como se tiene la suerte de poseer la imagen de sus rasgos seg\u00fan naturaleza. Toda su vida le apuraron para posar ante un pintor, sin que su humildad consintiera nunca. El abate de La Pinsonni\u00e8re, de visita para agradecerle despu\u00e9s de un retiro hecho en San L\u00e1zaro, le rog\u00f3 que se dejara pintar para consuelo de sus amigos. A esta propuesta el santo se prostern\u00f3 rostro en tierra exclamando: \u00abYo, miserable, yo, una nada!\u00bb.Y suplic\u00f3 que en adelante le ahorraran un dolor semejante.<\/p>\n<p>Lo que \u00e9l hab\u00eda negado a La Pinsonni\u00e8re, se lo neg\u00f3 a las instancias de las personas de condici\u00f3n que ten\u00edan m\u00e1s derecho sobre \u00e9l, como a las presidentas Gousault y de Lamoignon; se lo neg\u00f3 incluso a las s\u00faplicas y a las l\u00e1grimas de sus hijos.<\/p>\n<p>No obstante era m\u00e1s que octogenario y se sent\u00eda la amenaza de perderlo pronto. Con la desesperaci\u00f3n de vencer\u00a0 frontalmente su resistencia, los Misioneros tomaron el partido de usar de un fraude piadoso e hicieron venir en secreto a San L\u00e1zaro al pintor Sim\u00f3n Fran\u00e7ois, a quien retuvieron por mucho tiempo. \u00c9ste deb\u00eda ver sin ser visto. Descubierto, sin embargo, no habr\u00eda levantado las sospechas de Vicente que no le conoc\u00eda y le habr\u00eda tomado por uno de los numerosos laicos que hac\u00edan los ejercicios espirituales en San L\u00e1zaro. En efecto, para tener ocasi\u00f3n de estudiar mejor la fisonom\u00eda del santo anciano, el pintor segu\u00eda todos los ejercicios a los que asist\u00eda y se pegaba a \u00e9l como su sombra. Los d\u00edas de fiesta, cuando oficiaba Vicente, Sim\u00f3n Fran\u00e7ois estaba all\u00ed en primera fila; y all\u00ed estaba tambi\u00e9n cuando el santo dec\u00eda o asist\u00eda a la misa; en el refectorio lo hab\u00edan colocado enfrente de \u00e9l. Despu\u00e9s de cada una de estas sesiones y de estas poses no sospechadas por el anciano, el pintor iba a encerrarse en una habitaci\u00f3n que le hab\u00edan dado, donde trabajaba de recuerdos. As\u00ed fue como poco a poco hizo el retrato reproducido por el gravado en la cabeza de esta obra<span id='easy-footnote-2-17795' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#easy-footnote-bottom-2-17795' title='Es el original, creemos, de este retrato, o bien, ciertamente,\u00a0 una copia al \u00f3leo aut\u00e9ntica, que se conserv\u00f3 hasta la Revoluci\u00f3n, en la abad\u00eda de Moutier-Saint-Jean, ocupada por el abate de Chandenier, el disc\u00edpulo tan querido de san Vicente de Pa\u00fal y que transportaron m\u00e1s tarde al hospital de esta ciudad, donde hemos hecho tomar una fotograf\u00eda exacta. \u2013Hemos contado la historia de este retrato seg\u00fan las memorias manuscritas del hermano Du Courneau, conservadas en los archivos de la Misi\u00f3n.'><sup>2<\/sup><\/a><\/span>.<\/p>\n<p>Para acabar esta descripci\u00f3n f\u00edsica de nuestro santo, digamos que era de una complexi\u00f3n bastante robusta. Pero bilioso, hemos dicho, guardando siempre las funestas consecuencias de su cautividad de T\u00fanez, cada vez m\u00e1s sensible a las impresiones del aire, y cada vez m\u00e1s tambi\u00e9n era objeto de los ataques de la fiebre.<\/p>\n<p>M\u00e1s a\u00fan que sus rasgos, con mucha frecuencia se ha formado una falsa idea de su esp\u00edritu. Hombre de una bondad, una caridad maravillosa, se ha dicho, pero de una inteligencia mediocre; hombre de un coraz\u00f3n inmenso, pero de un cerebro estrecho, o m\u00e1s bien en quien el coraz\u00f3n parec\u00eda haber absorbido en su provecho todas las facultades del alma.<\/p>\n<p>Sin duda Vicente no ten\u00eda la imaginaci\u00f3n que hace al artista, ni el genio que produce las brillantes creaciones literarias; pero adonde nosotros hemos llegado de su historia, despu\u00e9s de ver tan grandes empresas tan bien concebidas y mejor realizadas todav\u00eda, tantas obras de todas clases, cada una de las cuales habr\u00eda pesado en una naturaleza poderosa, llevadas a la vez sin doblegarse, sin que una da\u00f1ara a la otra, y conducidas hasta el \u00faltimo punto de su desarrollo, tantas fundaciones fecundas y lanzadas, de alguna manera, para la eternidad, \u00bfnecesitamos nosotros ahora decir que Vicente ten\u00eda un esp\u00edritu penetrante, extenso, id\u00f3neo para abrazarlo todo, las cosas grandes como las peque\u00f1as? Pose\u00eda ante todo, en un grado supremo, ese buen sentido que Bossuet ha llamado el maestro de la vida humana; ese buen sentido, m\u00e1s raro tal vez, en el punto que \u00e9l lo ten\u00eda, que lo que se llama el genio, pues supone en el alma un ensamblaje y un equilibrio de facultades m\u00e1s numerosas y m\u00e1s inconciliables: la perfecci\u00f3n que se adue\u00f1a de una idea o de un asunto, la extensi\u00f3n que abraza sus relaciones, la perspicacia que descubre todas sus circunstancias y se adelanta a todas las consecuencias, el juicio que reglamenta su puesta por obra y su ejecuci\u00f3n, la fuerza que desaf\u00eda y triunfa de los obst\u00e1culos, la paciencia por \u00faltimo que no se cansa jam\u00e1s y maniobra con tanta habilidad y constancia que siempre llega; la paciencia larga, perseverante, que, en estas condiciones,\u00a0 Buff\u00f3n ha dicho ser el genio mismo. Tal era el buen sentido de Vicente de Pa\u00fal, con el que habr\u00eda gobernado un reino, con el que ha gobernado asuntos m\u00e1s dif\u00edciles que los de los Estados; tal el buen sentido que dinamizaba sus opiniones, sus palabras, sus empresas y todos sus comportamientos.<\/p>\n<p>Es este buen sentido el que le mantuvo siempre lejos de las rutas singulares, de las doctrinas extremas, del esp\u00edritu de cambio y de novedad. La singularidad, el exceso, todo lo que se sal\u00eda de este medio, en el que lo verdadero y lo bueno han fijado su trono, le parec\u00eda mentira y locura. Condenaba las innovaciones en materia religiosa y pol\u00edtica, porque se encuentran fuera de las condiciones de la vida de los Estados y de las almas. El pretexto mismo de lo mejor no pod\u00eda hacer ilusi\u00f3n a su virtud. En caso de necesidad, habr\u00eda inventado el adagio: \u00abLo mejor es enemigo de lo bueno,\u00bbpes lo ten\u00eda como una de sus m\u00e1ximas. Dec\u00eda tambi\u00e9n: \u00abEl esp\u00edritu humano es pronto y bullanguero. Los esp\u00edritus m\u00e1s vivos y m\u00e1s esclarecidos no son siempre los mejores, si no son los m\u00e1s comedidos. Se camina con seguridad cuando uno no se aparta del camino por el que el grupo de los sabios ha pasado\u00bb.<\/p>\n<p>El buen sentido, siempre franco, directo, le hac\u00eda enemigo de las v\u00edas oblicuas, del lenguaje doble, desconsiderado e indiscreto. Su palabra era siempre la expresi\u00f3n exacta de su pensamiento. Pero la sinceridad en \u00e9l no da\u00f1aba a la prudencia. Nadie ha sabido mejor callarse, cuando la palabra pod\u00eda\u00a0 violar un secreto, herir la caridad, comprometer un asunto, o cuando era simplemente in\u00fatil. Sab\u00eda escuchar, ciencia rara si bien necesaria, sin interrumpir nunca. Interrumpido a su vez, se deten\u00eda al instante; pero como nada era capaz de doblegar su inflexible buen sentido, acabada la interrupci\u00f3n, volv\u00eda a tomar el hilo de su discurso e iba directamente al grano. Ten\u00eda un hablar algo lento, por reflexi\u00f3n. Sus razonamientos eran precisos, justos y terminantes, expresados en t\u00e9rminos claros y netos, animados de un dulce calor, y llevaban la persuasi\u00f3n a los corazones al mismo tiempo que la convicci\u00f3n a los esp\u00edritus. Si hablaba el primero, desarrollaba y expon\u00eda una cuesti\u00f3n con tal orden y nitidez, con tanta profundidad y amplitud, que todos, hasta los m\u00e1s h\u00e1biles, se dec\u00edan: \u00ab\u00a1Eso es!\u00bb en homenaje a su sentido infalible. Por lo dem\u00e1s, el buen sentido le hac\u00eda adoptar tambi\u00e9n todos los tonos y todos los lenguajes, seg\u00fan la medida de los esp\u00edritus, de suerte que el hombre mediocre se cre\u00eda estar a su nivel, mientras que los genios m\u00e1s altos no le consideraban nunca por debajo de ellos.<\/p>\n<p>Y es porque ten\u00eda el discernimiento de los esp\u00edritus como de las doctrinas y de los asuntos. Ve\u00eda enseguida el alcance de todos como de las doctrinas y de los asuntos. \u00c9l ve\u00eda enseguida el alcance de cada uno y adaptaba a ello su conducta y su lenguaje. Penetraba lo fuerte y lo d\u00e9bil, las cualidades buenas y malas de todos, y sab\u00eda reglarles as\u00ed el puesto y el empleo. En todo, discern\u00eda lo verdadero de lo falso, lo bueno de lo malo, lo mejor de lo menos bueno, bajo las apariencias m\u00e1s enga\u00f1osas, las m\u00e1s h\u00e1bilmente hip\u00f3critas.<\/p>\n<p>Eso es lo que hac\u00eda su direcci\u00f3n tan segura, su decisi\u00f3n tan infalible, su acci\u00f3n tan firme y resuelta, cuando hab\u00eda tomado partido. Le consultaban, era a veces lento en responder, ya que \u00e9l mismo ped\u00eda consultar antes a Dios y a los sabios; pero le respuesta que daba por fin iba siempre marcada con la sabidur\u00eda y la experiencia.<\/p>\n<p>Era lento tambi\u00e9n en resolverse y en emprender, siempre en virtud de ese buen sentido que necesitaba penetrar antes y combinar entre s\u00ed la naturaleza, los medios y el fin de todas las cosas. Sus hijos, sobre todo los m\u00e1s j\u00f3venes, se lo reprochaban, y \u00e9l respond\u00eda ordinariamente como lo hizo el 7 de diciembre de 1641, en esta carta dirigida a Codoing, superior de la Misi\u00f3n de Annecy:<\/p>\n<p>\u00abMe contestar\u00e9is que soy demasiado largo, que esper\u00e1is a veces seis meses, y que sin embargo se pierde la ocasi\u00f3n y todo sigue igual. A lo que yo os respondo, Se\u00f1or, que es cierto que soy demasiado lento en responder y en hacer las cosas; pero que a pesar de ello nunca he visto todav\u00eda echarse a perder un asunto por mi atraso, sino que todo se ha hecho a su tiempo, y con las vistas y la precauci\u00f3n necesarias, y que no obstante me propongo en lo sucesivo daros respuesta lo antes posible, despu\u00e9s de recibir vuestras cartas y considerar la cosa delante de Dios, que se honra mucho por el tiempo que se emplea en considerar con madurez las cosas que tienen que ver con su servicio. Vos os corregir\u00e9is pues, por favor, por vuestra prontitud en resolver y hacer las cosas,\u00a0 y yo trabajar\u00e9 en corregirme de mi indolencia\u2026 \u00bfMe atrever\u00e9 a decirlo sin sonrojarme, Se\u00f1or? No hay otro remedio, es preciso que lo haga. Porque, pensando volviendo la mirada a todo lo ocurrido en nuestra compa\u00f1\u00eda, me parece, y es muy demostrativo, que si se hubiera hecho antes de lo que lo ha sido, no habr\u00eda resultado tan bien. Lo digo de todo sin exceptuar nada. Por eso tengo una devoci\u00f3n particular por seguir al paso a la adorable Providencia de Dios, y el \u00fanico consuelo que me queda es que me parece que es Nuestro Se\u00f1or solo quien ha hecho y hace incesantemente las cosas en esta peque\u00f1a Compa\u00f1\u00eda.\u00bb<\/p>\n<p>Vicente comparaba algunas veces a los esp\u00edritus demasiado apresurados, irreflexivos, que se agitan y abrazan el vac\u00edo, con las ruedas de molino que giran sin trigo, que, dec\u00eda \u00e9l, se inflaman y queman el molino.\u00bb<span id='easy-footnote-3-17795' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#easy-footnote-bottom-3-17795' title='Carta del 11 de julio de 1645.'><sup>3<\/sup><\/a><\/span>\n<p>Era pues amigo de la lentitud, o mejor enemigo de la precipitaci\u00f3n: efecto al mismo tiempo de su buen sentido y de su virtud. Percib\u00eda en los asuntos, sobre todo en los dif\u00edciles y los importantes, una cantidad de obst\u00e1culos contra los cuales van a romperse a la primera los impacientes, y que \u00e9l quer\u00eda cambiar a fuerza de circunspecci\u00f3n y de lenta prudencia. Acaba de decirnos, y le gustaba decirlo con frecuencia, que no ve\u00eda otra cosa m\u00e1s com\u00fan que el m\u00e1s \u00e9xito de los asuntos precipitados.<\/p>\n<p>La virtud se aliaba en \u00e9l con el buen sentido para mandarle, antes de obrar, largas y prudentes deliberaciones. Siempre tem\u00eda, seg\u00fan su palabra ordinaria, adelantarse a la Providencia: es decir anticiparse al tiempo fijado por la sabidur\u00eda divina, actuar sin su concurso y su gracia, adelantarse a su acci\u00f3n, en lugar de seguirla. Ten\u00eda de s\u00ed una idea tan baja, y una tan alta del soberano dominio de Dios, que habr\u00eda querido no a parecer en nada ni actuar jam\u00e1s, para dejar a Dios toda gloria, para dejarle tambi\u00e9n la iniciativa y la consumaci\u00f3n de toda empresa.<\/p>\n<p>Pero nada, en ello, que pareciera misticismo oriental, ni ese quietismo ocioso y blando, que no se borra delante de Dios m\u00e1s que para dar una especie de consagraci\u00f3n sacr\u00edlega a la cobard\u00eda y a la pereza. Nunca una vida m\u00e1s activa,\u00a0 m\u00e1s ocupada, m\u00e1s llena. \u00abEl Sr. Vicente ha hecho m\u00e1s bien por s\u00ed solo, dec\u00eda la Srta. de Lamoignon, que lo que han hecho otros veinte santos.\u00bb Cu\u00e1ntas obras, en efecto, en los cuarenta \u00faltimos a\u00f1os que hemos recorrido, en los veinte \u00faltimos sobre todo, correspondiendo no obstante a una vejez fatigada y enfermiza. Produce sorpresa que un solo hombre haya podido concebirlas, m\u00e1s a\u00fan que las haya emprendido y realizado. La lentitud de Vicente ten\u00eda por \u00fanico principio el temor de contrariar a Dios, el deseo de asegurarse su concurso, la necesidad de echar los fundamentos de una obra sin la certeza, o al menos, la esperanza probable de poder llevarla al remate. De all\u00ed, la sabia combinaci\u00f3n, la duraci\u00f3n y la permanencia de las suyas(obras).<\/p>\n<p>Pero, una vez seguro de la voluntad de Dios y de los recursos de su Providencia, nada pod\u00eda ya detenerlo. No le asustaban ni el n\u00famero ni las dificultades de los asuntos. \u00c9l las segu\u00eda con una fuerza de esp\u00edritu, una intrepidez de valor que ning\u00fan obst\u00e1culo pod\u00eda moverle, vinieran de las personas o de las cosas, de la conjuraci\u00f3n de los elementos o de las pasiones humanas. Se entregaba con una sagacidad llena de orden y de claridad; soportaba el peso, las lentitudes, con una calma que proven\u00eda de una santa seguridad, con una perseverancia que sacaba de la certidumbre religiosa del \u00e9xito.<\/p>\n<p>Alma verdaderamente superior\u00a0 por su sentido positivo y pr\u00e1ctico, cuyas pasiones no ven\u00edan nunca, como en la mayor parte de los hombres, a perturbar las combinaciones, cuya virtud, por el contrario, inspiraba, dirig\u00eda y llevaba a t\u00e9rmino todos los planes.<\/p>\n<p>El fundamento de esta virtud, -\u00bfvamos a tener que decirlo m\u00e1s veces?- era la humildad que ning\u00fan santo, despu\u00e9s de Aqu\u00e9l con quien nada puede compararse, despu\u00e9s de Aqu\u00e9l, que estando en la forma de Dios, se anonad\u00f3 y tom\u00f3 la forma de esclavo, despu\u00e9s de Aqu\u00e9l que ha sacado de su bajeza el principio de su grandeza, que ning\u00fan santo ha pose\u00eddo en el mismo grado que Vicente de Pa\u00fal. Humildad prodigiosa, que espanta no s\u00f3lo nuestro orgullo, sino nuestra inteligencia, cuando vemos a este hombre admirable descender a las profundidades y a los infiernos, buscarse los m\u00e1s perversos, los forzados, los ajusticiados y hasta los demonios. Humildad sin embargo la \u00fanica que explica a Vicente de Pa\u00fal, la \u00fanica que ha producido su caridad, prodigiosa como ella. el orgullo, \u00bfqui\u00e9n no lo sabe? odia a sus superiores y a sus iguales, desprecia a sus inferiores. Apunta a un primer rango \u00fanico, donde se complacer\u00e1, vivir\u00e1 en s\u00ed mismo, en la indiferencia y el desd\u00e9n hacia todo lo dem\u00e1s: ant\u00edpodas de la caridad! La humildad se queda en su rango, o m\u00e1s bien desciende para atraerse todo, teniendo para lo que le es superior o igual, no la envidia\u00a0 o las aspiraciones ambiciosas, sino solamente el amor y el respeto. Vicente de pa\u00fal no humilde habr\u00eda aspirado a\u00a0 las dignidades eclesi\u00e1sticas y se habr\u00eda agotado\u00a0 en su b\u00fasqueda; habr\u00eda perdido el recuerdo de su baja extracci\u00f3n y de las miserias de su cuna, y al mismo tiempo la compasi\u00f3n; se habr\u00eda alzado a una altura tal, que no hubiera visto m\u00e1s a los peque\u00f1os y a los pobres, muy lejos de ponerlos por encima de \u00e9l<\/p>\n<p>para hacerse su muy humilde y devoto servidor. La entrega es el sacrificio de s\u00ed, es decir del orgullo; y cuanto m\u00e1s sacrificado es el orgullo, m\u00e1s llena y entera es la entrega. Vicente de Pa\u00fal no ve\u00eda por encima de \u00e9l m\u00e1s que alturas de las que le deb\u00edan venir las aguas de una misericordiosa Providencia: alrededor de \u00e9l. qu\u00e9 cooperadores m\u00e1s h\u00e1biles y m\u00e1s bendecidos de Dios que \u00e9l mismo; por debajo, -si acaso hay un debajo de en este hombre,-m\u00e1s que un abismo de miserias y de necesidades adonde \u00e9l esperaba descender para confundirse all\u00ed y consumirse en provecho de todos; o m\u00e1s bien descubriendo, por la fe y la humildad, a superiores en los pobres y los peque\u00f1os, a se\u00f1ores y amos, seg\u00fan su expresi\u00f3n sublime, se daba a ellos como un presente de ning\u00fan precio. Ha sido el m\u00e1s caritativo, porque ha sido el m\u00e1s humilde de los hombres<span id='easy-footnote-4-17795' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#easy-footnote-bottom-4-17795' title='En medio de sus empleos m\u00e1s gloriosos, se le vio a menudo ir a la cocina a lavar la vajilla (&lt;em&gt;Summ&lt;\/em&gt;., n\u00ba 204, p. 243).'><sup>4<\/sup><\/a><\/span>.<\/p>\n<p>Y en verdad, sorprende que este car\u00e1cter esencial de la virtud de san Vicente de Pa\u00fal, que este principio fundamental de todas sus obras haya sido desconocido, hasta el punto que sus bi\u00f3grafos\u00a0 mismos, Collet despu\u00e9s de Abelly, se hayan cre\u00eddo obligados a defenderle contra la acusaci\u00f3n de un tal <em>defecto<\/em> que se contentan en llamar una <em>singularidad. <\/em>Singularidad, sin duda, como el genio y el hero\u00edsmo; pero no es eso lo que se entiende; se quiere que se haya excedido en este punto, sin comprender que de otra forma no hubiera excedido en caridad, si es posible exceder, sin embargo, en una virtud que, por parte de Dios, no tiene l\u00edmites m\u00e1s que el infinito de sus perfecciones y, por parte del hombre, que lo indefinido de sus necesidades y de sus miserias. Vicente ha podido excederse en la buena opini\u00f3n que ten\u00eda de los dem\u00e1s y en la hip\u00e9rbole de sus elogios; pero no, para entenderle bien, en el bajo sentimiento que ten\u00eda de s\u00ed mismo. En comparaci\u00f3n con el demonio y los mayores pecadores, inferior a los cuales se cre\u00eda, sin duda, \u00e9l no se pon\u00eda en su lugar; pero en comparaci\u00f3n con Dios, su grandeza, su santidad, \u00bfqu\u00e9 es el mayor y el m\u00e1s santo, sino bajeza e imperfecci\u00f3n? Ha sido este sentimiento m\u00e1s verdadero y m\u00e1s profundo de Dios el que ha hecho a los santos, aunque relativamente m\u00e1s grandes, m\u00e1s humildes que los dem\u00e1s hombres, y de ah\u00ed incluso m\u00e1s caritativos y m\u00e1s entregados.<\/p>\n<p>Se ha dicho: \u00abSi la clemencia fuera desterrada de la tierra, deber\u00eda buscarse un refugio en el coraz\u00f3n de los reyes.\u00bb<\/p>\n<p>Es la palabra que del cardenal de la Rochefoucauld aplicaba a la humildad y al coraz\u00f3n de Vicente de Pa\u00fal. Lo podr\u00eda haber dicho, y por la misma raz\u00f3n, de la caridad que, compa\u00f1era inseparable e hija necesaria de la humildad, tuvo siempre en esta alma su santuario privilegiado y, a falta de otro cualquiera, se habr\u00eda reservado en ella su \u00faltimo asilo.<\/p>\n<p>Por lo dem\u00e1s, Vicente no cre\u00eda que se pudiera exceder en humildad y en caridad, cuando consideraba a Aqu\u00e9l que se anonad\u00f3 y entreg\u00f3 hasta la muerte. En sus pensamientos, en sus palabras, en sus acciones, Vicente no se inspiraba m\u00e1s que en Jesucristo, no repet\u00eda m\u00e1s que su lenguaje, no se portaba m\u00e1s que seg\u00fan su modelo. Jesucristo, siempre, Jesucristo en todas partes, Jesucristo en todo y en todos; \u00e9sa era su doctrina, su moral y su pol\u00edtica, lo que \u00e9l sol\u00eda explicar con una palabra: \u00abNada me satisface sino en Jesucristo.\u00bb<\/p>\n<p>Esta visi\u00f3n continua y universal de Jesucristo iluminaba, elevaba, encend\u00eda su caridad. Jesucristo, \u00e9l le ve\u00eda pont\u00edfice supremo en el papa, obispo y pr\u00edncipe de los pastores en los obispos, soberano sacerdote en los sacerdotes, maestro y doctor \u00fanico en los doctores, rey de los reyes, juez de los jueces en los pr\u00edncipes y en los magistrados, grande y noble en los gentilhombres y peque\u00f1o en los peque\u00f1os, obrero en los artesanos, divino negociante en los hombres de tr\u00e1fico, pobre en los pobres, prisionero en los prisioneros, enfermo y agonizante en los enfermos y moribundos, de donde su respeto y su ternura con todos los hombres y, en particular con todos aquellos cuya bajeza y sufrimientos le presentaban una imagen m\u00e1s parecida al Dios anonadado y al Hombre de dolores.<\/p>\n<p>Esto, en cuanto a lo f\u00edsico y lo moral de Vicente de Pa\u00fal. Ve\u00e1mosle ahora en el trabajo durante una de sus jornadas, lo que nos servir\u00e1 de muestra de toda su vida.<\/p>\n<h3>II. <em>Jornada<\/em>.<\/h3>\n<p>Son las cuatro de la ma\u00f1ana. Aunque anciano, enfermo, acostado hace escasas horas, y encima transcurridas muy a menudo en el insomnio, Vicente se levanta, y el segundo golpe de la campana no lo encuentra en la misma postura que el primero. Esta obediencia a la regla de levantarse es para \u00e9l la primera en importancia como en el orden del d\u00eda, y es la primera tambi\u00e9n que recomienda a los suyos. Obediencia, les dice, tanto m\u00e1s agradable a Dios por ser la primera, tanto m\u00e1s honorable porque le ofrece las primicias de la jornada y de nuestras acciones; obediencia impuesta por el ejemplo de Nuestro Se\u00f1or quien, despu\u00e9s de dejar el para\u00edso, no tuvo donde descansar la cabeza; obediencia cada vez m\u00e1s f\u00e1cil con la costumbres; provechosa al esp\u00edritu y al cuerpo, y que alarga nuestra vida demasiado corta; obediencia por \u00faltimo cuya diligencia y fervor aseguran el fervor y la diligencia, de la que depende todo lo dem\u00e1s.<\/p>\n<p>As\u00ed pues, al primer toque, sale de la cama, hace la se\u00f1al de la cruz, se prosterna y besa el suelo. Adora la majestad de Dios, le da gracias por su gloria, por la que ha dado a su hijo, a la sant\u00edsima Virgen, a los santos \u00e1ngeles, al \u00e1ngel custodio, a san Juan Bautista, a los ap\u00f3stoles, a san Jos\u00e9 y a todos los santos y santas del para\u00edso. Le agradece tambi\u00e9n las gracias hechas a la santa Iglesia, y a \u00e9l mismo y, en particular haber sido conservado durante la noche. Le ofrece sus pensamientos, sus palabras, sus acciones, en uni\u00f3n con las de Jesucristo; le pide que le guarde de todo pecado y ayude a cumplir fielmente todo lo que le sea m\u00e1s de su agrado<span id='easy-footnote-5-17795' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#easy-footnote-bottom-5-17795' title='Extra\u00eddo textualmente de un escrito de la mano de san Vicente de Pa\u00fal, entregado por \u00e9l como regla a una persona de condici\u00f3n.'><sup>5<\/sup><\/a><\/span>.<\/p>\n<p>Despu\u00e9s de estos primeros actos de religi\u00f3n, hace la cama y se va a la iglesia donde, a pesar de la hinchaz\u00f3n de sus viejas piernas que han tenido que vend\u00e1rselas, ha llegado antes que los m\u00e1s sanos y m\u00e1s j\u00f3venes. La vista de su familia reunida ante Nuestro Se\u00f1or regocija y consuela su alma.. Felicita a los m\u00e1s diligentes. Los retrasados le afligen. En cuanto a \u00e9l, \u00e9l nunca deja de hallarse en la oraci\u00f3n de la ma\u00f1ana, en medio de la gran multiplicidad de los asuntos, aunque tuviese que sangrase, en el d\u00eda, o tomar alguna medicina, y la fatiga que ello le supondr\u00e1 no le impedir\u00e1 acudir al d\u00eda siguiente.<\/p>\n<p>Y es que sent\u00eda por la oraci\u00f3n la estima m\u00e1s profunda y m\u00e1s religiosa. .La considera como el man\u00e1 que se ha de recoger cada ma\u00f1ana, so pena de morir en el desierto de la vida. Por eso se entrega a ella con ardor. Se le oye emitir suspiros de un amor que no puede contener, y \u00e9l es el \u00fanico que no se entera de su explosi\u00f3n. \u00bfQu\u00e9 pasa entre Dios y \u00e9l? Su humildad lo ocultar\u00e1 con cuidado. Ero al descender\u00a0 de la santa monta\u00f1a, su frente parece a veces luminosa como la de Mois\u00e9s, y el fervor de su alma\u00a0 brota por toda su persona, pasa a sus palabras y a sus acto. Sus palabras, al salir de la conversaci\u00f3n divina, son m\u00e1s abrasadoras todav\u00eda de fe y de caridad; su humildad, su mortificaci\u00f3n, su paciencia, todas sus virtudes, brillan con un nuevo resplandor en su conducta.<\/p>\n<p>Esta oraci\u00f3n tan querida, \u00e9l se entregar\u00e1 a ella en sus largos insomnios; a ella dedicar\u00e1 todos los espacios libres que le dejen\u00a0 el desempe\u00f1o de su cargo y el servicio del pr\u00f3jimo: y cada a\u00f1o, sean las que fueren sus ocupaciones, les dedicar\u00e1 al menos ocho d\u00edas enteros, durante los cuales interrumpir\u00e1 las m\u00e1s santas ocupaciones para no hablar con nadie m\u00e1s que con Dios.<\/p>\n<p>Esta oraci\u00f3n de la ma\u00f1ana, lleva a ella a rodos aquellos sobre quienes tiene alg\u00fan trato; quiere que se forme en ella a los ordenandos y a los ejercitantes y que se lleven su resoluci\u00f3n y su pr\u00e1ctica\u00a0 como el fruto m\u00e1s precioso de su retiro. \u00c9l por su parte compromete\u00a0 a los eclesi\u00e1sticos de su conferencia, incluso a las Damas de su Asamblea.<\/p>\n<p>Pero \u00e9l no deja de exhortar a ello\u00a0 a sus Misioneros, por su inter\u00e9s y por el del pr\u00f3jimo. \u00abDadme, les dice, un hombre de oraci\u00f3n, y ser\u00e1 capaz de todo, podr\u00e1 decir con el santo Ap\u00f3stol: \u2018Todo lo puedo en aqu\u00e9l que me sostiene y me conforta\u2019\u00bb\u00a0 Y a\u00f1ade: \u00abLa Congregaci\u00f3n de la Misi\u00f3n subsistir\u00e1 mientras\u00a0 el ejercicio de la oraci\u00f3n se practique fielmente, porque la oraci\u00f3n es como un muro inexpugnable que pondr\u00e1 a los Misioneros a cubierto contra todas clases de ataques; que es como un arsenal m\u00edstico, o como la Torre de David que les dar\u00e1 toda clase de armas, no s\u00f3lo para defenderse, sino tambi\u00e9n para asaltar y poner en fuga a todos los enemigos de la gloria de Dios y de la salvaci\u00f3n de las almas.\u00bb<\/p>\n<p>No exime de ella ni a los enfermos, a quienes compromete a practicarla menos por una aplicaci\u00f3n imposible del entendimiento que por los afectos de la voluntad, por actos reiterados de resignaci\u00f3n, de contrici\u00f3n, de paciencia, de confianza, de perseverancia y de amor. La exige, y de una hora entera, los d\u00edas de descanso como los d\u00edas de trabajo, en la multiplicidad de las ocupaciones como en el tren ordinario de la vida. Monse\u00f1or el pr\u00edncipe de Conti, dice a este prop\u00f3sito, ser\u00e1 una d\u00eda nuestro juez, por lo menos el m\u00edo. Es admirable en su fidelidad a la oraci\u00f3n. Hace todos los d\u00edas dos horas, una por la ma\u00f1ana, la otra por la noche. Por grandes ocupaciones que tenga, por mucha gente que le rodee, no se la pierde nunca. Verdad es que no est\u00e1 apegado a ninguna hora, que no la adelanta o la retrasa\u00a0 seg\u00fan la exigencia de los asuntos. Quiera Dios darnos este atractivo para unirnos a \u00e9l por la oraci\u00f3n.\u00bb<\/p>\n<p>Se la recomienda en particular a los predicadores, a los catequistas y a los directores de almas: \u00abLa oraci\u00f3n, dice, es un gran libro para un predicador; Ah\u00ed es donde sacar\u00e1 las verdades divinas en el Verbo eterno que es su fuente para difundirlas despu\u00e9s entre el pueblo; es mediante la oraci\u00f3n como\u00a0 ser\u00e1 capaz de tocar los corazones y de convertir a las almas.\u00bb<\/p>\n<p>Por la ma\u00f1ana, al salir de su propia oraci\u00f3n, es cuando Vicente da estos consejos y estas ense\u00f1anzas a sus Misioneros. Al menos dos veces por semana, el domingo y el mi\u00e9rcoles. Les hace dar cuenta tambi\u00e9n de los buenos pensamientos y de los buenos sentimientos que les ha dado Dios. Esta <em>repetici\u00f3n de oraci\u00f3n<\/em> le edifica y le encanta. Fuera de su comunidad, de viaje, , la practica tambi\u00e9n. Si viaja con seglares, les hace que vean bien, no s\u00f3lo que se emplee todas las ma\u00f1anas alg\u00fan tiempo en la oraci\u00f3n, sino que tambi\u00e9n se converse luego sobre las comunicaciones que el esp\u00edritu de Dios ha hecho a cada uno. Los criados son invitados a hablar a su vez, y uno de ellos nos cuenta: \u00abHabiendo considerado que Nuestro Se\u00f1or ha recomendado el servicio de los pobres, he cre\u00eddo que deb\u00eda hacer algo por ellos; pero como no puedo yo, pobre como ellos, darles nada, he resuelto al menos rendirles honor, hablarles graciosamente, cuando se dirijan a m\u00ed, hasta quitarme el sombrero para saludarlos.\u00bb<\/p>\n<p>A este relato, Vicente bendice a Dios que ama comunicarse con los sencillos y, al comprometer a las damas piadosas a establecer la costumbre de la repetici\u00f3n de oraci\u00f3n entre sus criados, se confirma en su propia costumbre de preguntar al menor de sus hermanos en San L\u00e1zaro, los mismo que al m\u00e1s elevado de sus Misioneros.<\/p>\n<p>En efecto, en cada repetici\u00f3n de oraci\u00f3n, invita siempre a tres o cuatro a hablar y, por muy importantes que sean los asuntos que llaman a otra parte, los escucha con bondad y satisfacci\u00f3n horas enteras. Es una mutua y com\u00fan edificaci\u00f3n; tambi\u00e9n una escuela, una lecci\u00f3n pr\u00e1ctica, donde los reci\u00e9n llegados y los inexpertos se forman en el gran arte de la oraci\u00f3n.<\/p>\n<p>\u00abHermano, pregunta a uno de ellos, \u00bfqu\u00e9 m\u00e9todo segu\u00eds en vuestra oraci\u00f3n? \u2013Padre, yo divido siempre el asunto n ciertos puntos, -Hac\u00e9is muy bien, hermano m\u00edo. Sin embargo cuando se trata de alg\u00fan misterio como tema de la\u00a0 meditaci\u00f3n no es necesario ni conveniente detenerse\u00a0 en una virtud particular y hacer vuestra divisi\u00f3n\u00a0 sobre el tema de esa virtud; pero es m\u00e1s oportuno recordar la historia de\u00a0 del misterio y prestar atenci\u00f3n a todas sus circunstancias, no habiendo ninguna, por peque\u00f1a que pueda ser en la que no haya grandes tesoros encerrados, si sabemos buscarlos bien. Yo lo reconoc\u00ed \u00faltimamente\u00a0 en una conferencia de estos Se\u00f1ores que se re\u00fanen aqu\u00ed. Ten\u00edan por tema de su charla lo que se necesitaba para emplear santamente el tiempo de la Cuaresma. Era un tema muy com\u00fan, del que ten\u00edan la costumbre de hablar todos los a\u00f1os; y no obstante se dijeron tantas cosas buenas que todos los asistentes quedaron grandemente impresionados, y yo en particular; y puedo decir de verdad que no he visto conferencia m\u00e1s devota que aquella, ni que hubiera causado m\u00e1s impresi\u00f3n en los esp\u00edritus; ya que si bien hab\u00edan hablado del tema muchas veces, parec\u00eda que no se trataba de las mismas personas las que hablaban; Dios les hab\u00eda inspirado en la oraci\u00f3n otro lenguaje. As\u00ed es, hermanos m\u00edos, c\u00f3mo Dios oculta tesoros en estas cosas que parecen\u00a0 tan comunes, y en las menores circunstancias verdades y misterios\u00a0 de nuestra religi\u00f3n. Son como peque\u00f1os granos de mostaza que producen grandes \u00e1rboles, cuando Nuestro Se\u00f1or quiere derramar su bendici\u00f3n. Nuestros asuntos de meditaci\u00f3n se parecen a tiendas de comerciantes; y como hay tiendas en las que no se encuentra m\u00e1s que una clase de mercanc\u00eda, otras en las que se encuentra todo lo que se necesita. Hay tambi\u00e9n asuntos de meditaci\u00f3n que nos instruyen tan s\u00f3lo en una virtud, y otros que contienen tesoros de toda clase de virtudes; como son los misterios del nacimiento, de la vida, de la muerte y de la resurrecci\u00f3n de Nuestro Se\u00f1or Jesucristo. Para aprovecharlos bien, hay que adorar a Nuestro Se\u00f1or en el estado en el que el misterio nos le representa, admirarle, alabarle, darle gracias por hab\u00e9rnoslas merecido, representarle humildemente nuestras miserias y pedirle los auxilios y gracias necesarios para imitar y practicar las virtudes que nos ha ense\u00f1ado en ellos.<\/p>\n<p>\u00ab-Hermano m\u00edo, pregunta a otro, \u00bfaprovech\u00e1is la oraci\u00f3n? .-Poco, padre. \u2013Y \u00bfpor qu\u00e9 eso? replica Vicente. Mientras se repet\u00eda la oraci\u00f3n, pensaba en m\u00ed mismo de qu\u00e9 pod\u00eda depender que algunos hicieran tan poco progreso en este santo ejercicio. Hay motivos para temer que la causa de este mal sea que no se ejercitan lo suficiente en la mortificaci\u00f3n, y conceden demasiada libertad a sus sentidos. Que se lea lo que los mayores maestros de la vida espiritual han dejado por escrito respecto de la oraci\u00f3n, y se ver\u00e1 que todos un\u00e1nimemente han sostenido que la pr\u00e1ctica de la mortificaci\u00f3n es absolutamente necesaria para hacer bien estas oraciones, y que, para disponerse bien, se necesita no s\u00f3lo mortificar, sus ojos, su lengua, sus o\u00eddos y dem\u00e1s sentidos exteriores, sino tambi\u00e9n las facultades de su alma, el entendimiento, la memoria y la voluntad. Por este medio, dispondr\u00e1 a hacer bien la oraci\u00f3n y, rec\u00edprocamente, la oraci\u00f3n ayudar\u00e1 a practicar bien la mortificaci\u00f3n. \u2013Otra causa de este escaso progreso es que algunos tienen buenos pensamientos y buenos sentimientos, pero no se los aplican a s\u00ed mismos y no hace suficientes reflexiones\u00a0 sobre su estado interior. Y no obstante se ha recomendado muy a menudo que cuando Dios comunica algunas luces o algunos buenos movimientos en la oraci\u00f3n, hay que hacerlos servir a sus necesidades particulares. Hay que considerar sus propios defectos, confesarlos y reconocer ante Dios, y a veces incluso acusarse\u00a0 delante de la compa\u00f1\u00eda pata humillarse y confundirse m\u00e1s, y tomar una fuerte resoluci\u00f3n de corregirse, lo que no se hace nunca sin gran provecho.\u00bb<\/p>\n<p>En esto, un hermano cae de rodillas y pide perd\u00f3n por no hacer nada desde hace tiempo en la oraci\u00f3n, incluso<em> por <\/em>no poder dedicarse a ella. \u00abDios os bendiga, mi querido hermano,\u00a0 responde el santo. \u00c9l permite a veces que se pierda el gusto que se sent\u00eda y el atractivo que se ten\u00eda por la oraci\u00f3n, e incluso que llegue a desagradar. Pero es de ordinario un ejercicio que nos env\u00eda y una prueba que \u00e9l quiere hacer de nosotros, por la que no se ha de sentir desolaci\u00f3n, ni dejarse llevar al des\u00e1nimo. Hay almas buenas que son tratadas a s\u00ed, como muchos santos lo han sido tambi\u00e9n. S\u00ed, conozco a muchas personas que son muy virtuosas que no sientes m\u00e1s que hast\u00edo y sequedad en la oraci\u00f3n; pero como son muy fieles a Dios, hacen de ello muy buen uso. Lo que contribuye no poco para su adelanto en la virtud. Es verdad que cuando estos hast\u00edos y sequedades llegan a los que comienzan a darse a la oraci\u00f3n, hay algunas veces motivos para temer que ello provenga de algunas negligencias por su parte; y es en esto, hermano m\u00edo, donde deb\u00e9is prestar atenci\u00f3n. Tal vez sin embargo no ten\u00e9is culpa. \u00bfNo os duele la cabeza? \u2013S\u00ed, padre; y es por haber querido, en mi \u00faltimo retiro, hacerme sensibles las cosas en la oraci\u00f3n.\u00a0 \u2013No hay que obrar as\u00ed, hermano, ni esforzarse por hacerse sensible en la oraci\u00f3n lo que no lo es por su naturaleza, porque es el amor propio el que se busca en ello. Debemos obrar por esp\u00edritu de fe en la oraci\u00f3n, y considerar los misterios y las virtudes que meditamos en este esp\u00edritu de fe, dulcemente, humildemente, sin esforzar la imaginaci\u00f3n, y aplicar m\u00e1s bien la voluntad para los afectos y resoluciones que el entendimiento para los conocimientos. Y no obstante, debemos perseverar con valor, en la imitaci\u00f3n de Nuestro Se\u00f1or, el cual<em>, fractus in agonia, prolixius orabat. <\/em>La oraci\u00f3n es un don que nos ha dado Dios, que hay que pedirle con insistencia, diciendo con los ap\u00f3stoles: <em>Domine, doce nos orare;<\/em> y esperar esta gracia de su bondad con humildad y paciencia.\u00bb<\/p>\n<p>Otro hermano habla a su vez: \u00abYo no tengo esp\u00edritu para hacer oraci\u00f3n bien. de las facultades de mi alma, s\u00f3lo hay una de la que me pueda servir, que es la voluntad. Ella comienza nada m\u00e1s proponer el asunto, y sin usar ning\u00fan razonamiento, a producir sus afectos, ya dando gracias a Dios, ya pidi\u00e9ndole misericordia y excit\u00e1ndose en la confusi\u00f3n y al dolor de sus pecados; o bien suplic\u00e1ndole que le d\u00e9 la gracia de imitar a Nuestro Se\u00f1or en alguna virtud, y por \u00faltimo tomando algunas resoluciones\u2026-Espere un momento, hermano, interrumpi\u00f3 Vicente, y no se preocupe de las aplicaciones del entendimiento, que no son m\u00e1s que para mover la voluntad. Porque la vuestra, sin estas consideraciones, llega de esta manera a los afectos y a las resoluciones de practicar la virtud, Dios os conceda la gracia de seguir as\u00ed y de haceros cada vez m\u00e1s fiel a todas sus voluntades. El alma se parece a una galera que boga en el mar con los remos y las velas. Y como no se recurre a los remos sino\u00a0 cuando el viento llega a faltar y, cuando es favorable se navega m\u00e1s agradablemente y m\u00e1s r\u00e1pidamente; as\u00ed, hay que ayudarse de las consideraciones en la oraci\u00f3n cuando el esp\u00edritu santo no nos hace sentir sus movimientos; pero cuando ese Esp\u00edritu Santo empieza soplar en nuestros corazones, hay que abandonarse a su direcci\u00f3n.\u00bbAs\u00ed Vicente se aprovecha de todo para instruir a los suyos en esta materia importante de la oraci\u00f3n. \u00c9l les define en primer lugar la naturaleza: \u00abLa oraci\u00f3n, dice, es una predicaci\u00f3n que se hace uno a s\u00ed mismo para convencerse de la necesidad que uno tiene de recurrir a Dios, y de cooperar, con su gracia, para extirpar los vicios de nuestra alma y para plantar en ella las virtudes. Conviene que nos apliquemos a en particular a combatir la pasi\u00f3n o la mala inclinaci\u00f3n que nos reprende, y a tender siempre a mortificarla porque,\u00a0 una vez conseguida aquella, el resto sigue f\u00e1cilmente. Pero hay que mantenerse firme en este combate. Tambi\u00e9n es importante ir despacio en esto, y no quebrarse la cabeza fuerza de insistir y querer sutilizar; de elevar su esp\u00edritu a Dios y escucharle, pues una de sus palabras har\u00e1 m\u00e1s que mil razones y que todas las especulaciones del entendimiento. Deseo que estemos en esta pr\u00e1ctica de oraci\u00f3n, de elevarnos de vez en cuando a Dios, manteni\u00e9ndonos en un humilde reconocimiento de nuestra nada, a la espera de ver si le place hablar a nuestro coraz\u00f3n y decirnos alguna palabra de vida eterna. No hay otra cosa que lo que Dios nos inspira y lo que viene de \u00e9l que nos pueda aprovechar. Debemos tambi\u00e9n recibir de Dios para dar al pr\u00f3jimo a ejemplo de Jesucristo, el cual, hablando de s\u00ed mismo, dec\u00eda que \u00e9l no ense\u00f1aba a los dem\u00e1s m\u00e1s que lo que \u00e9l hab\u00eda o\u00eddo de su Padre.\u00bb<\/p>\n<p>As\u00ed, la oraci\u00f3n que aconseja y ense\u00f1a es positiva y pr\u00e1ctica, seg\u00fan el car\u00e1cter de su esp\u00edritu y de su virtud. \u00c9l respeta esta oraci\u00f3n extraordinaria y sublime, a la que Dios eleva a ciertas almas por una operaci\u00f3n particular de su Esp\u00edritu m\u00e1s que por la industria y los esfuerzos de sus facultades; \u00e9l reconoce que su direcci\u00f3n en estas almas privilegiadas es admirable, y sus caminos incomprensibles; pero \u00e9l tiene sin embargo la m\u00e1xima del Ap\u00f3stol de no creer f\u00e1cilmente en todas clases de esp\u00edritus, y experimentar bien si son de Dios; sabe tambi\u00e9n por san Pablo que Sat\u00e1n se transforma a menudo en \u00e1ngel de luz, y que enga\u00f1a por el atractivo del bien como por la sugesti\u00f3n del mal; sabe por su experiencia que hay maneras de oraci\u00f3n elevadas y perfectas en apariencia, que no obstante acaban en falso. Por eso aconseja seguir el camino m\u00e1s bajo y m\u00e1s humilde como el m\u00e1s seguro y m\u00e1s al alcance de todos, hasta que Dios, pero Dios mismo, solo Dios, nos tome de la mano para conducirnos por otro. Mientras tanto, quiere que se juzgue de la bondad de una oraci\u00f3n \u00fanicamente por las disposiciones que se llevan y por los frutos que se sacan, y entonces dice: \u00abSe conoce a los que hacen bien oraci\u00f3n , no s\u00f3lo por el modo de contarla, sino m\u00e1s a\u00fan por sus acciones y por sus comportamientos. Se ha de decir lo mismo de los que la hacen mal, de suerte que es f\u00e1cil ver que aqu\u00e9llos adelantan y que \u00e9stos retrasan. Pues bien, para sacar provecho de su oraci\u00f3n, hay que prepararse, y faltan gravemente los que descuidan este preparaci\u00f3n, y que no vienen a hacer oraci\u00f3n sino por costumbre, y porque los dem\u00e1s van: <em>Ante orationem, prepara animam tuam, <\/em>dice el Sabio. Pues la oraci\u00f3n es la elevaci\u00f3n del esp\u00edritu a Dios para presentarle nuestras necesidades y pedirle el auxilio de su misericordia y de su gracia. es pues razonable que teniendo que tratar con una majestad tan alta y tan sublime, se piense un poco qu\u00e9 se va a hacer, ante qui\u00e9n se va a comparecer, qu\u00e9 se le quiere decir, qu\u00e9 gracia se le va a pedir. Sucede no obstante a menudo que la pereza y la flojera impiden pensar en ello; o bien, por el contrario la precipitaci\u00f3n y la desconsideraci\u00f3n nos apartan de esto. Se ha de tener cuidado tambi\u00e9n con nuestra imaginaci\u00f3n vagabunda y curiosa y pararle los pies, y con nuestra ligereza de nuestro pobre esp\u00edritu para mantenerlo en la presencia de Dios, sin por el contrario hacer un esfuerzo demasiado grande, ya que el exceso es siempre da\u00f1oso.<\/p>\n<p>\u00abLa oraci\u00f3n tiene tres partes: cada uno sabe el orden y el m\u00e9todo; hay que seguirlo. El tema es de una cosa sensible o insensible. Si es sensible, como un misterio, hay que represent\u00e1rselo y prestar atenci\u00f3n a todas sus partes y circunstancias; si la cosa es insensible, como si es una virtud, se ha de considerar en qu\u00e9 consiste y cu\u00e1les son las principales propiedades, as\u00ed como cu\u00e1les son sus se\u00f1ales, sus efectos y en particular cu\u00e1les son sus actos y los medios de llevarla a la pr\u00e1ctica. Es bueno tambi\u00e9n buscar las razones que nos mueven a\u00a0 abrazar esta virtud y detenernos en los motivos que m\u00e1s nos mueven. Se pueden tomar de la Sagrada Escritura, o bien de los santos Padres; y cuando algunos pasajes de sus escritos nos vienen a la memoria sobre este tema durante la oraci\u00f3n, est\u00e1 bien que los rumiemos en su esp\u00edritu; pero no hace falta que los busquemos, ni siquiera entregarse a varios de estos pasajes; ya que \u00bfde qu\u00e9 sirve detener el pensamiento en un mont\u00f3n de pasajes y de razones, sino tal vez para iluminar y sutilizar nuestro entendimiento, lo que es dedicarse al estudio antes que hacer oraci\u00f3n?<\/p>\n<p>\u00abCuando se quiere hacer fuego, nos servimos de una acero, se golpea hasta que prende el fuego en la materia dispuesta, se enciende la vela; y har\u00eda el rid\u00edculo aqu\u00e9l que, una vez encendida su l\u00e1mpara, continuara golpeando la piedra; de la misma manera, cuando un alma est\u00e1 bastante iluminada\u00a0 por las consideraciones, \u00bfpara qu\u00e9 buscar otras, y golpear y m\u00e1s golpear nuestro esp\u00edritu para multiplicar las razones y los pensamientos\u00bf \u00bfNo ven ustedes que es perder el tiempo, y que entonces\u00a0 se ha de dedicar a inflamar la voluntad y hacer brotar los afectos por la belleza de la virtud y por la fealdad del vicio contrario? Cosa nada dificil, puesto que la voluntad sigue la luz del entendimiento y se dirige a lo que se le propone como bueno y deseable. Pero no es todav\u00eda suficiente: no basta con tener buenos afectos, hay que pasar m\u00e1s adelante y entrar en las resoluciones de trabar lo mejor posible en lo futuro para la adquisici\u00f3n de la virtud, proponi\u00e9ndose ponerla en pr\u00e1ctica y realizar sus actos. Aqu\u00ed est\u00e1 el punto importante y el fruto que se debe sacar de la oraci\u00f3n; por eso no se ha de pasar ligeramente por estas resoluciones, sino reiterarlas e interiorizarlas bien; tambi\u00e9n es bueno prever los obst\u00e1culos que se pueden presentar, y los medios que pueden ayudar para llegar a esta pr\u00e1ctica, y proponerse evitar unos y abrazar los otros.<\/p>\n<p>Pus bien, en esto, no es necesario, ni con frecuencia oportuno tener grandes sentimientos de esta virtud que queremos adquirir, ni siquiera desear tener estos sentimientos; pues el deseo de hacerse sensibles estas virtudes, que son cualidades puramente espirituales, puede a veces da\u00f1ar y producir pena al esp\u00edritu, y la demasiado grande aplicaci\u00f3n del entendimiento calienta el cerebro y causa dolores de cabeza; como tambi\u00e9n los actos de la voluntad, con demasiada frecuencia reiterados o demasiado violentos agotan el coraz\u00f3n y lo debilitan. Hay que moderarse en todo, y el exceso no es nunca laudable se trate de lo que se trate, en particular en la oraci\u00f3n. Se ha de actuar con moderaci\u00f3n t suavidad, y conservar ante todo la paz del esp\u00edritu y del coraz\u00f3n.\u00bb<\/p>\n<p>Vicente se dedica entonces a distinguir los pensamientos venidos del hombre y los pensamientos inspirados de Dios: \u00abVed, dice \u00e9l, la diferencia que existe entre la luz del fuego y la del sol. Durante la noche, nuestro fuego nos<\/p>\n<p>Ilumina y, por medio de su resplandor, vemos las cosas, pero no las vemos sino imperfectamente, no descubrimos m\u00e1s que la superficie, y este resplandor no va m\u00e1s lejos; pero el sol llena i vivifica todo por su luz; no descubre tan s\u00f3lo el exterior de las cosas, sino por una virtud secreta, penetra en el interior, y las hace obrar y hasta fructuosas y f\u00e9rtiles, seg\u00fan la calidad de su naturaleza. Bueno pues, los pensamientos y las consideraciones que vienen de nuestro entendimiento no son sino peque\u00f1os fuegos que muestran solamente un poco del exterior de los objetos y no producen nada m\u00e1s; pero las luces de la gracia, que el sol de justicia difunde en nuestras almas, descubren y penetran hasta el fondo y en lo m\u00e1s \u00edntimo de nuestro coraz\u00f3n que ellas excitan y conducen a producciones maravillosas. Hay pues que pedir a Dios que sea \u00e9l mismo quien nos ilumine y nos inspire lo que le es agradable. Todas estas consideraciones altas y rebuscadas no son oraci\u00f3n; son tal vez de vez en cuando cirujanos de lo soberbio. Y lo mismo sucede con aquellos que se detienen en ello y se complacen, como de una predicador que se pavoneara de sus bonitos discursos y que toda su complacencia fuera ver a los asistentes satisfechos por lo que \u00e9l declama; e lo cual es evidente que no ser\u00eda el Esp\u00edritu Santo, sino m\u00e1s bien el esp\u00edritu de soberbia el que iluminar\u00eda su entendimiento y que llevar\u00eda al exterior todos estos hermosos pensamientos; o mejor dicho, ser\u00eda el demonio el que le empujar\u00eda a y le har\u00eda hablar de esa manera. Lo mismo en la oraci\u00f3n, cuando se rebusca hermosas consideraciones, se juega con pensamientos extraordinarios, en particular cuando es para recitarlos en el exterior al repetir la oraci\u00f3n, con el fin de produzcan estima en los dem\u00e1s. Eso es una especie de blasfemia; es de alg\u00fan modo ser id\u00f3latra de su propio esp\u00edritu; ya que, al tratar con Dios en la oraci\u00f3n, medit\u00e1is en c\u00f3mo satisfacer a vuestra soberbia, emple\u00e1is este santo tiempo en rebuscar vuestra satisfacci\u00f3n y en complaceros en esta bella estima de vuestros pensamientos; sacrific\u00e1is a este \u00eddolo de la vanidad.<\/p>\n<p>\u00abAh, hermanos m\u00edos, guard\u00e9monos mucho de\u00a0 de estas locuras; reconozcamos que estamos llenos de estas miserias; no busquemos m\u00e1s que lo que nos puede ayudar m\u00e1s a humillar y llevarnos a la pr\u00e1ctica s\u00f3lida de las virtudes, descendamos siempre en la oraci\u00f3n hasta la nada y, en nuestras repeticiones de oraci\u00f3n, digamos con humildad nuestros pensamientos; y, si se nos ocurren algunos que nos parecen hermosos, desconfiemos mucho de nosotros mismos y temamos que sea el esp\u00edritu de soberbia el que los produzca y el diablo el que los inspire. Por eso debemos siempre humillarnos siempre profundamente cuando nos llegan estos pensamientos bonitos, sea haciendo oraci\u00f3n, sea predicando, sea en la conversaci\u00f3n con los dem\u00e1s, Ay, el Hijo de Dios pod\u00eda embelesar a todos los hombres con su elocuencia toda divina, y no lo quiso hacer; sino al contrario ense\u00f1ando las verdades del Evangelio se sirvi\u00f3 siempre de las expresiones y palabras comunes y familiares; \u00e9l prefiri\u00f3 m\u00e1s bien verse envilecido y despreciado que alabado y estimado. Veamos pues, hermanos, c\u00f3mo le podremos imitar y, para ello, cortemos esos pensamientos de soberbia en la oraci\u00f3n y en otras partes; sigamos en todo los pasos de la humildad de Jesucristo; usemos de palabras sencillas, comunes y familiares; y, cuando Dios as\u00ed lo permita, aceptemos que no se tenga cuenta de lo que digamos, que se nos desprecie, que se burlen de nosotros, y tengamos por cierto que, sin una verdadera y sincera humildad, nos es imposible adelantar ni a nosotros ni a los dem\u00e1s..\u00bb<\/p>\n<p>Los sentimientos m\u00e1s que los pensamientos, las resoluciones antes todav\u00eda que los sentimientos, en eso radica el sentido pr\u00e1ctico. \u00abDudo que yo deba tomar resoluciones en adelante, dice, repitiendo su oraci\u00f3n, un Misionero, mientras soy infiel a los ejercicios. \u2013Se\u00f1or, responde Vicente al punto, esa no es una raz\u00f3n suficiente; del mismo modo aunque no parezca provechosa la alimentaci\u00f3n, no por eso se deja de tomar. Es una de las partes m\u00e1s importantes, hasta la m\u00e1s importante de la oraci\u00f3n, hacer buenas resoluciones; y es en eso donde debemos detenernos, y no tanto en el razonamiento y en el discurso. El principal fruto de la oraci\u00f3n es resolverse firmemente, en fundamentar bien n sus resoluciones, en convencerse bien, en prepararse bien a ejecutarlas y prever los obst\u00e1culos para superarlos. Eso no es todo. Ya que por \u00faltimo nuestras resoluciones no son por s\u00ed mismas m\u00e1s que acciones f\u00edsicas y morales; y aunque hagamos bien en formarlas en nuestro coraz\u00f3n y afirmarnos en ellas debemos sin embargo reconocer que cuanto tienen de bueno, sus pr\u00e1cticas y sus efectos, depende absolutamente de Dios. \u00bfy de d\u00f3nde creen ustedes que proviene casi siempre que faltamos a nuestras resoluciones? es que nos fiamos demasiado; nos aseguramos de nuestros buenos deseos; nos apoyamos en nuestras fuerzas, y esto es la causa de que no sacamos ning\u00fan fruto. Por eso, despu\u00e9s de tomar algunas resoluciones en la oraci\u00f3n, hay que ped\u00edrselo mucho a Dios e invocar con insistencia su gracia con un a gran desconfianza en nosotros mismos, para que tenga a bien comunicarnos las gracias necesarias para hacer fructificar estas resoluciones. Y aunque, despu\u00e9s de esto, vini\u00e9ramos a faltar, no s\u00f3lo una o dos veces, sino muchas ocasiones y durante un largo tiempo, incluso cuando no hubi\u00e9ramos puesto en ejecuci\u00f3n, no conviene nunca dejar por ello de renovarlas y de recurrir a la misericordia de Dios, e implorar el auxilio de su gracia. las faltas pasadas deben naturalmente humillarnos, pero no hacernos perder los \u00e1nimos; y, en cualquier falta que se caiga, no por ello se va a disminuir la confianza que Dios quiere que tengamos en \u00e9l, sino tomar siempre una nueva resoluci\u00f3n de levantarse y poner m\u00e1s empe\u00f1o en no recaer, mediante el auxilio de su gracia que le debemos pedir. Aunque los m\u00e9dicos no vean ning\u00fan efecto a los remedios que dan a un enfermo, no dejan por ello de continuarlos y reiterarlos, hasta que reconocen alguna esperanza de vida. Si pues se contin\u00faa as\u00ed aplicando remedios para enfermedades del cuerpo, aunque largas y extremas, aun sin ver ninguna enmienda, con mayor raz\u00f3n de debe hacer lo mismo para las debilidades de nuestras almas, en las que, cuando Dios quiere, la gracia opera grandes maravillas. \u00bb<\/p>\n<p>Acabadas la oraci\u00f3n y la repetici\u00f3n, Vicente recita \u00e9l mismo en alta voz las letan\u00edas del santo Nombre de Jes\u00fas y, entre los gloriosos ep\u00edtetos que le da la Iglesia, insiste con un gusto singular en \u00e9ste: <em>Jesu pater pauperum! <\/em>De ah\u00ed, casi todos los d\u00edas va a confesarse, no pudiendo sufrir en \u00e9l la apariencia misma de pecado. Casi nunca su confesor encuentra materia de absoluci\u00f3n: Ah, Se\u00f1or, le dice el humilde santo, si supierais las luces que me da el Se\u00f1or, me juzgar\u00edais de otra manera!\u00bb<\/p>\n<p>Hace luego su preparaci\u00f3n a la misa y, si bien apenas salido de la oraci\u00f3n, le dedica un tiempo considerable. Se reviste por fin y celebra. Parece en el altar como otro Jesucristo, v\u00edctima y sacrificador; v\u00edctima, \u00e9l se rebaja y se humilla, es como un criminal, como condenado a muerte como pronuncia el <em>Confiteor<\/em>, el <em>Domine non sum dignus <\/em> y todas la palabras de la liturgia que expresan la humildad y la contrici\u00f3n, sobre todo el <em>Nobis quoque peccatoribus, <\/em>sobre el que \u00e9l escribir\u00e1: \u00abCuando lleguen ustedes al <em>Nobis<\/em> <em>qioque<\/em> de la santa Misa, acu\u00e9rdense de m\u00ed, como del mayor pecador que haya en la tierra;\u00bb<span id='easy-footnote-6-17795' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#easy-footnote-bottom-6-17795' title='Carta a Gaultier, en Richelieu, 26 de abril de 1648.'><sup>6<\/sup><\/a><\/span> sacrificador, es grave y majestuoso como el Salvador, y al mismo tiempo lleno de dulzura, de serenidad y de misericordia; con estos sentimientos pintados en su rostro y en su actitud, se vuelve hacia el pueblo y, en el tono de su voz y el modo como extiende los brazos y abre las manos, se ve la dilataci\u00f3n de su coraz\u00f3n y el deseo que tiene de abrazarlo, como en otro calvario, en la caridad de Jesucristo. Recita las oraciones de la misa y en realidad las ceremonias sin lentitud ni precipitaci\u00f3n, de manera que alcance pero no pase de la media hora. Pronuncia todas las palabras con una voz media y agradable, distinta y devota, en manifiesto acuerdo de la boca y del coraz\u00f3n. Su respeto y su atenci\u00f3n se doblan en la lectura del santo Evangelio y, si se encuentra con alguna palabra de Nuestro Se\u00f1or, las repite con un tono m\u00e1s tierno y m\u00e1s afectuoso; a la doble afirmaci\u00f3n\u00a0 del Dios de verdad: <em>Amen, amen dico vobis, <\/em>se recoge para estar m\u00e1s atento a las palabras siguientes, donde \u00e9l sospecha mas importancia y\u00a0 misterio, y las lee lentamente, con fe y sumisi\u00f3n, para ponerlas bien el coraz\u00f3n. Todos los asistentes quedan edificados. \u00abDios m\u00edo, dicen, \u00e9ste s\u00ed que es un sacerdote que dice bien la misa!\u00bb \u2013\u00bbEs preciso que sea un hombre santo,\u00bb a\u00f1ade \u00e9ste, y aqu\u00e9l: \u00abEs m\u00e1s bien un \u00e1ngel en el altar!\u00bb<span id='easy-footnote-7-17795' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#easy-footnote-bottom-7-17795' title='Vicente dec\u00eda y mandaba decir a menudo la santa misa por las almas m\u00e1s olvidadas del purgatorio, recomendando volar en socorro de los pobres m\u00e1s miserables y m\u00e1s desprovistos: devoci\u00f3n que ha dejado como preciosa herencia a sus hijos y que el soberano pont\u00edfice P\u00edo IX ha animado abriendo el tesoro de las indulgencias y una asociaci\u00f3n a favor de estas pobres almas, dirigida por los sacerdotes de la Misi\u00f3n, y otorgando un privilegio perpetuo a todos los altares de su iglesia para los asociados difuntos.'><sup>7<\/sup><\/a><\/span>\n<p>Y as\u00ed todos los d\u00edas, menos los tres primeros de su retiro anual, que abstiene de celebrar, seg\u00fan la costumbre de la Compa\u00f1\u00eda. Fuera de esos d\u00edas de penitencia y de purificaci\u00f3n m\u00e1s perfecta, en la ciudad o en los campos, en residencia fija o de viaje, sano o enfermo, \u00e9l no omite nunca el sacrificio cotidiano, y eso hasta en las \u00faltimas semanas de su vida, en que sus piernas se negar\u00e1n a sostenerle.<\/p>\n<p>Celebrada la misa, oye una segunda o a veces la ayuda. Est\u00e1 abrumado de asuntos, y es anciano, tiene ochenta a\u00f1os y no puede andar ya sin bast\u00f3n, ni ponerse de rodillas sin mucho trabajo: pero no importa, el venerable superior con la sencillez ingenua del cl\u00e9rigo y m\u00e1s a\u00fan\u00a0 de respeto y devoci\u00f3n, sirve en el altar al menor de sus sacerdotes. Lo hace por fe y con amor. Lo hace tambi\u00e9n para dar ejemplo a sus cl\u00e9rigos, para que ellos no permitan que un seglar ayude en la misa estando ellos delante: \u00abEs un asunto de verg\u00fcenza en un eclesi\u00e1stico que tiene el car\u00e1cter para el servicio de los altares, les dice con Bourdoise, que en su presencia los que no lo tienen hagan su oficio.\u00bb<\/p>\n<p>Los d\u00edas de fiesta y en los oficios solemnes, su piedad se muestra con nuevo esplendor. Ha previsto todas las ceremonias y se ha informado cuidadosamente<span id='easy-footnote-8-17795' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#easy-footnote-bottom-8-17795' title='Se deseaba con raz\u00f3n en San L\u00e1zaro, para guardar la uniformidad, que muchas ceremonias, demasiado poco detalladas, y por otra parte oscuras en el misal, fuesen desarrolladas y explicadas en un Manual especial. Se trabaj\u00f3 en \u00e9l viviendo todav\u00eda san Vicente de Pa\u00fal, quien autoriz\u00f3 conferencias sobre esta materia, no s\u00f3lo con Misioneros, sino con h\u00e1biles externos. T como nos pudieron mandar transcribir suficientes copias del Manual para todas las casas, se crey\u00f3 necesario mandar imprimirlo. Dos ejemplares fueron enviados a cada fundaci\u00f3n de la Misi\u00f3n. Almeras los acompa\u00f1\u00f3, en 166, de una memoria sobre las ceremonias, que no conten\u00eda nada sobre las fiestas particulares del a\u00f1o, tanto m\u00f3viles como fijas, y no distingu\u00eda los diferentes oficios de los ministros del altar, del celebrante, del di\u00e1cono, etc. Todo esto se reserv\u00f3 a un segundo tomo que no apareci\u00f3 hasta mucho tiempo despu\u00e9s. El primer volumen tuvo una segunda edici\u00f3n en 1670. (&lt;em&gt;Histoire g\u00e9n\u00e9rale de la Ccongr\u00e9gation de la Mission, &lt;\/em&gt;mss., archivos de la Misi\u00f3n).'><sup>8<\/sup><\/a><\/span>. Tambi\u00e9n, ni una r\u00fabrica violada por \u00e9l, ninguna que \u00e9l permita que se alejan. Se humilla mucho delante de Dios y de sus hermanos por no poder hacer las genuflexiones de la manera prescrita por la Iglesia y, si cree haber faltado a alguna otra ceremonia, pide, despu\u00e9s del oficio, perd\u00f3n de rodillas a toda su comunidad<span id='easy-footnote-9-17795' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#easy-footnote-bottom-9-17795' title='&lt;em&gt;Summ&lt;\/em&gt;., p. 285.'><sup>9<\/sup><\/a><\/span>. Se imputa a s\u00ed mismo las faltas cometidas por los dem\u00e1s, lo que no le impide, a pesar de su gran dulzura, reprenderlos por ello severamente. Por lo dem\u00e1s, \u00e9l da tal ejemplo y tal edificaci\u00f3n, que los oficios de San L\u00e1zaro se distinguen en todo Par\u00eds por la religi\u00f3n, la dignidad y la modestia que presiden all\u00ed. . Vicente mismo, cuando canta o salmodia en el coro, se parece menos a un hombre que a un \u00e1ngel del cielo cantando las alabanzas de Dios. Sus sacerdotes y sus cl\u00e9rigos imitan su respeto y su piedad. Se los ve con los ojos bajos y detenidos en el libro, en una inmovilidad modesta, sin traicionar la vida m\u00e1s que por el piadoso resplandor de sus voces y los impulsos del amor divino.<\/p>\n<p>C\u00f3mo se muestra en los oficios p\u00fablicos, Vicente, lo es tambi\u00e9n a la vista de Dios solo, en la recitaci\u00f3n privada de su breviario. Lo recita siempre con la cabeza descubierta, de rodillas exceptuados los dos o tres \u00faltimos a\u00f1os de vida, que sus debilidades, al prohibirle esta postura humilde y respetuosa, le fuerzan a permanecer sentado. De rodillas tambi\u00e9n y cabeza descubierta hace su lectura cotidiana de la Sagrada Escritura y en particular del Nuevo Testamento.<\/p>\n<p>Despu\u00e9s de mas de tres horas dedicadas as\u00ed a la oraci\u00f3n por la ma\u00f1ana, incluso durante los inviernos m\u00e1s rigurosos, siempre de rodillas en el pavimento de la iglesia, sin permitir nunca que le cubran el lugar con una estera sencilla, Vicente vuelve a su habitaci\u00f3n. Habitaci\u00f3n m\u00e1s que modesta, habitaci\u00f3n peque\u00f1a, pobre y desnuda, paredes blanqueadas de cal, un suelo sin estera; por todo mueble una mesa de madera sin tapiz, dos sillas de paja y una cama de la que hablaremos m\u00e1s tarde cuando la descubra; por todo ornamento un crucifijo de madera y algunas im\u00e1genes de papel que un hermano, en diversos tiempos, ha pegado a las paredes, y que el santo acabar\u00e1 por mandarlas quitar, como contrarias a la pobreza, para quedarse con una sola. Ni fuego, ni siquiera chimenea, y eso hasta la edad de m\u00e1s de ochenta a\u00f1os, que sus disc\u00edpulos le forzaran a ocupar otra habitaci\u00f3n\u00a0 porque necesita un poco de fuego para vendar sus \u00falceras. Pero c\u00f3mo se humillar\u00e1! C\u00f3mo se acusar\u00e1 de pecados por haberle reducido a una miseria semejante, que \u00e9l llamar\u00e1 escandalosa<span id='easy-footnote-10-17795' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#easy-footnote-bottom-10-17795' title='&lt;em&gt;Summ&lt;\/em&gt;., p. 352..'><sup>10<\/sup><\/a><\/span>. Qu\u00e9 parsimonia pondr\u00e1 en el uso de le\u00f1a, que \u00e9l llama, como a todo lo dem\u00e1s,\u00a0 el bien de los pobres! Y todav\u00eda teme que haya demasiado lujo en\u00a0 su casa. Por eso, cuando se hace la visita de las habitaciones, exige que se visite tambi\u00e9n la suya para quitar todo lo que sea superfluo. \u00abHay en mi habitaci\u00f3n, dijo un d\u00eda, dos mantas, de las que me sirvo para hacerme sudar: que se las lleven.\u00bb La misma indigencia en la habitaci\u00f3n de abajo, donde recibe a las personas del mayor mundo. Un hermano a puesto u pedazo de tapiz una puerta por la cual se cuela un aire muy fr\u00edo: lo manda quitar ese mismo d\u00eda. Ya se ha visto las pobres ropas que lleva en la corte; as\u00ed de miserables son los objetos que usa; se conserva a\u00fan, por ejemplo su paraguas, trozo de tela encerada parecida a los pabellones en que se cobijan las pobres mujeres de nuestras plazas.<\/p>\n<p>Ve\u00e1mosle entregado del todo a las visitas y a los asuntos. Su diversidad y su n\u00famero no le quitan la calma en nada, su ecuanimidad y su recogimiento. Recibe con bondad,, y escucha con su atenci\u00f3n ordinaria a toda clase de personas del interior y del exterior. No las interrumpe nunca, m\u00e1s a\u00fan, antes de tomar \u00e9l mismo la palabra, pone siempre entre sus relatos o sus demandas, y su respuesta un intervalo de alg\u00fan instante, para reflexionar y consultar a Dios. San L\u00e1zaro es la casa de consulta universal, o m\u00e1s bien es la casa del vidente, como en el tiempo de los jueces de Israel, donde se dan cita, de Par\u00eds y de las provincias, todos aquellos que necesitan consejos para su persona o sus empresas. Nada se hace, por la religi\u00f3n o por la caridad, sin el parecer de Vicente y sin la cooperaci\u00f3n al menos de sus oraciones.<\/p>\n<p>Y no es suficiente con sus ocupaciones a domicilio. Todos los d\u00edas, dos veces por semana, lo m\u00e1s ordinario, el santo sacerdote sale y recorre todos los barrios de Par\u00eds, donde se reclama su presencia, donde hay que visitar alguno de sus establecimientos caritativos. Va a la corte para asistir a una sesi\u00f3n\u00a0 del consejo, o solicitar la caridad de la reina o mediar en las querellas de los partidos; tres veces por semana preside la Asamblea de las Damas y de los Se\u00f1ores; muchas veces es llamado a otras asambleas particulares, bien de prelados, bien de doctores, bien de superiores de comunidades o por \u00faltimo de personas de condici\u00f3n. De ah\u00ed se dirige a un monasterio, o a una familia, para restablecer el orden y la paz; va a animar a alguna cofrad\u00eda de la Caridad, a consolar a los presos y a los forzados, a visitar a los enfermos a domicilio y en los hospitales, a alegrar a los ancianos del Nombre de Jes\u00fas, a divertir a los peque\u00f1os ni\u00f1os exp\u00f3sitos.<\/p>\n<p>En el paso de un lugar a otro, emplea cuidadosamente el tiempo. Reza, combina una obra, prepara una instrucci\u00f3n; a veces incluso, cuando va en veh\u00edculo, escribe: \u00abEsta carta, dice una vez, se hace en plena calle de Par\u00eds, donde me hallo con un espacio para escribiros.\u00bb<span id='easy-footnote-11-17795' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#easy-footnote-bottom-11-17795' title='Carta a Martin, en G\u00e9nova, del 28 de julio de 1651.'><sup>11<\/sup><\/a><\/span>\n<p>Pero en el tumulto de las calles, de la corte y de las asambleas, lo mismo que en el silencio y la soledad de su habitaci\u00f3n, no pierde de vista a Dios ni su santa presencia. Piensa en ello lo menos cuatro veces a la hora. Suena el reloj: en seguida se descubre, hace la se\u00f1al de la cruz y levanta los ojos al cielo. Normalmente los tiene bajos, y hasta cerrados cuando va en carroza y no los abre m\u00e1s que al crucifijo del rosario que lleva siempre en su cintur\u00f3n. Para no ver nada, no ser visto de nadie y poderse dirigir a Dios m\u00e1s f\u00e1cilmente, corre casi siempre la cortina del veh\u00edculo. Por lo dem\u00e1s, la vista de las criaturas, muy lejos de distraerle, le lleva a su autor. Campos cubiertos de mieses, \u00e1rboles cargados de frutos le dan lugar a bendecir la bondad de Dios y su paternal Providencia; las flores, los p\u00e1jaros o todo otro objeto agradable le hacen exclamar: \u00ab\u00bfQu\u00e9 hay que se pueda comparar a la belleza de Dios, que es el principio de toda la belleza y perfecci\u00f3n de las criaturas? \u00bfAcaso no toman su lustre y esplendor de \u00e9l?\u00bb<\/p>\n<p>Lo m\u00e1s com\u00fan sin embargo es priv\u00e1ndose de la vista de los objetos agradables y mortificando sus sentidos, que honre a dios y se mantenga unido a \u00e9l. No mira ni los hermosos campos, ni los brillantes edificios. No recibe nunca flores. A su perfume \u00e9l prefiere el olor malo de los hospitales o de las habitaciones de enfermos. A pesar de su sensibilidad a las temperaturas extremas. \u00c9l no se cuida ni contra el fr\u00edo ni contra el calor; ni siquiera guantes en invierno, y sus manos se hinchan y se agrietan como sus piernas.<\/p>\n<p>Si se encuentra con alguien en estas santas pr\u00e1cticas, que \u00e9l aconseja a todos, se humilla como si \u00e9l mismo faltara en ello. Una persona del mundo se acusa a \u00e9l de haber estado tres veces al d\u00eda distra\u00edda del pensamiento de Dios, y \u00e9l exclama: \u00abEsa gente ser\u00e1n nuestros jueces que nos condenen ante la majestad divina del olvido que tenemos de ella, nosotros que no tenemos otra cosa que hacer que imitarle y manifestarle nuestro amor con nuestras miradas y nuestros servicios.\u00bb<\/p>\n<p>Si camina a pie por las calles, observa el mismo recogimiento y las mismas pr\u00e1cticas. Al pasar por delante de una iglesia, entra y se prosterna con el rostro en tierra. Que suena el <em>Angelus, <\/em>en medio de la gente como en la corte, se descubre, cae de rodillas y lo recita. No ve a nadie, si bien todos le miran y admiran, los ni\u00f1os mismos se le se\u00f1alan y dicen: \u00abMirad al santo que pasa!\u00bb<\/p>\n<p>Regresa por fin. Saluda enseguida a la sant\u00edsima Virgen y al \u00e1ngel de la guarda, como lo ha hecho al salir, como lo hace siempre y como prescribe que se haga a la entrada y al salir de una habitaci\u00f3n; como al salir tambi\u00e9n va a adorar al Sant\u00edsimo Sacramento, que \u00e9l llama el amo de la casa. Es muy tarde a veces, y sin embargo se olvida all\u00ed muchas horas. Acaba por entrar en el refectorio<span id='easy-footnote-12-17795' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#easy-footnote-bottom-12-17795' title='Vicente hab\u00eda establecido la costumbre de un examen particular antes de la comida, que hac\u00eda seguir de un &lt;em&gt;De profundis &lt;\/em&gt;por los bienhechores de la Compa\u00f1\u00eda; costumbre que ha sido adoptada por un gran n\u00famero de comunidades.'><sup>12<\/sup><\/a><\/span>. Si la comunidad se encuentra, \u00e9l se sienta donde encuentra libre, lo m\u00e1s frecuente en el \u00faltimo asiento, incluso detr\u00e1s de los hermanos. Ninguna distinci\u00f3n entre \u00e9l y los suyos, por la alimentaci\u00f3n como por el lugar, hasta en las debilidades de una extrema ancianidad. Si la comida comunitaria se ha terminado, su mortificaci\u00f3n se alegra, pues no le quedan m\u00e1s que restos, y cuanto m\u00e1s escasos y poco apetitosos, m\u00e1s deliciosas le parecen las sobras. Adem\u00e1s parece no sentir apetito por nada, menos todav\u00eda preferencia. Le sirven huevos crudos por un descuido: se los come sin decir palabra, y nadie se entera hasta el d\u00eda siguiente por el cocinero. Si se ha servido todo, \u00e9l no pide nada y se contenta con un poco de pan. En cuanto al vino, no lo reclama nunca y no bebe m\u00e1s que agua clara. Acabada esta comida sobria en un instante, es lo primero que\u00a0 toma y a menudo lo \u00fanico en todo el d\u00eda, ya que ha llegado muy tarde y, seg\u00fan su costumbre, no ha comido nada por la ma\u00f1ana. En su extrema vejez, le insisten para que tome alg\u00fan caldo antes de salir. \u00abVos me tent\u00e1is, se\u00f1or, dice al sacerdote que se lo presenta. \u00bfNo es el demonio el que os hace persuadirme que alimente as\u00ed a este miserable cuerpo, a esta despreciable carcasa, es esto justo? Que Dios os lo perdone! \u00abNo obstante en sus \u00faltimos d\u00edas, consiente en tomar por la ma\u00f1ana una poci\u00f3n, pero tan s\u00f3lo a modo de medicina: pues es un caldo sin carne, preparado con achicoria salvaje y cebada mondada, donde no entre ni saz\u00f3n, ni grasa, ni mantequilla, ni aceite.<\/p>\n<p>Y a pesar de todo tiene un gran apetito. Un d\u00eda, ense\u00f1ando un pan de dos o tres libras, dijo: \u00abSi me hiciera caso a m\u00ed mismo, me comer\u00eda todo eso\u00bb. No es suficiente para su mortificaci\u00f3n\u00a0 con un alimento\u00a0 malo y tomado en demasiada peque\u00f1a cantidad; tiene tambi\u00e9n en reserva polvos amargos que los mezcla para hacerle m\u00e1s desagradable al gusto. La naturaleza a veces sucumbe, y por la noche necesita llevar un pedazo de pan seco en un desfallecimiento, \u00fanico confort que quiera aceptar.<\/p>\n<p>Es toda la comida para reparar las fuerzas perdidas en una larga jornada de trabajo, y adem\u00e1s se lo reprocha y, cada noche, sent\u00e1ndose ante su pobre pitanza, exclama: \u00abAh, miserable, no has ganado el pan que te comes!\u00bb<\/p>\n<p>Es un ayuno continuo. No obstante, guarda uno m\u00e1s riguroso dos veces por semana y todos los d\u00edas mandados por la Iglesia. Con m\u00e1s ochenta a\u00f1os se contenta con las salazones servidas a la comunidad. Quieren enga\u00f1arle cuando llega despu\u00e9s de los dem\u00e1s y servirle pescado fresco, pero se informa de lo que se ha dado a todos y, si no se le trata como a ellos, no come. La noche, un poco de pan, una manzana y agua\u00a0 roja constituyen toda su colaci\u00f3n. Se abstiene de todo cuando llega un poco tarde de la ciudad; entonces, sin comer, se retira a su habitaci\u00f3n, o va a la iglesia a presidir una conferencia espiritual. Es tan duro consigo mismo, que es preciso, para moderarle, hacer intervenir a las autoridades mayores y, ante las s\u00faplicas de sus hijos, el cardenal de La Rochefoucauld le ordena cuidar una salud preciosa en la Iglesia.<\/p>\n<p>Despu\u00e9s de la comida, los suyos tienen una hora de recreaci\u00f3n; \u00e9l no se la toma nunca. Por \u00faltimo, todos se retiran y pronto San L\u00e1zaro se sumerge en el silencio; \u00e9l solo vela. Sus noches son casi siempre tan laboriosas como sus d\u00edas. Se ha encontrado, a su vuelta por la noche una multitud de cartas; es por la noche cuando las responde. Le llegan de todos los puntos del reino, de Italia, de Polonia, de Berber\u00eda y de Madagascar. Es un obispo, un abad, un director quienes le consultan sobre los asuntos m\u00e1s importantes y m\u00e1s delicados; son grandes se\u00f1ores, grandes damas que le proponen misiones en sus tierras o alguna obra de caridad; es la congregaci\u00f3n de Propaganda, la compa\u00f1\u00eda de las Indias las que piden sacerdotes para Asia y para \u00c1frica; es una pobre madre quien le ruega que se interese en\u00a0 un hijo cautivo en Argel, o bien un renegado quien le suplica que le arregle su regreso a la fe; son los nuncios en Francia que quieren tener su parecer\u00a0 sobre las cuestiones que interesan a la Iglesia galicana o incluso la Iglesia universal; son jefes de religiones, superiores de comunidades que reclaman su concurso para la reforma de su orden o de su casa, o bien un religioso, una sencilla novicia quienes le consultan sobre su vocaci\u00f3n o cambio de estado; es una multitud de p\u00e1rrocos, de sacerdotes quienes le someten la dificultades de su ministerio o de su conciencia; por fin, y sobre todo es su doble familia de misioneros o de Hijas de la Caridad la que exige sus cuidados de todos los d\u00edas. Al menor de sus hijos responde con una exactitud que iguala sola su bondad; a todas sus casas escribe regularmente cada semana, y a cada una transmite, aparte de los consejos y de las decisiones, las noticias generales de la Compa\u00f1\u00eda: sus cartas son as\u00ed una especie de gaceta de la Misi\u00f3n y de su obras.<\/p>\n<p>Con la mayor frecuencia le dan las doce de la noche, y est\u00e1 todav\u00eda trabajando. Piensa al fin en tomar algo de reposo. Pero no ser\u00e1 sin castigarse por tantas buenas obras, en las que \u00e9l no descubre m\u00e1s que imperfecci\u00f3n<\/p>\n<p>y pecado, con una dura disciplina; por la ma\u00f1ana se hab\u00eda preparado por un penitencia parecida. Un hermano, su vecino, y cuya habitaci\u00f3n no est\u00e1 separada de la suya m\u00e1s que por unas planchas, afirma que hace doce a\u00f1os que dura eso. Hay mucho m\u00e1s: se remonta por lo menos a Ch\u00e2tillon, donde sus hu\u00e9spedes le oyeron con frecuencia entregarse a esta dura gimn\u00e1stica, donde se le encontr\u00f3 bajo su cabecera, despu\u00e9s de su partida, un instrumento de penitencia olvidado. Desde entonces, ni de viaje, ni siquiera en enfermedad, ha dejado de usarlo. Pero eso no deja de ser m\u00e1s que el ejercicio reglado y cotidiano de su mortificaci\u00f3n. Se impone penitencias extraordinarias en las desgracias p\u00fablicas, en las necesidades generales y particulares de su Compa\u00f1\u00eda, y sobre todo cuando se entera de alguna falta cometida en alguna de sus casas. Entonces, comienza por darse la disciplina dos veces por noche durante una semana, para expiar las faltas de los dem\u00e1s, que \u00e9l se imputo siempre a s\u00ed mismo: \u00abMis pecados, dice, son causa de todo el mal que sucede; \u00bfno es justo que haga penitencia? \u00bb Luego busca el remedio y lo aplica. En todo tiempo, a la disciplina a\u00f1ade el cilicio, los brazaletes, los cinturones de cuero con puntas, que \u00e9l sustituye a veces por una camisa de penitencia conservada a\u00fan, que hace temblar nada m\u00e1s verla.<\/p>\n<p>Por \u00faltimo cae de rodillas para las \u00faltimas oraciones y para hacer su preparaci\u00f3n cotidiana a la muerte. Descubre la cama, que no es sino un rudo jerg\u00f3n, sin colch\u00f3n, sin cortinas, y hasta sin s\u00e1banas los \u00faltimos a\u00f1os de su vida. Por lo menos cuarenta a\u00f1os se ha acostado de esa manera, ya que, con ocasi\u00f3n del viaje de Macon, los Oratorianos que le hab\u00edan alojado, habiendo entrado una ma\u00f1ana temprano en su habitaci\u00f3n, vieron que hab\u00eda quitado el colch\u00f3n de su cama. Por corresponder a las peticiones de los suyos, acab\u00f3 por consentir que le pusieran una cortina, pero \u00e9l contin\u00faa acost\u00e1ndose en la paja. Y encima, c\u00f3mo se culpa por este <em>lujo de cama<\/em>, esta cama con cortinas. Se puede juzgar tambi\u00e9n de este lujo hoy, a la vista de estas cortinas preciosamente conservadas, que se parecen a la gruesa sarga que rodea la cama de los m\u00e1s pobres granjeros de nuestros campos.<\/p>\n<p>Muy a menudo, en este lecho miserable, no encuentra ni descanso ni sue\u00f1o. La fiebre le devora, sus \u00falceras le torturan, se ahoga en sudores; durante esos largos y crueles insomnios, bendice a Dios, ora o combina sus santas empresas.<\/p>\n<p>Esto es una jornada de san Vicente de Pa\u00fal, el tejido uniforme de su vida. Natural que despu\u00e9s de una serie de d\u00edas tan larga, estuviera preparado a comparecer ante Dios, y parece que no tuvo otra cosa que recibir su recompensa. Pero Dios, admirable en sus santos, celoso de su m\u00e1s grande perfecci\u00f3n, quer\u00eda todav\u00eda probar a su fiel servidor. Por eso, poco antes de su muerte, le golpe\u00f3 en los bienes de su comunidad, yen las personas que le eran m\u00e1s queridas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Libro IX: Muerte de san Vicente de Pa\u00fal Cap\u00edtulo I: Retrato y Jornada. I. Retrato. Antes de que san Vicente de Pa\u00fal nos sea robado por la muerte, contemplemos por \u00faltima vez sus rasgos, esbocemos &#8230; <a href=\"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":103451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[218,168,173,142,172,143,116],"class_list":["post-17795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vicente-de-paul","tag-abelly","tag-argel","tag-chatillon-les-dombes","tag-collet","tag-pobreza","tag-san-lazaro","tag-tunez"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Vicente de Pa\u00fal. Su vida, su tiempo; sus obras, su influencia. Libro 9, cap\u00edtulo 1 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Vicente de Pa\u00fal. Su vida, su tiempo; sus obras, su influencia. Libro 9, cap\u00edtulo 1 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Libro IX: Muerte de san Vicente de Pa\u00fal Cap\u00edtulo I: Retrato y Jornada. I. Retrato. Antes de que san Vicente de Pa\u00fal nos sea robado por la muerte, contemplemos por \u00faltima vez sus rasgos, esbocemos ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-03T01:54:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T15:21:47+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"69 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"San Vicente de Pa\u00fal. Su vida, su tiempo; sus obras, su influencia. Libro 9, cap\u00edtulo 1\",\"datePublished\":\"2015-02-03T01:54:17+00:00\",\"dateModified\":\"2016-07-26T15:21:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/\"},\"wordCount\":13717,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Abelly\",\"Argel\",\"Chatillon\",\"Collet\",\"Pobreza\",\"San L\u00e1zaro\",\"T\u00fanez\"],\"articleSection\":[\"Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/\",\"name\":\"San Vicente de Pa\u00fal. Su vida, su tiempo; sus obras, su influencia. Libro 9, cap\u00edtulo 1 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-02-03T01:54:17+00:00\",\"dateModified\":\"2016-07-26T15:21:47+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Vicente de Pa\u00fal. Su vida, su tiempo; sus obras, su influencia. Libro 9, cap\u00edtulo 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Vicente de Pa\u00fal. Su vida, su tiempo; sus obras, su influencia. Libro 9, cap\u00edtulo 1 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/","og_locale":"es_ES","og_type":"article","og_title":"San Vicente de Pa\u00fal. Su vida, su tiempo; sus obras, su influencia. Libro 9, cap\u00edtulo 1 - Somos Vicencianos","og_description":"Libro IX: Muerte de san Vicente de Pa\u00fal Cap\u00edtulo I: Retrato y Jornada. I. Retrato. Antes de que san Vicente de Pa\u00fal nos sea robado por la muerte, contemplemos por \u00faltima vez sus rasgos, esbocemos ... Read More","og_url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-02-03T01:54:17+00:00","article_modified_time":"2016-07-26T15:21:47+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"69 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"San Vicente de Pa\u00fal. Su vida, su tiempo; sus obras, su influencia. Libro 9, cap\u00edtulo 1","datePublished":"2015-02-03T01:54:17+00:00","dateModified":"2016-07-26T15:21:47+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/"},"wordCount":13717,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#primaryimage"},"thumbnailUrl":"","keywords":["Abelly","Argel","Chatillon","Collet","Pobreza","San L\u00e1zaro","T\u00fanez"],"articleSection":["Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/","url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/","name":"San Vicente de Pa\u00fal. Su vida, su tiempo; sus obras, su influencia. Libro 9, cap\u00edtulo 1 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-02-03T01:54:17+00:00","dateModified":"2016-07-26T15:21:47+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-su-vida-su-tiempo-sus-obras-su-influencia-libro-9-capitulo-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"San Vicente de Pa\u00fal. Su vida, su tiempo; sus obras, su influencia. Libro 9, cap\u00edtulo 1"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-4D1","jetpack-related-posts":[{"id":118520,"url":"http:\/\/vincentians.com\/es\/bibliografia-basica-sobre-san-vicente-de-paul\/","url_meta":{"origin":17795,"position":0},"title":"Bibliograf\u00eda b\u00e1sica sobre san Vicente de Pa\u00fal","author":"Francisco Javier Fern\u00e1ndez Chento","date":"14\/03\/2015","format":false,"excerpt":"ABELLY Louis: Vida del Venerable Siervo de Dios Vicente de Pa\u00fal, Fundador y primer Superior General de la Congregaci\u00f3n de la Misi\u00f3n. Salamanca: CEME. 1994. 814p 25cm. Abelly public\u00f3 esta obra s\u00f3lo cuatro a\u00f1os despu\u00e9s de la muerte de San Vicente, a quien conoci\u00f3 durante m\u00e1s de veinte a\u00f1os. Ha\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"vicentepaul","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/12\/vicentepaul-235x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":119544,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-y-su-entronque-hispanico-ii\/","url_meta":{"origin":17795,"position":1},"title":"San Vicente de Pa\u00fal y su entronque hisp\u00e1nico (II)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"06\/05\/2013","format":false,"excerpt":"Art\u00edculo segundo: Oriundez hisp\u00e1nica de San Vicente de Pa\u00fal Los padres del santo se llamaban Juan de Pa\u00fal y Bel\u00adtranda de Moras, procedentes de Tamarite de Litera, regi\u00f3n del Alto Arag\u00f3n, lindante con la provincia de L\u00e9rida. R.anquines era un caser\u00edo de Pouy, en donde se hab\u00eda ins\u00adtalado el matrimonio\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"SANV","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/04\/SANV.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":121642,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-04\/","url_meta":{"origin":17795,"position":2},"title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 04","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/07\/2024","format":false,"excerpt":"Cap\u00edtulo IV Vicente de Pa\u00fal en la casa del general de las galeras. - Retratos de familia: Felipe Manuel de Gondi, su mujer Margarita de Silly y sus hijos. - Vicente de Pa\u00fal, fundador. Volvamos sobre nuestros pasos y entremos en el castillo de Montmirail donde, hacia el fin del\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=1050%2C600 3x"},"classes":[]},{"id":121635,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-00-prefacio\/","url_meta":{"origin":17795,"position":3},"title":"San Vicente de Pa\u00fal y los Gondi: 00 Prefacio","author":"Francisco Javier Fern\u00e1ndez Chento","date":"31\/12\/2013","format":false,"excerpt":"Prefacio Los historiadores antiguos y modernos de san Vicente de Pa\u00fal. - Publicaci\u00f3n de su correspondencia - Documentos in\u00e9ditos del Oratorio y de los archivos del Ministerio de Asuntos exteriores. Dos siglos despu\u00e9s, ser\u00eda dif\u00edcil citar a un hombre ilustre, por grande que fuera su fama, cuya vida haya sido\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"Felipe-Manuel de Gondi","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2013\/12\/Felipe-Manuel_de_Gondi-185x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":130435,"url":"http:\/\/vincentians.com\/es\/las-viejas-caridades-vicencianas-y-las-modernas-conferencias-de-san-vicente-de-paul\/","url_meta":{"origin":17795,"position":4},"title":"Las viejas \u00abCaridades\u00bb y las modernas \u00abConferencias\u00bb","author":"Francisco Javier Fern\u00e1ndez Chento","date":"08\/05\/2014","format":false,"excerpt":"La cuna de las \"Caridades\" No muy lejos de Li\u00f3n, en las rientes y f\u00e9rtiles m\u00e1rgenes del Chalaronne, hay una peque\u00f1a poblaci\u00f3n, denominada Chatini les-Dombes, que en el a\u00f1o de gracia de 1617 acaba de adquirir en su nuevo y joven p\u00e1rroco, un gran tesoro. Tiene 36 a\u00f1os escasos. Llamase\u2026","rel":"","context":"En \u00abHistoria de la Sociedad de san Vicente de Pa\u00fal\u00bb","block_context":{"text":"Historia de la Sociedad de san Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-la-sociedad-de-san-vicente-de-paul\/"},"img":{"alt_text":"Retrato de Federico Ozanam en 1852, copia en miniatura del retrato hecho por Janmot Louis (1814-1892), hecha probablemente por el propio pintor.","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/01\/Frederic_Ozanam.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":131353,"url":"http:\/\/vincentians.com\/es\/el-senor-vicente-evolucion-de-un-santo-vi\/","url_meta":{"origin":17795,"position":5},"title":"El se\u00f1or Vicente, evoluci\u00f3n de un santo (VI)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"28\/09\/2014","format":false,"excerpt":"6. LA FRAGUA INTERIOR 1. Cimientos del car\u00e1cter. \u2013 2. El Gasc\u00f3n.- 3. Razas del sur de Francia.- 4. Retratos de San Vicente de Pa\u00fal.- 5. El se\u00f1or Vicente y las razas de Asia anterior y oriental.- 6. Su complexi\u00f3n ps\u00edquica.- 7. Temperamento.- 8. Behaviorismo o conductismo.- 9. Constituci\u00f3n y\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"coraz\u00f3n","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/03\/coraz%C3%B3n.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/17795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=17795"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/17795\/revisions"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=17795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=17795"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=17795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}