{"id":14994,"date":"2012-09-15T03:31:28","date_gmt":"2012-09-15T01:31:28","guid":{"rendered":"http:\/\/somos.vicencianos.org\/blog\/2010\/03\/26\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/"},"modified":"2012-09-15T03:31:28","modified_gmt":"2012-09-15T01:31:28","slug":"compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/","title":{"rendered":"Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 10"},"content":{"rendered":"<h2>Cap\u00edtulo d\u00e9cimo: Veneraci\u00f3n al se\u00f1or Perboyre despu\u00e9s de su muerte y hechos extraordinarios que parecen autorizarla (1840-1885)<\/h2>\n<blockquote><p>1 \u2014 Veneraci\u00f3n inspirada por el m\u00e1rtir antes de su muerte y que se torna en culto despu\u00e9s de ella. \u2014 2. Aparici\u00f3n de una cruz luminosa. \u2014 3. El siervo de Dios se aparece a un pagano, que se convierte. \u2014 4 Curaci\u00f3n extraordinaria de la hermana Antonieta Vicent en Constantinopla. \u2014 5. Otra curaci\u00f3n no menos extraordinaria de Sor Margarita Bouyssi\u00e9 en la Casa-Madre de las Hijas de la Caridad en Par\u00eds. \u2014 6. Castigos con que la Divina Justicia hiere a los perseguidores del se\u00f1or Perbovre. \u2014 7. Traslaci\u00f3n de sus preciosas reliquias a la Casa-Madre de la Congregaci\u00f3n de la Misi\u00f3n en Par\u00eds. \u2014 8. Esperanza de su pr\u00f3xima beatificaci\u00f3n.<\/p><\/blockquote>\n<p><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/06\/perboyre.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-91766\" title=\"perboyre\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/06\/perboyre-240x300.jpg?resize=240%2C300\" alt=\"\" width=\"240\" height=\"300\" \/><\/a>1. Viviendo, y antes de haber sufrido tantos tormentos por el nombre de Jesucristo, ya inspiraba el Sr. Perboyre una verdadera veneraci\u00f3n a todos cuantos se le acercaban. Con frecuencia se oy\u00f3 decir al Padre Rizzolati, misionero capuchino que se hallaba de paso en la residencia de Tcha-Yuen-Keou cuando estall\u00f3 la persecuci\u00f3n, y que despu\u00e9s fue Vicario Apost\u00f3lico en Hou-Kouang: \u00abAunque el Sr. Perboyre no hubiera obtenido la palma del martirio, sus virtudes heroicas le hubieran merecido subir a los altares.\u00bb<\/p>\n<p>Pero despu\u00e9s que tan generosamente confes\u00f3 la fe y habiendo coronado el Se\u00f1or con muerte preciosa sus gloriosos c\u00f3mbales, cambi\u00f3se esta veneraci\u00f3n en una especie de culto. Dios mismo parece que la autoriza por hechos extraordinarios, que no pertenece a nos\u00adotros calificar, pero que llevan en s\u00ed todas las se\u00f1ales de una intervenci\u00f3n sobrenatural.<\/p>\n<p>2. Tal es, en primer lugar, la aparici\u00f3n de una cruz luminosa que un misionero de la China refiere en los siguientes t\u00e9rminos: \u00abCuando el Sr. Perboyre fue martirizado, una cruz grande y luminosa apareci\u00f3 en el cielo. Fue observada por muchos fieles que ha\u00adbitaban diversas cristiandades, muy distantes las unas de las otras.\u00bb Tambi\u00e9n fueron testigos de este prodigio muchos paganos, de los cuales algunos gritaron: \u00abHe ah\u00ed el signo que adoran los cristianos; yo renuncio a los \u00eddolos, y quiero servir al Se\u00f1or del cielo.\u00bb Abra\u00adzaron efectivamente el Cristianismo, y Mr. Clauzetto les administr\u00f3 el Bautismo. Cuando Su Ilustr\u00edsima supo estos acontecimientos no les dio grande impor\u00adtancia; mas despu\u00e9s, impresionado por el n\u00famero y calidad de los testigos y de sus testimonios abri\u00f3 una verdadera informaci\u00f3n, de la cual resulta claramente: que apareci\u00f3 en los cielos una cruz grande, luminosa y bien formada; que fue vista al mismo tiempo, de la misma manera y forma, en el mismo punto del cielo y del mismo grandor por un gran n\u00famero de testigos cristianos y paganos; que estos testigos habitaban dis\u00adtritos muy distantes unos de otros, y que no pudieron tener entre s\u00ed ninguna comunicaci\u00f3n. Adem\u00e1s, Su Ilustr\u00edsima ha preguntado a los cristianos que conoc\u00edan al Sr. Perboyre, y todos han declarado que siempre le miraron como a un gran santo.<\/p>\n<p>3. El mismo siervo de Dios apareci\u00f3 despu\u00e9s de su muerte a varias personas, cuyos testimonios no pueden ponerse en duda. Tambi\u00e9n le manifest\u00f3 una vez a un pagano, a aquel pagano misericordioso llamado Lieu-Kioun-Lin, el cual le hab\u00eda hecho llevar a expensas suyas en una litera desde el mercado de Kouang-In-Tam a la ciudad de Kou-Tchagn-Kieng. He aqu\u00ed c\u00f3mo supo pagarle con usura la deuda del reconocimiento. Habiendo Lieu-Kioun-Lin ca\u00eddo enfermo algunos a\u00f1os despu\u00e9s de la muerte del siervo de Dios, se vio muy pronto a las puertas de la muerte. Hall\u00e1ndose desahuciado por completo y absorto en pensamientos desoladores, apareci\u00f3sele el Sr. Perboyre en lo alto de una escalera de color rojo, junto a la cual hab\u00eda otra de color blanco y le invitaba a que por \u00e9sta fuese a juntarse con \u00e9l. Dec\u00edale: \u00abAh\u00ed donde est\u00e1s sufres mucho, \u00bfno es verdad? Pues bien: ven por esa escalera blanca aqu\u00ed, en donde yo estoy, y ser\u00e1s dichoso.\u00bb Trat\u00f3 entonces de subir el enfermo, pero como el demonio se esforzase en impedirlo bajo una forma horrible, pronunci\u00f3 el nombre de Jes\u00fas, cuya virtud omnipotente le hab\u00edan hecho conocer los cristianos, y al punto desapareci\u00f3 la visi\u00f3n. Recordando entonces todas las circunstancias de la aparici\u00f3n, as\u00ed como las reiteradas exhortaciones por las cuales el siervo de Dios, cuando viv\u00eda, trat\u00f3 de abrir sus ojos a la luz, declar\u00f3 ante todos los suyos, con grande sorpresa de \u00e9stos, que quer\u00eda hacerse cristiano. Hizo luego venir a un catequista, quien hall\u00e1ndole suficientemente instruido le administr\u00f3 el bautismo: algunos d\u00edas despu\u00e9s entreg\u00f3 al Se\u00f1or su alma regenerada.<\/p>\n<p>4. Vamos a citar en otro orden de cosas un hecho no menos extraordinario, una curaci\u00f3n declarada por muchos m\u00e9dicos milagrosa.<\/p>\n<p>Hab\u00eda en Constantinopla en una casa de Hijas de la Caridad una hermana llamada Antonieta Vincent, aplicada a la clase de los ni\u00f1os. Todo el mundo la apreciaba, as\u00ed por su bondad y dulzura, que eran grandes, como a causa de la abnegaci\u00f3n sin l\u00edmites con que trataba de cumplir con su oficio. As\u00ed es que todos sintieron mucho que cayese enferma. La indis\u00adposici\u00f3n que padec\u00eda databa ya de bastante tiempo. Sent\u00eda con alguna interrupci\u00f3n agud\u00edsimo dolor al costado, y cuando desaparec\u00eda por breves momentos, s\u00f3lo era para volver a acometerla con m\u00e1s violencia. Hab\u00edanse pasado ya nueve a\u00f1os en estas alternativas, cuando en Diciembre de 1841 se tornaron los dolores tan fuertes y continuos, que no dejaban a la paciente momento de reposo. En medio de tan espantosos pa\u00addecimientos, la hermana, llena de valor y de virtud, todav\u00eda pudo hacer su clase por espacio de tres sema\u00adnas enteras. Pero, al fin, vencida por el mal, tuvo que rendirse a la cama y entonces fue cuando se conoci\u00f3 el verdadero car\u00e1cter del mal. Era una apos\u00adtema interior que, despu\u00e9s de muchos a\u00f1os de for\u00admaci\u00f3n lenta y progresiva, acababa de abrirse, y merced a la gangrena ya inevitable, pon\u00eda en peligro inminente los d\u00edas de la enferma. As\u00ed lo aseguraron los m\u00e9dicos, seg\u00fan el testimonio de su Superiora: \u00abDesahuciada Sor Antonieta, dice, por muchos m\u00e9\u00addicos, llamamos a otros, los cuales juzgaron un\u00e1ni\u00admemente en presencia m\u00eda que la apostema formada al lado izquierdo hab\u00eda ulcerado el bazo, produciendo tal desorden en la regi\u00f3n del coraz\u00f3n, que su existencia no pod\u00eda prolongarse m\u00e1s all\u00e1 de algunos d\u00edas. No quisieron firmar su consulta, porque dec\u00eda que eso ser\u00eda firmar una <em>partida mortuoria. <\/em>Uno de ellos tuvo el valor verdaderamente cristiano de manifest\u00e1rselo a la enferma, y dijo tomando el Crucifijo: \u00abHe ah\u00ed el que s\u00f3lo puede volveros la salud en defecto de la ciencia impotente.\u00bb La hermana Antonieta recibi\u00f3 entonces los \u00faltimos Sacramentos, con disposiciones verdaderamente edificantes, y despu\u00e9s de ellos la indulgencia plenaria en el art\u00edculo de la muerte. Todos tem\u00edamos a cada instante verla exhalar el \u00faltimo suspiro.<\/p>\n<p>Antes, empero, que el m\u00e9dico desconfiase de los remedios humanos, hab\u00edamos recurrido a los sobrenaturales, y ya se hab\u00edan comenzado dos novenas de oraciones al Venerable Perboyre, la una por las Hermanas de la enferma, la otra por las ni\u00f1as disc\u00edpulas suyas. Estas hac\u00edanla con tanto fervor que, uniendo el sacrificio a la oraci\u00f3n, hasta se privaban de las cosillas a que en su edad se tiene, tanto afecto para poder comprar las velas de la novena.<\/p>\n<p>Era viernes en la noche del 21 de Enero de 1842, quinto d\u00eda de la novena de las Hermanas y tercero de la de las ni\u00f1as, y la enferma perd\u00eda m\u00e1s y m\u00e1s; el estertor que comenzaba, el color terroso de su cara, el olor a cad\u00e1ver que exhalaba ya, todo anunciaba que le quedaban tan s\u00f3lo algunas horas de vida, y he aqu\u00ed que repentinamente duerme un sue\u00f1o profundo, dulce y tranquilo, que dur\u00f3 tres horas. Cuando despert\u00f3 era ya media noche: sinti\u00f3se aliviada y fortificada, sent\u00f3se en la cama y se toc\u00f3 el lado, en donde ning\u00fan dolor sent\u00eda. Procur\u00f3 entonces tomar alg\u00fan alimento, caldo, uvas, cuarterones de naranja, que era lo que ten\u00eda a mano; todo le parec\u00eda de un gusto excelente. Barruntaba que algo de extraordinario se hab\u00eda operado en ella; pero temiendo ser el juguete de su imaginaci\u00f3n, no osaba creerlo, ni mucho menos decirlo. Estaba, por lo dem\u00e1s, tan conforme con la muerte, hab\u00edala aceptado tan generosamente y a\u00fan con tal gozo, que sent\u00eda ver prolongado su destierro y as\u00ed prefer\u00eda creerse v\u00edctima de una ilusi\u00f3n.<\/p>\n<p>Los testigos de esta escena tampoco se atrev\u00edan a creer en la curaci\u00f3n: \u00abObserv\u00e1bamos perfectamente, dice su Superiora, que la respiraci\u00f3n y todos los rasgos de su cara hab\u00edan tomado su estado natural, pero no nos fi\u00e1bamos de estos s\u00edntomas consoladores, pues que muchos enfermos se hallan al parecer mejor poco antes de morir. \u00bb<\/p>\n<p>Sin embargo, muy pronto ya no fue posible la duda; llegada la ma\u00f1ana, quiso levantarse; habiendo obtenido el permiso, se visti\u00f3 sola, arregl\u00f3 su cama, subi\u00f3 sin apoyo alguno tres pisos que la separaban de la capilla, y despu\u00e9s de haber agradecido al Se\u00f1or el bien que se hab\u00eda dignado concederla, fue a visitar a una de sus compa\u00f1eras enferma. La Superiora, las Hermanas, las ni\u00f1as, todo el mundo estaba lleno de admiraci\u00f3n. No estaba menos sorprendido el m\u00e9dico de la casa, pero antes de pronunciarse acerca de un hecho tan extra\u00f1o quiso examinar a la enferma. Ha\u00adbiendo, pues, palpado el sitio en donde radicaba el mal, declar\u00f3 que no ten\u00eda m\u00e1s que una parte del bazo, pero que la llaga estaba enteramente cicatrizada y la curaci\u00f3n era perfecta, lo cual s\u00f3lo pod\u00eda explicarse por un milagro. Del mismo parecer fueron los otros m\u00e9dicos de la consulta, entre los cuales se hallaba un jud\u00edo; uno de ellos hasta se neg\u00f3 a recibir los honorarios, diciendo que se avergonzar\u00eda de recibir cosa alguna por una operaci\u00f3n cuyo autor era solo Dios.<\/p>\n<p>5. Hacia la misma \u00e9poca hubo en Par\u00eds otra Hija de la Caridad objeto de una curaci\u00f3n tan maravillosa como la anterior. Llam\u00e1base Margarita Bouyssi\u00e9, y en 1842 contaba veinti\u00fan a\u00f1os. De salud d\u00e9bil, dice el Sr. J. Ratheau que la asist\u00eda, de temperamento linf\u00e1tico, con muchas enfermedades, de las cuales especialmente era bastante grave una que padec\u00eda en el hospital en donde hac\u00eda la prueba para ser Hija de la Caridad, el 2 de Abril cay\u00f3 con una pleuro-pneumon\u00eda grav\u00edsima. A pesar de las sangr\u00edas, ya generales, ya locales y de las bebidas atemperantes, se agrav\u00f3 el mal de tal modo, que fue necesario administrarla. Sin embargo, poco a poco fue disminuyendo la intensidad de los accidentes y lleg\u00f3 a una cuasi convalecencia; entonces se la prescribi\u00f3 el aire del campo, que no la hizo bien alguno. Por esta \u00e9poca, es decir, en los primeros d\u00edas de Agosto, dej\u00f3 el hospital en donde hac\u00eda su postulado para ir a la Casa-Madre con el fin de comenzar el noviciado. Tambi\u00e9n comenz\u00f3 entonces el Dr. Ratheau a prodigarla sus cuidados.<\/p>\n<p>\u00abF\u00e1cil cosa fue, dice \u00e9l, establecer el diagn\u00f3stico. Vimos que ten\u00edamos que hab\u00e9rnoslas con una pleuro-pneumon\u00eda mal juzgada, por un infarto de pulm\u00f3n y por un derrame de pus que ocupaba las tres cuartas partes de la pleura izquierda y en un sujeto hasta mal constituido y amenazado de tub\u00e9rculos en la parte superior de los pulmones, si es que ya no exist\u00edan.<\/p>\n<p>A\u00f1adamos a esto el estado general de la paciente, y nuestro pron\u00f3stico no pod\u00eda ser agradable. Sin embar\u00adgo, aconsejamos todos los medios empleados por el arte; vejigatorios al costado enfermo, diur\u00e9ticos cal\u00admantes, acci\u00f3n general sobre la piel por medio de los ba\u00f1os. Ning\u00fan medio interior ni exterior pudo ser continuado, y por consiguiente, ninguno produjo efec\u00adto. La enferma se debilitaba cada d\u00eda m\u00e1s; se determi\u00adn\u00f3 enviarla a tomar los aires del campo a algunas le\u00adguas de Par\u00eds, y consent\u00ed en ello. Parti\u00f3 el 16 de Agos\u00adto, pero su estado se agrav\u00f3; se aumentaron los v\u00f3mitos. Volvi\u00f3 a Par\u00eds cuatro d\u00edas despu\u00e9s, no que\u00adriendo, dec\u00eda ella, morir en otra parte m\u00e1s que en su casa. As\u00ed continuaron los s\u00edntomas hasta el 22 de Agos\u00adto, d\u00eda en que dese\u00f3 hacer una novena para invocar la intercesi\u00f3n de un nuevo confesor de la fe, martirizado en la China (Juan Gabriel Perboyre). Hasta el d\u00eda 25 fueron los dolores aumentando, y en la ma\u00f1ana de ese mismo d\u00eda llegaron a un grado supremo. Habiendo querido levantarse para que la hicieran la cama, no pudo resistir m\u00e1s que algunos minutos: la asfixia era inminente. Tan pronto como volvi\u00f3 a acostarse, se aletarg\u00f3, cubri\u00f3se instant\u00e1neamente la piel de un sudor fr\u00edo, y luego sali\u00f3 bruscamente de este estado, diciendo: \u00abHe sanado; traedme de comer, pues tengo ganas.\u00bb Eran las doce menos cuarto. Crey\u00f3se que de\u00adliraba; pero viendo su buen estado real, las compa\u00f1e\u00adras di\u00e9ronla una copa, una chuleta y un buen pedazo de pan; y no bastando todav\u00eda esto, para satisfacer un hambre que la devoraba, a\u00f1adieron tres patatas asadas. Todo esto lo digiri\u00f3 perfectamente.<\/p>\n<p>\u00abSe levant\u00f3 en seguida, habiendo recobrado sus fuerzas, asisti\u00f3 a recreaci\u00f3n con sus compa\u00f1eras y durmi\u00f3 con perfecto sue\u00f1o. Al d\u00eda siguiente trabaj\u00f3 sin cesar en tender ropa, y por la noche ya vel\u00f3 a los enfermos.\u00bb<\/p>\n<p>Algunos d\u00edas despu\u00e9s, en primer lugar, y otra vez el 4 de Octubre, el doctor Ratheau, queriendo asegurarse bien de la realidad de esta curaci\u00f3n, someti\u00f3 a la hermana Bouyssi\u00e9 a un examen de los m\u00e1s minuciosos, y pudo certificar que todos los \u00f3rganos que hab\u00edan estado tan gravemente comprometidos se hallaban a la saz\u00f3n perfectamente sanos y sin conservar resto alguno de afecci\u00f3n morbosa. As\u00ed escribi\u00f3 \u00e9l con fecha 5 de Octubre de 1841:<\/p>\n<p>\u00abRuego yo a todo m\u00e9dico probo y concienzudo: \u00bfes esta la terminaci\u00f3n natural de enfermedad semejante? Cierto es que algunos curan de ella; pero tambi\u00e9n sabemos cu\u00e1ntos cuidados exigen y despu\u00e9s de qu\u00e9 convalecencias tan interminables, que bien frecuentemente acaban con la muerte; innumerables son los m\u00e9dicos que tienen todos los d\u00edas la triste experiencia de ellos. Conocemos cu\u00e1n largas son las convalecencias de estas enfermedades; y en nuestro caso, \u00bfd\u00f3nde est\u00e1 la convalecencia? Solamente vemos aqu\u00ed el tr\u00e1nsito brusco de la enfermedad m\u00e1s grave a la m\u00e1s perfecta curaci\u00f3n. De todos estos hechos incontestables, debemos deducir la conclusi\u00f3n siguiente: Esta curaci\u00f3n debe ser considerada como efecto de una causa que no es natural, y para hablar m\u00e1s claramente, como efecto de un milagro.\u00bb<\/p>\n<p>6. A estas conversiones o curaciones extraordinarias con que plugo a la divina misericordia manifestar el poder de su siervo, podr\u00edamos a\u00f1adir los golpes con que la divina justicia ha castigado a sus perseguidores, y por los cuales ha vengado aqu\u00ed mismo en la tierra su inocencia. El mandar\u00edn de Kou-Tcheng-Kieng, que le hizo arrestar, fue poco despu\u00e9s destituido de su empleo, y desesperado, se ahorc\u00f3. El Virrey de Ou-Tchang-Fou, verdadera bestia carnicera que hab\u00eda consumido contra este tierno y manso cordero todos los dardos m\u00e1s crueles de una rabia b\u00e1rbara y feroz, fue bien pronto desterrado por el Emperador a causa de sus crueldades; y el pueblo, juzgando que este castigo era harto suave, hubiera querido descuartizarle. As\u00ed es como en otro tiempo muri\u00f3 Herodes vergonzosa y cruelmente devorado de gusanos, y como Pilatos, desterrado a las Galias por el Gobierno romano, acab\u00f3, seg\u00fan se dice, por matarse a s\u00ed mismo.<\/p>\n<p>\u00bfNo ten\u00edamos, pues, raz\u00f3n en afirmar que Dios mismo parece autorizar por los milagros de su misericordia o de su justicia la especie de culto con que el venerable siervo de Dios, Juan Gabriel Perboyre, ha sido honrado despu\u00e9s de su muerte? As\u00ed es que a nadie puede extra\u00f1ar que la Casa-Madre de la fami\u00adlia religiosa a la cual pertenece, y que se glor\u00eda de contarle entre sus hijos, se complace hoy en poseer sus preciosas reliquias. Desde 1858 fueron exhuma\u00addas por los cuidados de Monse\u00f1or Spelta, Vicario Apost\u00f3lico de Hou-P\u00e9, reconocidas por Monse\u00f1or Laplace, Vicario Apost\u00f3lico de Tche-Kiang, y arrebata\u00addas a esa tierra china, tan inhospitalaria, para ser devueltas a Francia, su cara patria. He aqu\u00ed como el Sr. Etienne, que a la saz\u00f3n gobernaba las dos fa\u00admilias de San Vicente, hace conocer esta traslaci\u00f3n en una carta circular de 1\u00b0 de Enero de 1861:<\/p>\n<p>7. \u00abAl comenzar este a\u00f1o de 186o, el 6 de Enero, la divina bondad ha tenido a bien realizar nuestros deseos m\u00e1s ardientes y nuestras m\u00e1s dulces esperanzas. Este d\u00eda, aniversario del nacimiento de nuestro venerable m\u00e1rtir Sr. Juan Gabriel Perboyre, fue en el que tuvimos la satisfacci\u00f3n de ver entrar en nuestra Casa-Madre el precioso cuerpo tra\u00eddo de la China por nuestro compa\u00f1ero de Congregaci\u00f3n, Monse\u00f1or Danicourt, Vicario Apost\u00f3lico de la provincia de Kiang-Si. Ser\u00eda dif\u00edcil expresar la emoci\u00f3n de todos los corazones en el momento en que nos vimos poseedores de tan rico tesoro. Estando de rodillas, alrededor de la caja, que respiraba santidad, \u00a1con qu\u00e9 veneraci\u00f3n tan afectuosa procur\u00e1bamos cubrirla de nuestros homenajes! Parec\u00edanos que desde el cielo se sonre\u00eda de nuestra dicha, y que correspond\u00eda a nuestra acogida tan piadosamente fraternal. \u00a1Qu\u00e9 gozo para todos nosotros el que haya vuelto a nuestro seno rodeado de la aureola del apostolado y del m\u00e1rtir, el mismo que hace veinticinco a\u00f1os hab\u00edamos visto salir de esta misma casa para dirigirse a trav\u00e9s de los mares a lejanas tierras, con el objeto de llevar la buena nueva de salud, consumar una carrera de trabajos, de privaciones y de sufrimientos por la gloria de Jesucristo, y sellar con su propia sangre su fe y su amor a las almas\u2026! Antiguo director del Seminario interno, despu\u00e9s de haber mostrado a las nuevas generaciones por medio de sus ejemplos y ense\u00f1anzas lo que debe ser un Misionero, volv\u00eda a ense\u00f1arles c\u00f3mo deben sufrir y morir por la gloria de Dios y por la salud de sus hermanos.<\/p>\n<p>\u00abEl d\u00eda 25 de Enero, d\u00eda memorable de la fundaci\u00f3n de la Compa\u00f1\u00eda, fue el se\u00f1alado por Su Emma. el Sr. Cardenal Morlot para proceder al reconocimiento can\u00f3nico del cuerpo del venerable m\u00e1rtir, seg\u00fan instrucciones venidas <em>ad hoc <\/em>de Roma. \u00c9l por s\u00ed mismo tuvo la bondad de presidir esta ceremonia. Despu\u00e9s que la identidad del cuerpo fue reconocida can\u00f3nicamente, se le transport\u00f3 a nuestra Capilla y fue depositado en un sepulcro al efecto preparado para recibirle. En \u00e9l deber\u00e1 permanecer hasta que sea del agrado de la divina bondad permitir que lo coloquemos sobre los altares y le asociemos a los honores y a la gloria del cuerpo de San Vicente.\u00bb<\/p>\n<p>8. Esta esperanza del digno Superior general parece estar ya pr\u00f3xima a realizarse. Ya antes de la muerte del siervo de Dios, habiendo el Papa Gregorio XVI o\u00eddo su cautividad y algunos de los trabajos que padec\u00eda, recomend\u00f3 que con mucho cuidado se recogiesen todos los datos que un d\u00eda pudieran servir para el proceso de su beatificaci\u00f3n; manifestando con esto la intenci\u00f3n que ten\u00eda de favorecer la introducci\u00f3n de la causa lo m\u00e1s pronto posible, si el martirio llegaba a realizarse. No olvid\u00f3 su promesa el Sumo Pont\u00edfice; y dos a\u00f1os despu\u00e9s de la muerte del confesor de la fe, en 1843, habi\u00e9ndose ya tomado los primeros testimonios, firm\u00f3 el Decreto que introduc\u00eda la causa de la beatificaci\u00f3n. Este fue el primer acto oficial de la Santa Sede, y desde entonces el Santo m\u00e1rtir pudo ser llamado <em>venerable.<\/em><\/p>\n<p>Despu\u00e9s, la distancia de los lugares, la condici\u00f3n de los testigos cuyas deposiciones se hab\u00edan de recibir, la p\u00e9rdida de piezas importantes que ha sido necesario reconstituir, si bien pronto volvieron a aparecer, las formalidades, en fin, m\u00faltiples que requieren estos procedimientos y la sabia lentitud con que mar\u00adcha<sup>.<\/sup> Roma en estos asuntos, han impedido hasta el presente la realizaci\u00f3n de un hecho tan deseado por todos los hijos de San Vicente de Pa\u00fal. Un trabajo muy reciente, en el cual el Sr. D. Fernando Moroni, Abogado de la causa, resume todas las informaciones can\u00f3nicas hechas anteriormente sobre el martirio del siervo de Dios y los milagros obtenidos por su inter\u00adcesi\u00f3n, ser\u00e1 muy pronto presentado a la Sagrada Con\u00adgregaci\u00f3n de Ritos. Las pruebas que en ella desen\u00advuelve el sabio Abogado, revisadas por S. E. el Vice\u00adpromotor, y ya hechas del dominio p\u00fablico, parecen tan fuertes y s\u00f3lidas, que en Roma nadie duda del pr\u00f3ximo feliz resultado de la causa. \u00a1Quiera el Se\u00f1or realizar nuestras esperanzas, y, por consiguiente, darnos un nuevo modelo que imitar y un Santo m\u00e1s a quien invocar para sostener y confirmar nuestros pasos en el camino de la virtud!<\/p>\n<p style=\"text-align: center\">FIN<br \/>\nDE LA VIDA DEL VENERABLE SIERVO DE DIOS<br \/>\nJUAN GABRIEL PERBOYRE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cap\u00edtulo d\u00e9cimo: Veneraci\u00f3n al se\u00f1or Perboyre despu\u00e9s de su muerte y hechos extraordinarios que parecen autorizarla (1840-1885) 1 \u2014 Veneraci\u00f3n inspirada por el m\u00e1rtir antes de su muerte y que se torna en culto despu\u00e9s &#8230; <a href=\"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":91766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[295],"tags":[161,196],"class_list":["post-14994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juan-gabriel-perboyre","tag-etienne","tag-perboyre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 10 - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 10 - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Cap\u00edtulo d\u00e9cimo: Veneraci\u00f3n al se\u00f1or Perboyre despu\u00e9s de su muerte y hechos extraordinarios que parecen autorizarla (1840-1885) 1 \u2014 Veneraci\u00f3n inspirada por el m\u00e1rtir antes de su muerte y que se torna en culto despu\u00e9s ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-15T01:31:28+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 10\",\"datePublished\":\"2012-09-15T01:31:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/\"},\"wordCount\":3710,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Etienne\",\"Perboyre\"],\"articleSection\":[\"Juan Gabriel Perboyre\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/\",\"name\":\"Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 10 - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2012-09-15T01:31:28+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 10 - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/","og_locale":"es_ES","og_type":"article","og_title":"Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 10 - Somos Vicencianos","og_description":"Cap\u00edtulo d\u00e9cimo: Veneraci\u00f3n al se\u00f1or Perboyre despu\u00e9s de su muerte y hechos extraordinarios que parecen autorizarla (1840-1885) 1 \u2014 Veneraci\u00f3n inspirada por el m\u00e1rtir antes de su muerte y que se torna en culto despu\u00e9s ... Read More","og_url":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2012-09-15T01:31:28+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 10","datePublished":"2012-09-15T01:31:28+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/"},"wordCount":3710,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/#primaryimage"},"thumbnailUrl":"","keywords":["Etienne","Perboyre"],"articleSection":["Juan Gabriel Perboyre"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/","url":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/","name":"Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 10 - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/#primaryimage"},"thumbnailUrl":"","datePublished":"2012-09-15T01:31:28+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 10"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-3TQ","jetpack-related-posts":[{"id":12782,"url":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-introduccion\/","url_meta":{"origin":14994,"position":0},"title":"Compendio De La Vida Del V. J. Gabriel Perboyre. Introducci\u00f3n","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/09\/2012","format":false,"excerpt":"Carta del Sr. Fiat, Superior General de la Misi\u00f3n, al autor de la vida del Venerable Perboyre MUY SE\u00d1OR M\u00cdO Y CARI\u00d1OS\u00cdSIMO HERMANO: La gracia de Nuestro Se\u00f1or sea siempre con usted. En vista del parecer favorable de dos te\u00f3logos. encargados de examinar el COMPENDIO DE LA VIDA DEL V.\u2026","rel":"","context":"En \u00abJuan Gabriel Perboyre\u00bb","block_context":{"text":"Juan Gabriel Perboyre","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/la-familia-vicenciana-en-los-altares\/santos\/juan-gabriel-perboyre\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/06\/perboyre-240x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":54564,"url":"http:\/\/vincentians.com\/es\/decreto-de-canonizacion-del-beato-juan-gabriel-perboyre\/","url_meta":{"origin":14994,"position":1},"title":"Decreto de Canonizaci\u00f3n del Beato Juan Gabriel Perboyre","author":"Francisco Javier Fern\u00e1ndez Chento","date":"09\/07\/2019","format":false,"excerpt":"JUAN PABLO, OBISPO SIERVO DE LOS SIERVOS DE DIOS PARA PERPETUA MEMORIA Habiendo manifestado su caridad Jes\u00fas, el Hijo de Dios, entregando su vida por nosotros, \"nadie tiene amor m\u00e1s grande que \u00e9ste de dar uno su vida por sus amigos\" (Jn 15,13: Cf. 1 Jn. 3,10). El Beato Juan\u2026","rel":"","context":"En \u00abJuan Gabriel Perboyre\u00bb","block_context":{"text":"Juan Gabriel Perboyre","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/la-familia-vicenciana-en-los-altares\/santos\/juan-gabriel-perboyre\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/anyos-vida-vicente.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/anyos-vida-vicente.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/anyos-vida-vicente.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/anyos-vida-vicente.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/anyos-vida-vicente.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":13071,"url":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-3\/","url_meta":{"origin":14994,"position":2},"title":"Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 3","author":"Francisco Javier Fern\u00e1ndez Chento","date":"08\/09\/2012","format":false,"excerpt":"Cap\u00edtulo tercero: Sus primeros empleos en Montdilier y en Saint-Flour (1823 a 1832) 1. Su primer a\u00f1o en Montdidier. \u2014 2. Ense\u00f1a la Filosof\u00eda \u2014 3. Su amor a los pobres. \u2014 4. Es llamado a Par\u00eds para recibir las Sagradas \u00d3rdenes. \u2014 5. Va a ense\u00f1ar Teolog\u00eda al Seminario\u2026","rel":"","context":"En \u00abJuan Gabriel Perboyre\u00bb","block_context":{"text":"Juan Gabriel Perboyre","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/la-familia-vicenciana-en-los-altares\/santos\/juan-gabriel-perboyre\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/06\/perboyre-240x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12787,"url":"http:\/\/vincentians.com\/es\/compendio-de-la-vida-del-v-j-gabriel-perboyre-capitulo-1\/","url_meta":{"origin":14994,"position":3},"title":"Compendio De La Vida Del V. J. Gabriel Perboyre. Cap\u00edtulo 1","author":"Francisco Javier Fern\u00e1ndez Chento","date":"06\/09\/2012","format":false,"excerpt":"Cap\u00edtulo primero: Nacimiento del Venerable Perboyre y sus primeros a\u00f1os hasta su entrada en la Congregaci\u00f3n de la Misi\u00f3n (1802-1818 ) 1. Su nacimiento, sus padres y sus primeros a\u00f1os. \u2014 2. Instrucci\u00f3n primaria, catecismo y primera comuni\u00f3n. \u2014 3. Su perseverancia en el bien. \u2014 4. Apostolado que ejerce\u2026","rel":"","context":"En \u00abJuan Gabriel Perboyre\u00bb","block_context":{"text":"Juan Gabriel Perboyre","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/la-familia-vicenciana-en-los-altares\/santos\/juan-gabriel-perboyre\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2012\/06\/perboyre-240x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":27972,"url":"http:\/\/vincentians.com\/es\/historia-de-la-causa-de-canonizacion-de-san-francisco-regis-clet\/","url_meta":{"origin":14994,"position":4},"title":"Historia de la Causa de Canonizaci\u00f3n de San Francisco R\u00e9gis Clet","author":"Francisco Javier Fern\u00e1ndez Chento","date":"18\/02\/2016","format":false,"excerpt":"En la Asamblea General de la Congregaci\u00f3n de la Misi\u00f3n celebrada en Par\u00eds en 1835, a la propuesta presentada por la Provincia de Roma acerca de la introducci\u00f3n de la Causa de Beatificaci\u00f3n del cohermano Francisco Folchi, muerto en 1823 en olor de santidad, se decidi\u00f3 cuanto sigue: \"\u2026 unanimi\u2026","rel":"","context":"En \u00abFrancisco R\u00e9gis Clet\u00bb","block_context":{"text":"Francisco R\u00e9gis Clet","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/la-familia-vicenciana-en-los-altares\/santos\/francisco-regis-clet\/"},"img":{"alt_text":"regis clet 5","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2015\/02\/regis-clet-5-213x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":28626,"url":"http:\/\/vincentians.com\/es\/la-causa-de-canonizacion-de-juan-gabriel-perboyre\/","url_meta":{"origin":14994,"position":5},"title":"La causa de canonizaci\u00f3n de Juan Gabriel Perboyre","author":"Francisco Javier Fern\u00e1ndez Chento","date":"09\/06\/2023","format":false,"excerpt":"Juan Gabriel Perboyre fue ejecutado en China el 11 de Septiembre de 1840. El 9 de Julio de 1843 un decreto del Papa Gregorio XVI autorizaba la introducci\u00f3n de la causa de beatificaci\u00f3n de cuarenta y tres m\u00e1rtires, incluidos Francisco Regis Clet y Juan Gabriel. La causa de Juan Gabriel\u2026","rel":"","context":"En \u00abJuan Gabriel Perboyre\u00bb","block_context":{"text":"Juan Gabriel Perboyre","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/la-familia-vicenciana-en-los-altares\/santos\/juan-gabriel-perboyre\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/07\/Justino-de-Jacobis-1.jpg?fit=795%2C417&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/07\/Justino-de-Jacobis-1.jpg?fit=795%2C417&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/07\/Justino-de-Jacobis-1.jpg?fit=795%2C417&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2011\/07\/Justino-de-Jacobis-1.jpg?fit=795%2C417&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/14994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=14994"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/14994\/revisions"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=14994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=14994"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=14994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}