{"id":137540,"date":"2015-02-09T00:02:24","date_gmt":"2015-02-08T23:02:24","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=137540"},"modified":"2016-07-26T11:13:41","modified_gmt":"2016-07-26T09:13:41","slug":"vicente-de-paul-carta-1274-a-propaganda-fide","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/","title":{"rendered":"Vicente de Pa\u00fal, Carta 1274: A Propaganda Fide"},"content":{"rendered":"[Mayo 1650]\n<p>Eminentissimi e Reverendissimi Signori:<\/p>\n<p>Furono successivamente concesse da questa Sacra Congregazione le facolta de missionari a Bonifazio Nouelly, Giacomo Lesage e Gioveanni Dieppe, sacerdoti della Congregazione della Missione e mandati in Algeri tanto per soccorrere i poveri schiavi cattolici quanto per estendere maggiormente la nostra santa fede in quelle parti, quali essendo l&#8217;uno dopo l&#8217;altro morti di contagione nell&#8217;aiuto spirituale e corporale che hanno reso a quei popoli; ora il molto Reverendo Padre Vincenzo de Paul, superiore generale di detta congregazione della Missione non perdendosi d&#8217;animo per tanti soggetti suoi, morti in si poco tempo di due anni incirca, e volendo continuare quella carit\u00e0 incominciata, propone di nuovo alla Sacra Congregazione un altro chiamato Filippo Le Vacher, pur sacerdote dell&#8217;istessa Congregazione della Missione, gia missionario in Ibernia con altri suoi confratelli, e di presente applicato al servizio di un seminario di ecclesiastici nella cita di Marsiglia; e supplica umilmente che le Eminenze Vostre siano servite di concedergli la rinnovazione di dette facolt\u00e0 pel medesimo luogo d&#8217;Algeri, con aggiungervi qualche nuova facolt\u00e0 per mezzo della quale abbia autorit\u00e0 di aggiustare delle dissenzioni e contrasti che assai spesso succedono tra religiosi schiavi, acci\u00f2 possa rimediare agli scandali che ne nascono, e avra il tutto per singolar grazia dalle Eminenze Vostre.<\/p>\n<p>Quas deus&#8230;&#8230;&#8230;<\/p>\n<p>Direcci\u00f3n: Alla Sacra Congregazione de Propaganda Fide, per Filippo Le Vacher, sacerdote della Congregazione della Missione.<\/p>\n<p>TRADUCCION<\/p>\n[Mayo de 1650]\n<p>Eminent\u00edsimos y Reverend\u00edsimos se\u00f1ores:<\/p>\n<p>La Sagrada Congregaci\u00f3n de Propaganda Fide fue concediendo sucesivamente las facultades propias de los misioneros a Bonifacio Nouelly, Santiago Lesage y Juan Dieppe, sacerdotes de la congregaci\u00f3n de la Misi\u00f3n, enviados a Argel para socorrer a los pobres esclavos cat\u00f3licos y para contribuir a la extensi\u00f3n de nuestra santa fe en aquellas regiones, y que murieron uno tras otro v\u00edctimas de la peste, asistiendo corporal y espiritualmente a los enfermos. El reverend\u00edsimo padre Vicente de Paul, superior general de dicha congregaci\u00f3n de la Misi\u00f3n, sin desanimarse por la p\u00e9rdida de tantos sujetos en el escaso t\u00e9rmino de dos a\u00f1os, y queriendo proseguir con la caridad comenzada, propone de nuevo a esa Sagrada Congregaci\u00f3n a otro de sus sacerdotes, Felipe Le Vacher, que trabaj\u00f3 anteriormente en las misiones de Irlanda con algunos de sus hermanos y que se encuentra actualmente en Marsella al servicio de un seminario eclesi\u00e1stico. Y suplica humildemente a sus eminencias que tengan a bien conceder al mencionado padre Le Vacher las mismas facultades para aquel pa\u00eds, a\u00f1adiendo otras nuevas, de forma que tenga la autoridad suficiente para hacer cesar las disensiones y contrastes que con tanta frecuencia surgen entre los religiosos esclavos, evitando de esta forma todo posible esc\u00e1ndalo. Mirar\u00e9 todo esto como una gracia y favor se\u00f1alado de sus eminencias.<\/p>\n<p>Quas deus&#8230;&#8230;&#8230;<\/p>\n<p>Direcci\u00f3n: A la sagrada congregaci\u00f3n de Propaganda Fide, en favor de Felipe Le Vacher, sacerdote de la congregaci\u00f3n de la Misi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[Mayo 1650] Eminentissimi e Reverendissimi Signori: Furono successivamente concesse da questa Sacra Congregazione le facolta de missionari a Bonifazio Nouelly, Giacomo Lesage e Gioveanni Dieppe, sacerdoti della Congregazione della Missione e mandati in Algeri tanto &#8230; <a href=\"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":393753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[65],"tags":[168],"class_list":["post-137540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-de-vicente-de-paul","tag-argel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vicente de Pa\u00fal, Carta 1274: A Propaganda Fide - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vicente de Pa\u00fal, Carta 1274: A Propaganda Fide - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"[Mayo 1650] Eminentissimi e Reverendissimi Signori: Furono successivamente concesse da questa Sacra Congregazione le facolta de missionari a Bonifazio Nouelly, Giacomo Lesage e Gioveanni Dieppe, sacerdoti della Congregazione della Missione e mandati in Algeri tanto ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-08T23:02:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T09:13:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Vicente de Pa\u00fal, Carta 1274: A Propaganda Fide\",\"datePublished\":\"2015-02-08T23:02:24+00:00\",\"dateModified\":\"2016-07-26T09:13:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/\"},\"wordCount\":511,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630\",\"keywords\":[\"Argel\"],\"articleSection\":[\"Escritos de Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/\",\"name\":\"Vicente de Pa\u00fal, Carta 1274: A Propaganda Fide - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630\",\"datePublished\":\"2015-02-08T23:02:24+00:00\",\"dateModified\":\"2016-07-26T09:13:41+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/07\\\/escritos-vicente-de-paul.jpg?fit=1200%2C630\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/vicente-de-paul-carta-1274-a-propaganda-fide\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vicente de Pa\u00fal, Carta 1274: A Propaganda Fide\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vicente de Pa\u00fal, Carta 1274: A Propaganda Fide - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/","og_locale":"es_ES","og_type":"article","og_title":"Vicente de Pa\u00fal, Carta 1274: A Propaganda Fide - Somos Vicencianos","og_description":"[Mayo 1650] Eminentissimi e Reverendissimi Signori: Furono successivamente concesse da questa Sacra Congregazione le facolta de missionari a Bonifazio Nouelly, Giacomo Lesage e Gioveanni Dieppe, sacerdoti della Congregazione della Missione e mandati in Algeri tanto ... Read More","og_url":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-02-08T23:02:24+00:00","article_modified_time":"2016-07-26T09:13:41+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Vicente de Pa\u00fal, Carta 1274: A Propaganda Fide","datePublished":"2015-02-08T23:02:24+00:00","dateModified":"2016-07-26T09:13:41+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/"},"wordCount":511,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630","keywords":["Argel"],"articleSection":["Escritos de Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/","url":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/","name":"Vicente de Pa\u00fal, Carta 1274: A Propaganda Fide - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630","datePublished":"2015-02-08T23:02:24+00:00","dateModified":"2016-07-26T09:13:41+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1274-a-propaganda-fide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vicente de Pa\u00fal, Carta 1274: A Propaganda Fide"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-zMo","jetpack-related-posts":[{"id":155870,"url":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1322-a-propaganda-fide\/","url_meta":{"origin":137540,"position":0},"title":"Vicente de Pa\u00fal, Carta 1322: A Propaganda Fide","author":"Francisco Javier Fern\u00e1ndez Chento","date":"09\/06\/2015","format":false,"excerpt":"[ 1650, hacia septiembre] Eminentissimi e Reverendissimi Signori, Per decreto della Sacra Congregazione sotto li 9 luglio dell' anno 1648 furono concesse le facolt\u00e0 di Missionari Apostolici nell'isola di San Lorenzo, vulgo Madagascar, a Carlo Nacquart, dichiarato prefetto della suddetta Missione, et a Nicolo Gondr\u00e9e, suo compagno, tutti due sacerdoti\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":118541,"url":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1094-a-propaganda-fide\/","url_meta":{"origin":137540,"position":1},"title":"Vicente de Pa\u00fal, Carta 1094: A Propaganda Fide","author":"Francisco Javier Fern\u00e1ndez Chento","date":"17\/03\/2013","format":false,"excerpt":"[1648] Eminentissimi e Reverendissimi Signori, Non essendo per ancora date ad alcuna religione a Preti secolari le tre Arabie Felice, Petrea e Deserta da coltivarsi e ridursi alla fede cristiana. Vincenzo a Paolo, superiore della Congregazione della Missione, offerisce di mandara dei suoi a dette Arabie quando l'Eminenze Vostre restino\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":398971,"url":"http:\/\/vincentians.com\/es\/vicente-paul-carta-1352-cardenal-deste-san-vicente\/","url_meta":{"origin":137540,"position":2},"title":"Vicente de Pa\u00fal, Carta 1352: Cardenal D&#8217;Este a San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"14\/11\/2016","format":false,"excerpt":"4 diciembre 1650 Al merito di Vostra Paternita et allo zelo che avete nelle materia che riguardano il servizio di Dio e l'ampliazione della santa fede contribuir\u00f2 sempre con particolare prontezza a tutto quello che dipender\u00e0 dal mio arbitrio per riscontrar le soddisfazioni vostre e della vostra congregazione; e come\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":57326,"url":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-0777-el-cardenal-antonio-barberini-prefecto-de-propaganda-fide-a-san-vicente\/","url_meta":{"origin":137540,"position":3},"title":"Vicente de Pa\u00fal, Carta 0777: El Cardenal Antonio Barberini, Prefecto De Propaganda Fide, A San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"04\/01\/2012","format":false,"excerpt":"Molto Reverendo Signore, Sapendosi quanto volontieri Vostra Signoria si impieghi per ajuto spirituale del prossimo e particolarmente per istruire quelli che hanno da professare lo stato ecclesiastico nell' esercizio delle loro funzionii mi hanno li Signori Cardinali di questa Sacra Congregazione di Propaganda Fede ordinato di esortarla, come faccio con\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":398536,"url":"http:\/\/vincentians.com\/es\/andreis-carta-001-felix-andreis-c-m\/","url_meta":{"origin":137540,"position":4},"title":"Andreis, Carta 001. A Felix de Andreis, C.M.","author":"Francisco Javier Fern\u00e1ndez Chento","date":"28\/07\/2016","format":false,"excerpt":"(Entre 1801 y 1803) Est\u00e9 preparado para salir hacia la misi\u00f3n que tanto desea. Est\u00e1 destinado a China, y usted y sus compa\u00f1eros podr\u00e1n ver en esta circunstancia los dise\u00f1os de la providencia divina que, para lograr sus prop\u00f3sitos, hace uso de medios ciertamente imprevistos. (Francois Brunet)","rel":"","context":"En \u00abEscritos de F\u00e9lix de Andreis\u00bb","block_context":{"text":"Escritos de F\u00e9lix de Andreis","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-felix-de-andreis\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-felix-de-andreis.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-felix-de-andreis.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-felix-de-andreis.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-felix-de-andreis.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-felix-de-andreis.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":43203,"url":"http:\/\/vincentians.com\/es\/nuevas-pistas-de-investigacion-para-la-historia-del-vicencianismo\/","url_meta":{"origin":137540,"position":5},"title":"Nuevas pistas de investigaci\u00f3n para la historia del vicencianismo","author":"Mitxel Olabu\u00e9naga","date":"23\/11\/2021","format":false,"excerpt":"Cada generaci\u00f3n siente la necesidad de volver sobre los propios pasos, remontarse a los or\u00edgenes y recorrer el camino que la ha lle\u00advado a los cambios que conocemos. La historia no termina nunca de escribirse. Existen dos recorridos que nos llevan a escribir una vez m\u00e1s la historia: el encuentro\u2026","rel":"","context":"En \u00abHistoria de la Congregaci\u00f3n de la Misi\u00f3n\u00bb","block_context":{"text":"Historia de la Congregaci\u00f3n de la Misi\u00f3n","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-la-congregacion-de-la-mision\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/identidad.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/137540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=137540"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/137540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/393753"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=137540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=137540"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=137540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}