{"id":131661,"date":"2014-11-02T08:39:43","date_gmt":"2014-11-02T07:39:43","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=131661"},"modified":"2016-07-26T16:58:15","modified_gmt":"2016-07-26T14:58:15","slug":"la-vida-del-cardenal-de-retz-iv","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/","title":{"rendered":"La vida del Cardenal de Retz (IV)"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"http:\/\/vicencianos.org\/blog\/la-vida-del-cardenal-de-retz-i\/cretz\/\" rel=\"attachment wp-att-131652\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-131652\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/10\/cretz.jpg?resize=236%2C277\" alt=\"cretz\" width=\"236\" height=\"277\" \/><\/a>COMBATIENTES DE LA CONTRAREFORMA<br \/>\nJean-Fran\u00e7ois-Paul de Gondi, el futuro memorialista, naci\u00f3 en el castillo de Montmirail, en las tierras que sus padres pose\u00edan en Brie, en septiembre de 1613. Su partida de bautismo menciona que fue llevado a las fuentes el 20*. Era el \u00faltimo de los tres hijos de Philippe-Emmanuel de Gondi, tambi\u00e9n \u00e9l hijo del mariscal. Situaci\u00f3n poco envidiable del segund\u00f3n de la rama menor. A su hermano, Pierre, nacido en 1606**, est\u00e1 reservado lo esencial del patrimonio. El segundo, Henri, marqu\u00e9s de las Islas de Oro, nacido en 1610, debe ser arzobispo de Par\u00eds, como sus t\u00edos. En cuanto al peque\u00f1o Paul, se har\u00e1 de \u00e9l a toda prisa caballero de Malta. Pero nada se ha decidido para \u00e9l: constituye un recurso en caso de accidente, para recoger la herencia en el mundo o en la Iglesia.<br \/>\nLos hombres del siglo XVII no ten\u00edan costumbre de enternecerse por los primeros pasos, las primeras sonrisas de sus v\u00e1stagos; y sobre todo se absten\u00edan, con alguna excepci\u00f3n, de hablar sobre ello. Su infancia es pues mal conocida. \u00c9l mismo no hace comenzar el relato de su vida hasta el momento que \u00abha conocido [su] estado\u00bb -1, en el que ha tomado conciencia de su lugar en la sociedad. Se permite con todo imaginar lo que fueron sus primeros a\u00f1os, pues estamos bien informados sobre sus padre y madre: se hallan en el primer rango del combate por el renacimiento del catolicismo.<\/p>\n<p>El \u00absiglo de los santos\u00bb<br \/>\nNos exponemos a no entender nada de la Francia de comienzos del siglo XVII si se deja a un lado la extraordinaria vitalidad de este movimiento.<br \/>\nLos \u00e9xitos protestantes se hab\u00edan apoyado en la pretendida decadencia de una Iglesia demasiado comprometida con el mundo de la que se dec\u00eda olvidadiza de la fe y de la pureza moral originales. Al cabo de un siglo de desgarros y de guerras despiadadas, el catolicismo ha comprendido la lecci\u00f3n intentando ocupar el mismo territorio de sus adversarios. Francia es, en una Europa partida en dos, el \u00fanico gran Estado en que coexisten las dos confesiones: la religi\u00f3n del pr\u00edncipe no es necesariamente la de los s\u00fabditos. Los hugonotes minoritarios, protegidos por el edicto de Nantes, siguen con fuerza. Adem\u00e1s, nuestro pa\u00eds tiene en mucho la autonom\u00eda que le aseguran por parte de la Santa Sede las tradicionales \u00ablibertades de la Iglesia galicana\u00bb. Los decretos del concilio de Trento no son recibidos; la Inquisici\u00f3n le es perdonada, las autoridades eclesi\u00e1sticas no se ponen al frente de la reconquista.<br \/>\nEsta abstenci\u00f3n deja el campo abierto a las iniciativas privadas, que florecen m\u00e1s libremente, m\u00e1s diversas, m\u00e1s originales, m\u00e1s expuestas tambi\u00e9n, ya se ver\u00e1, a las derivas doctrinales. La primera mitad del siglo XVII no ha usurpado su apelativo de \u00absiglo de los santos\u00bb. Raramente semejante esfuerzo se hizo para acordar la vida con la fe, para llevar a la pr\u00e1ctica el deseo de absoluto que abrasa las almas. Entre vida laica y vida religiosa, se borran las fronteras. Hay solitarios que llevan, al margen de las congregaciones, una existencia casi conventual. La muerte de un esposo o de una esposa suscita vocaciones tard\u00edas, a menos que dos conjuntados se separen deliberadamente para hacer profesi\u00f3n al mismo tiempo en sus monasterios respectivos. Se puede ser por turno padre o madre seg\u00fan la carne, y Padre o Madre en religi\u00f3n. Una ni\u00f1a como las dem\u00e1s, la peque\u00f1a Marie de Rabutin, futura marquesa de S\u00e9vign\u00e9, es tambi\u00e9n la \u00abviva reliquia\u00bb de una santa, su abuela Jeanne de Chanta, fundadora de la Visitaci\u00f3n. El padre de nuestro memorialista entrar\u00e1 en las \u00f3rdenes despu\u00e9s de su viudez. Toda la familia de Gondi se ba\u00f1a entonces en este clima de fe muy viva y de militantismo cat\u00f3lico. Todos est\u00e1n mezclados, de cerca o de lejos, en la empresa de renovaci\u00f3n religiosa, Gracias a ellos \u2013 \u00bfcompensaci\u00f3n providencial?- una buena parte de la fortuna acumulada en el siglo XVI por el prudente mariscal cae en la escarcela de la Iglesia para sus obras de evangelizaci\u00f3n y de caridad.<br \/>\nSolo los t\u00edtulos de gloria del m\u00e1s insignificante de entre ellos, Enrique, segundo obispo de Par\u00eds y cardenal de Retz primero del nombre en 1618, \u00abun esp\u00edritu dulce, d\u00e9bil, de ningunas letras y poca resoluci\u00f3n\u00bb, son su presencia entre os ej\u00e9rcitos reales en las \u00faltimas guerras contra los protestantes \u2013muere, de enfermedad, al pie de las murallas de Lunel el 15 de agosto de 1622- y la lista de las innumerables casas religiosas parisinas cuyas cartas de fundaci\u00f3n \u00e9l contrafirm\u00f3. Entre ellas, las Carmelitas, las Ursulinas y las del C\u00edster en el barrio de Saint-Jacques; los Jacobinos, los Agustinos, reformados en el barrio de Saint-Germain, los Capuchinos calle de Saint-Honor\u00e9, la Visitaci\u00f3n calle Saint-Antoine, los M\u00ednimos plaza real, las religiosas de Nuestra Se\u00f1ora de la Merced, las religiosas de la Anunciaci\u00f3n, el hospital Saint-Louis y el de la Caridad; y, por iniciativa del futuro cardenal de Berulle, la congregaci\u00f3n de los sacerdotes del Oratorio, en la que entrar\u00e1 despu\u00e9s su hermano Philippe-Emmanuel.<\/p>\n<p style=\"text-align: justify\">Una pareja cristiana<br \/>\nNada parec\u00eda destinar a este \u00faltimo a jugar un papel en la Iglesia. Dos de sus hermanos hab\u00edan sido designados para ello por transmisi\u00f3n familiar: el segundo, Enrique, a quien se ha evocado ahora mismo brevemente, y el cuarto, Jean-Fran\u00e7ois, de quien hablaremos m\u00e1s adelante. Philippe-Emmanuel, \u00e9l, fue el encargado de asegurar la perpetuidad de la l\u00ednea, amenazada por la muerte prematura del mayor de todos, Charles, en 1596. Este mayor dejaba bien es cierto un hijo de poca edad, heredero del t\u00edtulo ducal y de la mejor parte del patrimonio, pero era imprudente, en aquellos tiempos de alta mortalidad, hacer descansar sobre una misma cabeza el futuro de la casa. El mariscal hab\u00eda dimitido pues en favor de su tercer hijo del generalato de las galeras y le hab\u00eda establecido en el mundo.<br \/>\nCasado en 1604 con Margarita de Silly, lleva en compa\u00f1\u00eda de amigos brillantes \u2013los duques de Guisa y de Chevreuse, Bassompierre, Cr\u00e9qui\u2026- la vida f\u00e1cil de un cortesano, en el clima de civilidad elegante cuyo modelo proporcionaba la obra c\u00e9lebre de Baldassar Castiglioni. Su gusto por el fasto le hizo rebasar los l\u00edmites que le fijaban sus rentas. Se le dec\u00eda acribillado de deudas. Era, dir\u00e1 su hijo, el hombre mejor hecho, el m\u00e1s diestro y uno de los m\u00e1s valientes del reino. Un grabado nos le muestra en traje de pompa con gorguera, puntillas, bordados, vasta toca de penacho blanco. Un rostro fino, regular, barba, mostacho y cabellera abundantes, una expresi\u00f3n abierta, componen una fisonom\u00eda amable, en la que se buscar\u00edan en vano rastros de ascetismo. Es de un mundano de quien se trata que, si se ha de cr\u00e9er a la tradici\u00f3n familiar, habr\u00eda \u00bb brillado en el Parnaso \u00ab, es decir manifestado algunos dones literarios. Resumiendo un gentilhombre como hab\u00eda muchos en la \u00e9poca.<br \/>\nSu generalato de las galeras no era una simple sinecura, particip\u00f3 contra los piratas y contra los protestantes, en operaciones de las que Le Mercure fran\u00e7ais da una cuenta elogiosa.<br \/>\nAl acabar junio de 1620, sale de Marsella a la cabeza de siete galeras para dar caza a los corsarios berberiscos. El 22 de julio, primer \u00e9xito: somete a dos buques enemigos a la vista de Oran , libera a los cuarenta esclavos cristianos encadenados al remo, env\u00eda en represalias a ciento cincuenta Turcos a engrosar la chusma de Toulon. Se apodera de un bergant\u00edn, luego desaloja un gran nav\u00edo instalado por un renegado de La Rochelle, famoso en Argel por el nombre del ra\u00efs Soliman, a quien persigue y fuerza a inmovilizarse. Tras esta faena, hundiendo o quemado otras dos embarcaciones adversas sin perder \u00e9l uno solo, lleg\u00f3 a Marsella gloriosamente con cuatro nav\u00edos enemigos y una carga de prisioneros.<br \/>\nEn la primavera de 1622, se uni\u00f3 a la escuadra que cercaba La Rochelle. Patrull\u00f3 en alta mar durante el verano. Cuando el ataque del 22 de octubre, salv\u00f3 la embarcaci\u00f3n que llevaba la duque de Guisa, jefe de la expedici\u00f3n, al que unos barcos incendiarios hab\u00edan puesto en llamas.<br \/>\n\u00bb El Sr. General (es decir Philippe-Emmanuel) dio se\u00f1ales de un valor muy varonil en esta ocasi\u00f3n, y se mostr\u00f3 lleno de valor y de generosidad en medio de sus oficiales. El duque de Guisa se mostr\u00f3 muy satisfecho de \u00e9l y de sus galeras, atribuy\u00e9ndoles la mejor parte en el honor de esta victoria, y escribi\u00f3 al Rey en t\u00e9rminos encomi\u00e1sticos \u00ab.<br \/>\nEl combate, suspendido por la noche, se reanud\u00f3 al d\u00eda siguiente. Las galeras dieron la caza al barco almirante enemigo. Le hicieron hundirse en los bancos de arena de la isla de R\u00e9, le ca\u00f1onearon y dieron muerte a m\u00e1s de doscientos hombres. Duro mucho la victoria y la paz que sigui\u00f3.<br \/>\nEl joven Pierre de Gondi, entonces de diecis\u00e9is a\u00f1os, estaba cerca de su padre. Cuando los combates de la isla de R\u00e9, recibi\u00f3 el bautismo de fuego, gloriosamente materializado por una descarga de mosquete en la espalda. Tuvo un caballo muerto a sus pies. El relato de sus trofeos, amplificado por la imaginaci\u00f3n infantil, debi\u00f3 hacer palidecer de envidia a sus hermanos, en particular al m\u00e1s joven, que no so\u00f1aba m\u00e1s que con hechos gloriosos. El futuro cardenal alimentar\u00e1 contra Richelieu, quien priv\u00f3 a la familia del generalato de las galeras, un odio tenaz. Son inseparables, en su esp\u00edritu, del fracaso de los ca\u00f1ones , de la sangre, de la gloria \u2013la \u00fanica, cre\u00eda \u00e9l por entonces, que fuera digna de un gran se\u00f1or, la que se conquista a punta de espada.<br \/>\nPero en Philippe-Emmanuel, desde hac\u00eda tiempo, la moral aristocr\u00e1tica del honor se hab\u00eda batido en brecha por la piedad. Sin duda, es la raz\u00f3n por la cual se le pudo reprochar la falta de bravura. Sin dar un paso atr\u00e1s en los combates, no los buscaba. Ten\u00eda otras aspiraciones. El itinerario que le condujo de la toldilla de un nav\u00edo de guerra a la celda de un convento lleva consigo bastantes sombras. Es cierto, en todo caso, que su mujer le sirvi\u00f3 de mediaci\u00f3n.<br \/>\nSe hab\u00eda casado en 1604 \u2013el contrato de matrimonio lleva la fecha del 22 de junio-8 -con una de las dos hijas de Antoine de Silly, conde de la Rochepot, doncel de Commercy. Rubia, p\u00e1lida, con los ojos muy separados y el ment\u00f3n fugitivo, ce\u00f1ida en su coselete rebordado de oro y de perlas, Fran\u00e7oise-Marguerite aparece, en su retrato grabado, de una irreal fragilidad. \u00abEra una gran gazmo\u00f1a\u00bb, dice Tallemant bien informado sobre el cap\u00edtulo de las costumbres. Era de una piedad profunda, inquieta, exaltada que repercut\u00eda sobre su salud delicada. Hac\u00eda en al Carmelo las visitras asiduas, all\u00ed trataba a la Madre Margarita del Sabto Sacramento, hija de la c\u00e9lebre Sra. Acarie, m\u00e1s tarde beatificada que fue la fundadora de la orden en Francia y marc\u00f3 con sus irradiaci\u00f3n m\u00edstica los primeros a\u00f1os del siglo XVII. All\u00ed fue donde Philippe Emmanuel se encontr\u00f3 con B\u00e9rulle, quien fue decisivo en su vocaci\u00f3n.<br \/>\nLa leyenda familiar rodea este encuentro con un aura sobrenatural, que viene a autentificar el testimonio del futuro memorialista:<br \/>\n\u00abHe o\u00eddo decir varias veces a mi difunto padre que, muchos a\u00f1os antes de que entrara en la congregaci\u00f3n del Oratorio, y en el tiempo en que a\u00fan se encontraba implicado en las intrigas y en los placeres de la corte, se vio obligado por mi difunta madre a ir a ver a la Madre Marguerite ; a la que resisti\u00f3 por alg\u00fan tiempo, y que habi\u00e9ndose decidido al final por pura complacencia, encontr\u00f3 all\u00ed al difunto cardenal de B\u00e9rulle, quien no era todav\u00eda m\u00e1s que superior del Oratorio, con el que no ten\u00eda ninguna confianza, y que la Madre Marguerite le dijo abord\u00e1ndole estas mismas palabras : \u00bb Mirad, se\u00f1or, al R. P. de B\u00e9rulle a quien no conoc\u00e9is, pero le conocer\u00e9is alg\u00fan d\u00eda. El ser\u00e1 el instrumento m\u00e1s eficaz del que Dios se servir\u00e1 para vuestra salvaci\u00f3n. Os burl\u00e1is de m\u00ed a la hora que es, pero conocer\u00e9is un d\u00eda que os digo la verdad \u00ab. Yo he o\u00eddo hacer este relato a mi difunto padre una infinidad de veces desde que estuvo en el Oratorio; pero recuerdo hab\u00e9rselo incluso o\u00eddo decir en mi infancia, mucho antes de que tuviera el pensamiento de entrar\u00bb.<br \/>\nLos efectos de la profec\u00eda se hicieron esperar unos doce a\u00f1os por lo menos. Nada en lo inmediato se modific\u00f3 en la existencia de Philippe-Emmanuel de Gondi. Mas cuando busc\u00f3 para sus hijas a un preceptor, se dirigi\u00f3 a B\u00e9rulle, quien le recomend\u00f3 a Vicente de Pa\u00fal.<\/p>\n<p style=\"text-align: justify\">Vicente de Pa\u00fal con los Gondi<br \/>\nSe ha de rechazar entre las f\u00e1bulas edificantes la an\u00e9cdota citada con frecuencia : La Sra. de Gondi visitando en Marsella las galeras de su marido y descubriendo entre la chusma a un sacerdote desconocido quien se hab\u00eda sustituido heroicamente por un condenado ; era Vicente, a quien ella habr\u00eda mandado soltar y aceptado en su casa. En realidad este entr\u00f3 en los Gondi como preceptor de los hijos nacidos y por nacer, en 1613, el a\u00f1o mismo de la llegada al mundo de Jean-Fran\u00e7ois-Paul. Sus funciones pedag\u00f3gicas de los dos mayores \u2013siete a\u00f1os y tres a\u00f1os- se duplicaron bien pronto con un papel de director de conciencia con los padres.<br \/>\nCon Philippe-Emmanuel, las relaciones fueron de inmediato excelentes. Vicente hab\u00eda dado, poco despu\u00e9s de su entrada en la casa, un golpe de efecto. Al enterarse de que su amo, insultado por otro gentilhombre, se preparaba para enfrentarse a \u00e9l en duelo, le esper\u00f3 a la salida de la misa y se ech\u00f3 a sus pies:<br \/>\n\u00abPerdone, Se\u00f1or, le dijo, que os diga unas palabras con toda humildad. S\u00e9 de buena tinta que ten\u00e9is el proyecto de batiros en duelo, pero yo os declaro de parte de mi Salvador,[\u2026] a quien acab\u00e1is de adorar, que si no alej\u00e1is de vos ese mal proyecto, \u00e9l ejercer\u00e1 su justicia sobre vos y sobre toda vuestra posteridad\u00bb.<br \/>\nPhilippe-Emmanuel, sorprendido, pero impresionado, renunci\u00f3 a exigir reparaci\u00f3n por las armas: rara victoria de la piedad sobre la moral del honor, que fue citada como ejemplo durante las campa\u00f1as de la Iglesia contra el duelo y que es se\u00f1al de la extraordinaria fuerza que emanaba de Vicente.<br \/>\nCon la piadosa, la buena, la caritativa Sra. de Gondi, que ha hecho las delicias de la hagiograf\u00eda, el trato era m\u00e1s delicado. Ciertamente, ella rebosaba de virtudes. \u00bb No hablaba nunca y no pod\u00eda permitir que en su presencia se hablara de los defectos de otro\u00bb. Hac\u00eda reinar en su casa un clima de paternalismo cristiano, velando por las necesidades materiales de sus criados, pero tambi\u00e9n de su educaci\u00f3n moral y espiritual, asoci\u00e1ndolos en la oraci\u00f3n de la tarde en com\u00fan. Pero llevaba la introspecci\u00f3n al extremo, se atormentaba de escr\u00fapulos, ve\u00eda a cada instante los infiernos entreabiertos a sus pasos. La sola idea de la condenaci\u00f3n le inspiraba una ansiedad nerviosa. Permanec\u00eda pendiente de la palabra de su confesor. Siempre dolida, ten\u00eda la triste propensi\u00f3n a caer enferma cada vez que \u00e9l se alejaba.<br \/>\nTodo prueba que Vicente de Pa\u00fal hab\u00eda intentado sustraerse a sus exigencias. Llevaba al mismo tiempo su preceptorado y las funciones de p\u00e1rroco de Clichy, que procuraba conservar. En 1617, ruega a B\u00e9rulle que le retire de esta casa, sin tratar de despedirse de los due\u00f1os, \u00e9l se escapa, sale el mes de julio a la parroquia de Ch\u00e2tillon-l\u00e8s-Dombes, en Bresse, que le ha sido confiada. Ay, los Gondi llevan muy mal su deserci\u00f3n y remueven cielo y tierra para recuperarlo. El general de las galeras se da a la desesperaci\u00f3n. Su esposa conf\u00eda a una amiga su sorpresa entristecida:<br \/>\n\u00bb Nunca se me habr\u00eda ocurrido. El Sr. Vicente se hab\u00eda mostrado tan caritativo con su alma que yo no pod\u00eda sospechar que me fuera a abandonar de esta manera. Pero, Dios se alabado, yo no le acuso de nada, ni mucho menos; creo que no ha hecho nada sino por una especial providencia de Dios y llevado de su santo amor. Pero, de verdad, su alejamiento es muy extra\u00f1o, y confieso no ver ni gota. Ya sabe la necesidad que tengo de su direcci\u00f3n y los asuntos que tengo que comunicarle; los dolores del alma y del cuerpo que he sufrido, falta de ayuda ; el bien que deseo hacer en mis pueblos y que es imposible emprender sin su consejo. En una palabra, veo a mi alma en un estado lastimoso\u00bb.<br \/>\nLa presencia de un confesor suplente elegido por Vicente no podr\u00eda consolar su penitencia enfebrecida que le impide comer, beber, y dormir: si la hemos de creer, sus hijos se debilitan, sus s\u00fabditos sufren, ella misma languidece y se muere. Acaba por entregarse por director que la ha traicionado a un chantage espiritual refinado y perverso: no sobrevivir\u00e1, su alma se condenar\u00e1, y es \u00e9l quien tendr\u00e1 toda la culpa.<br \/>\n\u00abYo no me equivocaba al temer perder vuestra asistencia, como os he contado tantas veces, le escribe, ya que en efecto la he perdido. La angustia en que me hallo me resulta insoportable sin una gracia de Dios totalmente extraordinaria, que yo no merezco. Si tan solo fuera por alg\u00fan tiempo, no sentir\u00eda tanta pena; pero cuando veo todas las ocasiones en las que tendr\u00e9 necesidad de ser ayudada, con direcci\u00f3n y consejo, bien en la muerte, bien en vida, mis dolores se renuevan. Juzgad pues si mi alma y mi cuerpo pueden soportar largo tiempo estas penas. Me encuentro en el estado de no buscar ni recibir asistencia de otra parte, porque sab\u00e9is muy bien que no tengo la libertad para las necesidades de mi alma con mucha gente. [\u2026] Si, despu\u00e9s de esto, me rechaz\u00e1is, yo os declaro culpable ante Dios de todo lo que me suceda y de todo el bien que dejar\u00e9 de hacer, por falta de ayuda. Me pondr\u00e9is en la circunstancia de estar en lugares con frecuencia privada de los sacramentos, por las grandes penas que me pasan y la poca gente que es capaz de asistirme. [\u2026] S\u00e9 que mi vida no sirviendo m\u00e1s que para ofender a Dios, no es peligroso ponerla al azar; pero mi alma debe ser asistida en la muerte. Acordaos de la aprensi\u00f3n en que me visteis en mi \u00faltima enfermedad, en un pueblo. Estoy ceca de llegar a un situaci\u00f3n peor ; y el solo miedo de ello me causar\u00eda tanto mal que no s\u00e9 si, sin gran disposici\u00f3n precedente, no me producir\u00eda la muerte\u00bb.<br \/>\nVicente estuvo ciertamente tentado de dejar pasar la salvaci\u00f3n f\u00edsica y espiritual de sus parroquianos de la Bresse, cuya conquista se hab\u00eda ganado en pocos meses, antes que la de la general de las galeras. Pero el desarrollo, incluso hasta la simple supervivencia de las obras cuyos fundamentos acababa de echar exig\u00edan protecciones. El era tambi\u00e9n un escrupuloso. Ante la imposibilidad de convencer a la Sra. de Gondi, y con los consejos de B\u00e9rulle, acab\u00f3 por obtemperar, lo que Philippe-Emanuel le agradeci\u00f3 en t\u00e9rminos de una calurosa sencillez, que contrastan aeotunadamente con las intemperancias de lenguaje de su esposa, compartiendo su alegr\u00eda, y a\u00f1adiendo:<br \/>\n\u00abYo no os dir\u00e9 m\u00e1s, ya que hab\u00e9is le\u00eddo la carta que escribo a mi mujer. Os ruego tan solo que consider\u00e9is que al parecer Dios quiere que por vuestro medio el padre y los hijos sean gentes de bien\u00bb.<br \/>\nEl d\u00eda de Navidad de ese a\u00f1o 1617, volv\u00eda a los Gondi, a quienes no abandonar\u00e1 hasta despu\u00e9s de la muerte de la ama de casa, ocho a\u00f1os m\u00e1s tarde. Pero esta breve fuga \u2013seis meses apenas- no le ha sido in\u00fatil. A su regreso, la brida es m\u00e1s floja. Si sigue alojado en el lugar, y conserva la direcci\u00f3n moral y religiosa de la familia, est\u00e1 descargado del preceptorado, y encuentra en las misiones de evangelizaci\u00f3n y de caridad un campo a la medida de su temperamento de hombre de acci\u00f3n.<br \/>\nPaul de Gondi no fue pues el alumno de Vicente. \u00a1Qu\u00e9 consuelo para los historadores preocupados por lavar a este de toda responsabilidad en las extravagancias ulteriores de un indigno disc\u00edpulo! Hab\u00eda sido un error creer que le hab\u00eda ense\u00f1ado el lat\u00edn, hasta la teolog\u00eda! El futuro arzobispo acababa de nacer se encarg\u00f3 de sus funciones y ten\u00eda cuatro a\u00f1os cuando el preceptor de sus hermanos al regreso de Ch\u00e2tillon-l\u00e8s-Dombes, fue dispensado de toda tarea pedag\u00f3gica. El santo hombre no tuvo pues ninguna parte en la formaci\u00f3n del futuro fautor de esc\u00e1ndalo.<br \/>\nEso es confundir instrucci\u00f3n y educaci\u00f3n. Vicente contin\u00faa habitando en casa de los Gondi hasta 1625, es decir durante los doce primeros a\u00f1os del ni\u00f1o. Dirige la conciencia de los padres. Por lo tanto estos estaban mucho m\u00e1s atentos a su prgenitura que la mayor parte de los miembros de la alta aristocracia. La Sra. de Gondi proclamaba, en su favor: \u00abDeseo mucho m\u00e1s hacer de estos que Dios me ha dado y que pueda darme todav\u00eda santos en el cielo que grandes se\u00f1ores en la tierra\u00bb. La solicitud que prodigaba a sus criados, para formarlos en el examen de conciencia, debi\u00f3 ejercerse prioritariamente sobre sus hijos. \u00bfC\u00f3mo no habr\u00eda reclamado, para su educaci\u00f3n, los consejos de su confesor?<br \/>\nLa ausencia de documentos nos condena a las conjeturas. Una cosa es segura despu\u00e9s de todo : Vicente ha conocido bien al m\u00e1s joven de los ni\u00f1os de la casa. Ha sentido simpat\u00eda por \u00e9l. Y \u00e9l no era hombre para equivocarse sobre la calidad de los seres. La extrema inteligencia del peque\u00f1o Paul, su car\u00e1cter apasionado, entero, intratable, no eran hechos que le desagradaran: solos son capaces de lo mejor los que cortan por la mediocridad, aun cuando sus aspiraciones vayan con riesgos. Sin duda, calcul\u00f3 \u00e9l, porque \u00e9l mismo tambi\u00e9n sufr\u00eda, cu\u00e1nto deb\u00eda pesar la piedad triste, austera, severa, angustiada de la madre a un ni\u00f1o lleno de vida, de regocijo, de exuberancia: y \u00e9l pudo temer por este los efectos de un perfeccionismo espiritual tir\u00e1nico. Velando sus primeros pasos en la vida clerical, habr\u00eda dicho sobre su protegido que \u00bb no ten\u00eda suficiente piedad, pero que no estaba demasiado lejos del reino de Dios \u00ab-17. La carta que dirigir\u00e1 el 5 de septiembre de 1658, muy cercana ya su muerte, al cardenal exiliado, muestra que los acontecimientos ulteriores no le hab\u00edan hecho volver a hablar de su juicio. Mientras tanto, su itinerario se ha cruzado, en muchas ocasiones, ya se ver\u00e1, con el del frondista. Antes que negar estos lazos, ser\u00e1 mejor buscarles el sentido.<\/p>\n<p>Francia, tierra de misi\u00f3n<\/p>\n<p>Vicente, una vez implantado en casa de los Gondi, los convenci\u00f3 f\u00e1cilmente que se asociaran a las empresas de evangelizaci\u00f3n y de caridad que proyectaba. Los doce primeros a\u00f1os del futuro cardenal se desarrollan pues en una casa toda zumbando de militantismo cat\u00f3lico. La lecci\u00f3n no estar\u00e1 perdida para \u00e9l totalmente.<br \/>\nPhilippe-Emmanuel y su esposa repart\u00edan el tiempo entre Par\u00eds y sus dominios rurales. En la capital, habitaban bien en la calle Neuve-des-Petits-Champs, en la plaza Saint-Eustache, donde se los ve hacia 1613-1615, bien en la calle Pav\u00e9e, en el Marais, donde documentos dan fe de su presencia en 1625. En provincias, tienen incluido en las propiedades heredadas del mariscal \u2013el conde de Joigny, la baron\u00eda de Villepreux- tierras aportadas en dote por Margarita de Silly en Folleville, en el Somme, y en Montmirail, en Brie.<br \/>\nEstancias en el campo les hicieron calibrar la extrema pobreza de las iglesias rurales. Se sab\u00eda ciertamente que la instrucci\u00f3n de los sacerdotes era muy insuficiente y que los estragos operados por las guerras de religi\u00f3n los hab\u00edan acostumbrado m\u00e1s a pensar m\u00e1s en su supervivencia que en sus tareas lit\u00fargicas. A pesar de todo, de lejos, no se imaginaba la amplitud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COMBATIENTES DE LA CONTRAREFORMA Jean-Fran\u00e7ois-Paul de Gondi, el futuro memorialista, naci\u00f3 en el castillo de Montmirail, en las tierras que sus padres pose\u00edan en Brie, en septiembre de 1613. Su partida de bautismo menciona que &#8230; <a href=\"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":131652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[17],"tags":[168,224,173,148,175,119,125,131,172,128,135],"class_list":["post-131661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-tiempos-de-vicente-de-paul","tag-argel","tag-berulle","tag-chatillon-les-dombes","tag-clichy","tag-folleville","tag-gondi","tag-joigny","tag-montmirail","tag-pobreza","tag-silly","tag-villepreux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La vida del Cardenal de Retz (IV) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vida del Cardenal de Retz (IV) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"COMBATIENTES DE LA CONTRAREFORMA Jean-Fran\u00e7ois-Paul de Gondi, el futuro memorialista, naci\u00f3 en el castillo de Montmirail, en las tierras que sus padres pose\u00edan en Brie, en septiembre de 1613. Su partida de bautismo menciona que ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-02T07:39:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T14:58:15+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"21 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"La vida del Cardenal de Retz (IV)\",\"datePublished\":\"2014-11-02T07:39:43+00:00\",\"dateModified\":\"2016-07-26T14:58:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/\"},\"wordCount\":4217,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Argel\",\"Berulle\",\"Chatillon\",\"Clichy\",\"Folleville\",\"Gondi\",\"Joigny\",\"Montmirail\",\"Pobreza\",\"Silly\",\"Villepreux\"],\"articleSection\":[\"En tiempos de Vicente de Pa\u00fal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/\",\"name\":\"La vida del Cardenal de Retz (IV) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2014-11-02T07:39:43+00:00\",\"dateModified\":\"2016-07-26T14:58:15+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/la-vida-del-cardenal-de-retz-iv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vida del Cardenal de Retz (IV)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vida del Cardenal de Retz (IV) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/","og_locale":"es_ES","og_type":"article","og_title":"La vida del Cardenal de Retz (IV) - Somos Vicencianos","og_description":"COMBATIENTES DE LA CONTRAREFORMA Jean-Fran\u00e7ois-Paul de Gondi, el futuro memorialista, naci\u00f3 en el castillo de Montmirail, en las tierras que sus padres pose\u00edan en Brie, en septiembre de 1613. Su partida de bautismo menciona que ... Read More","og_url":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2014-11-02T07:39:43+00:00","article_modified_time":"2016-07-26T14:58:15+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"21 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"La vida del Cardenal de Retz (IV)","datePublished":"2014-11-02T07:39:43+00:00","dateModified":"2016-07-26T14:58:15+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/"},"wordCount":4217,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/#primaryimage"},"thumbnailUrl":"","keywords":["Argel","Berulle","Chatillon","Clichy","Folleville","Gondi","Joigny","Montmirail","Pobreza","Silly","Villepreux"],"articleSection":["En tiempos de Vicente de Pa\u00fal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/","url":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/","name":"La vida del Cardenal de Retz (IV) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/#primaryimage"},"thumbnailUrl":"","datePublished":"2014-11-02T07:39:43+00:00","dateModified":"2016-07-26T14:58:15+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/la-vida-del-cardenal-de-retz-iv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"La vida del Cardenal de Retz (IV)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-yfz","jetpack-related-posts":[{"id":119698,"url":"http:\/\/vincentians.com\/es\/el-senor-vicente-relee-su-vida-preceptor\/","url_meta":{"origin":131661,"position":0},"title":"El Se\u00f1or Vicente relee su vida: Preceptor","author":"Francisco Javier Fern\u00e1ndez Chento","date":"11\/02\/2022","format":false,"excerpt":"Fue en la segunda mitad de 1613 cuando concluy\u00f3 mi b\u00fasqueda que tanto dur\u00f3. Recib\u00eda en efecto \"el cargo de preceptor de los hijos del Se\u00f1or Philippe-Emmanuel de Gondi, Conde de Joigny, General de las Galeras de Francia\". El mayor de los hijos, Pierre, ten\u00eda 11 a\u00f1os, el segundo, Henri,\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/f-3-scaled.jpg?fit=1200%2C570&resize=1050%2C600 3x"},"classes":[]},{"id":121642,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-04\/","url_meta":{"origin":131661,"position":1},"title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 04","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/07\/2024","format":false,"excerpt":"Cap\u00edtulo IV Vicente de Pa\u00fal en la casa del general de las galeras. - Retratos de familia: Felipe Manuel de Gondi, su mujer Margarita de Silly y sus hijos. - Vicente de Pa\u00fal, fundador. Volvamos sobre nuestros pasos y entremos en el castillo de Montmirail donde, hacia el fin del\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=1050%2C600 3x"},"classes":[]},{"id":121640,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-02\/","url_meta":{"origin":131661,"position":2},"title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 02","author":"Francisco Javier Fern\u00e1ndez Chento","date":"03\/06\/2024","format":false,"excerpt":"Cap\u00edtulo II Entrada de Vicente en casa de los Gondi en el momento de nacer el cardenal de Retz. - Galer\u00eda de retratos: el mariscal de Retz; el cardenal Pierre de Gondi; Enrique de Gondi, primer cardenal de Retz. Felipe-Manuel de Gondi, general de las galeras, y su mujer Francisca-Margarita\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=1050%2C600 3x"},"classes":[]},{"id":121663,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-06\/","url_meta":{"origin":131661,"position":3},"title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 06","author":"Francisco Javier Fern\u00e1ndez Chento","date":"09\/07\/2024","format":false,"excerpt":"Cap\u00edtulo VI Vicente de Pa\u00fal en Ch\u00e2tillon-lez-Dombes. - Primera fundaci\u00f3n de una asociaci\u00f3n de sirvientas para los pobres. - Vuelta de Vicente a la casa de los Gondi. - Misiones en sus dominios. - Vicente de Pa\u00fal capell\u00e1n real de las galeras. Al llegar a Ch\u00e2tillon-lez-Dombes, Vicente de Pa\u00fal encontr\u00f3\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=1050%2C600 3x"},"classes":[]},{"id":121669,"url":"http:\/\/vincentians.com\/es\/san-vicente-de-paul-y-los-gondi-capitulo-10\/","url_meta":{"origin":131661,"position":4},"title":"San Vicente de Pa\u00fal y los Gondi: Cap\u00edtulo 10","author":"Francisco Javier Fern\u00e1ndez Chento","date":"11\/07\/2024","format":false,"excerpt":"Cap\u00edtulo X Nuevas misiones en las tierras de los Gondi. - Vicente de Pa\u00fal, Retz y Bossuet en San L\u00e1zaro. Un a\u00f1o despu\u00e9s de la entrada de Vicente de Pa\u00fal en los Bons-Enfants, el arzobispo de Par\u00eds, Juan Francisco de Gondi, aprob\u00f3 la obra de las Misiones; el 24 de\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2023\/08\/aaaf.jpg?fit=1200%2C827&resize=1050%2C600 3x"},"classes":[]},{"id":387854,"url":"http:\/\/vincentians.com\/es\/san-vicente-amigo-de-los-pobres-anos-de-busqueda-1613-1617\/","url_meta":{"origin":131661,"position":5},"title":"San Vicente: Amigo de los pobres: a\u00f1os de b\u00fasqueda (1613-1617)","author":"Mitxel Olabu\u00e9naga","date":"12\/10\/2016","format":false,"excerpt":"El se\u00f1or Vicente abandona Clichy El pueblo de Clichy guard\u00f3 siempre un grato recuerdo del mejor de sus p\u00e1rrocos. Pero, cuando m\u00e1s entusiasmado estaba \u00e9ste en sus proyectos, le lleg\u00f3 una carta de Berulle: Deb\u00eda cam\u00adbiar sus actividades. El director espiritual le ped\u00eda que volviera a Par\u00eds. Argumenta\u00adba que ser\u00eda\u2026","rel":"","context":"En \u00abFormaci\u00f3n Vicenciana\u00bb","block_context":{"text":"Formaci\u00f3n Vicenciana","link":"http:\/\/vincentians.com\/es\/category\/formacion-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/st-vincent-de-paul.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/131661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=131661"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/131661\/revisions"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=131661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=131661"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=131661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}