{"id":130366,"date":"2015-03-08T22:19:36","date_gmt":"2015-03-08T21:19:36","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=130366"},"modified":"2016-07-26T17:27:20","modified_gmt":"2016-07-26T15:27:20","slug":"un-perfil-heroico-santa-luisa-de-marillac-14","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/","title":{"rendered":"Un perfil heroico: santa Luisa de Marillac (14)"},"content":{"rendered":"<p style=\"text-align: justify\">No es Efra\u00edm para Mi el hijo querido,<br \/>\nel ni\u00f1o que yo he criado con ternura?<br \/>\nPor eso tendr\u00e9 con \u00e9l entra\u00f1as de misericordia,<br \/>\ndice el Se\u00f1or.<br \/>\n(Jerem\u00edas, XXXI.)<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/04\/louise-marillac.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-140652\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/04\/louise-marillac-300x248.jpg?resize=300%2C248\" alt=\"OLYMPUS DIGITAL CAMERA\" width=\"300\" height=\"248\" \/><\/a>Otra de las obras emprendidas por el ben\u00e9fico celo de la se\u00f1orita Legras fue la de los ni\u00f1os abandonados, llamados m\u00e1s com\u00fanmente exp\u00f3sitos. Estos ni\u00f1os, fruto de pasiones muchas veces inconfesables, fueron en el tiempo de Luisa, como actualmente, una lacra social. Hoy, recibidos y educados convenientemente en establecimientos que se fundan para ellos, nos parece que forman parte de una sociedad que los ha visto nacer as\u00ed y repara la negligencia y el pecado de sus padres, que los abandonaron en su primera edad. Los ni\u00f1os exp\u00f3sitos de hoy cuentan con la compasi\u00f3n social, que, por medio de organismos adecuados, vela por hallar los medios igualitarios entre ellos y los dem\u00e1s hijos de la sociedad.<\/p>\n<p style=\"text-align: justify\">En el siglo XVII tales establecimientos no exist\u00edan. Dicho con m\u00e1s exactitud, a Vicente y a Luisa se debe, en toda su integridad, la beneficencia que se ha hecho en torno a los ni\u00f1os abandonados. Las condiciones en que estas criaturas viv\u00edan antes de que los santos de la caridad se ocuparan de ellos eran tan precarias como desconocidas para sus mismos contempor\u00e1neos.<\/p>\n<p style=\"text-align: justify\">Recogidos por los agentes municipales, eran depositados en casa de una viuda, mujer de pocos escr\u00fapulos morales, y que, por a\u00f1adidura, recib\u00eda una exigua pensi\u00f3n oficial para el mantenimiento de estas criaturas en lo que se llamaba \u00abLa Cuna\u00bb. Dos o tres mujeres, dedicadas a cuidar y alimentar a los pobres ni\u00f1os, eran insuficientes para estos desgraciados.<\/p>\n<p style=\"text-align: justify\">En pleno siglo XVII, en el seno de una sociedad distinguida por la exquisitez de sus costumbres, se encontraban casi diariamente en los atrios de las iglesias y en las puertas de las casas particulares ni\u00f1os reci\u00e9n nacidos que, extenuados de hambre y de miseria, perec\u00edan in\u00e1nimes a los ojos de los que pasaban. Otros eran recogidos por los vigilantes, y despu\u00e9s, por medio del comisario de la barriada, eran depositados en \u00abLa Cuna\u00bb. Las mujeres sirvientas de la viuda que los cuidaba hurtaban de \u00abLa Cuna\u00bb a los ni\u00f1os y los entregaban a personas desalmadas que los destinaban a distintos fines; el m\u00e1s com\u00fan era el de deformar sus miembros en los primeros meses de su vida, de tal modo que pudieran excitar la conmiseraci\u00f3n de las gentes para recoger de ellas alguna limosna.<\/p>\n<p style=\"text-align: justify\">Los fundadores de las Caridades sent\u00edan gran compasi\u00f3n ante la desgracia de estos pobres acogidos, que eran cuatrocientos cada a\u00f1o. Su n\u00famero no llegaba a ser muy crecido en la inh\u00f3spita residencia de \u00abLa Cuna\u00bb porque la mayor\u00eda mor\u00edan de la inanici\u00f3n o medio intoxicados por estupefacientes que les daban aquellas mujeres a fin de dormirlos. Y lo m\u00e1s lamentable, lo que m\u00e1s her\u00eda el coraz\u00f3n de los dos santos en aquel espantoso cuadro de miseria moral, era que estas criaturas mor\u00edan sin esperanza de alcanzar el cielo, puesto que la viuda declar\u00f3 que no hab\u00eda bautizado ni hecho bautizar jam\u00e1s a ninguno de aquellos peque\u00f1uelos.<\/p>\n<p style=\"text-align: justify\">Hacer la propuesta entre las Damas de la Caridad de que pudieran socorrer a estos ni\u00f1os tal y como lo hac\u00edan con los enfermos del Hospital General era cosa en extremo delicada en una sociedad que miraba con extra\u00f1os prejuicios la personalidad ambigua de los bastardos. Mas, a decir verdad, para mejorar la situaci\u00f3n de estas criaturas era necesaria la colaboraci\u00f3n de las damas de la alta sociedad, con las cuales, aunque no rodearan a los ni\u00f1os del afecto maternal de que carec\u00edan, siquiera no les hubieran faltado los recursos materiales, que eran para ellos la vida misma.<\/p>\n<p style=\"text-align: justify\">Una de las m\u00e1s ardientes empresas de Vicente de Pa\u00fal fue la de inspirar en el coraz\u00f3n de aquellas damas el que supieran vencer este concepto poco cristiano de los hijos naturales, que, a pesar de su inocencia personal, eran estigmatizados como hijos del pecado m\u00e1s horrible. Vicente rog\u00f3 a algunas de estas damas que visitasen \u00abLa Cuna\u00bb que viesen los abusos que all\u00ed se comet\u00edan con estas criaturas, y despu\u00e9s solicit\u00f3 de esa generosidad, de esa ternura que toda mujer lleva en su coraz\u00f3n, la ayuda que necesitaba para los pobres ni\u00f1os.<\/p>\n<p style=\"text-align: justify\">Esta sociedad aristocr\u00e1tica ten\u00eda coraz\u00f3n, pero se hallaba demasiado alejada de las miserias humanas para poder encerrarlas en s\u00ed, para poderlas conocer. Cuando se hubo puesto en contacto con la miseria latente en los cuerpos d\u00e9biles de los ni\u00f1os abandonados fue capaz de todas las generosidades, y, movido por la palabra ardiente de Vicente de Pa\u00fal, el peque\u00f1o grupo de damas que visitaron \u00abLa Cuna\u00bb de Par\u00eds se resolvi\u00f3 a encontrar para ellos una ayuda en la primera persona de todas las que compon\u00edan la Caridad, providencia visible de los peque\u00f1os desgraciados, que era Luisa de Marillac.<\/p>\n<p style=\"text-align: justify\">Los comienzos de las obras de Vicente, como sabemos, fueron siempre humildes, porque fue enemigo de la ostentaci\u00f3n, de emprender obras grandiosas en sus principios, que hubieran ca\u00eddo despu\u00e9s por falta de recursos. Por esto, requeridas por las damas, Luisa de Marillac y sus hijas, las Siervas de los Pobres, recogieron a algunos de estos ni\u00f1os, pocos en un principio, faltos de nodrizas, hubieron de alimentarlos con leche de cabra; son notables, conmovedores, los detalles de las cartas de Luisa de Marillac acerca de los cuidados de los pobres ni\u00f1os abandonados.<\/p>\n<p style=\"text-align: justify\">Luisa, en todo sujeta a las iniciativas de Vicente, era, una vez que se le hab\u00eda dado la indicaci\u00f3n de actuar, quien abr\u00eda las puertas de los tesoros de la compasi\u00f3n y volaba a la consecuci\u00f3n de todo aquello que pod\u00eda ser beneficioso para las obras de la Peque\u00f1a Compa\u00f1\u00eda. \u00bfQu\u00e9 sentir\u00eda su coraz\u00f3n de madre al primer contacto con aquellas criaturas, bellas por su inocencia, pero envueltas en las m\u00e1s repugnantes miserias? Podr\u00eda considerar, en la balanza del amor divino, la contraposici\u00f3n que hab\u00eda entre aquellas madres que abandonaron sin coraz\u00f3n a los peque\u00f1uelos y el amor inmenso con que ella hab\u00eda cuidado a su \u00fanico hijo, viviendo siempre pendiente de su suerte, hasta tal punto que Vicente hubo de refrenar muchas veces su \u00edmpetu algo desasosegado.<\/p>\n<p style=\"text-align: justify\">Por otra parte, su alma se conmov\u00eda pensando en la misericordia divina, que no se olvida de los peque\u00f1os, puesto que ella, en nombre de Dios mismo, les abr\u00eda las puertas de la Caridad. Desde entonces aquellos ni\u00f1os no carecer\u00edan jam\u00e1s del amor maternal. junto a su cuna ve-lar\u00edan, en todas las partes del mundo, en todos los tiempos, las alas blancas de una Hija de la Caridad. Recordemos que su misma condici\u00f3n de hu\u00e9rfana la har\u00eda mucho m\u00e1s comprensiva del abandono de estos peque\u00f1uelos, puesto que ella, capaz de las mayores ternuras, las hab\u00eda deseado muchas veces en sus primeros a\u00f1os, faltos siempre de las caricias maternas. De ah\u00ed que su coraz\u00f3n, que indudablemente guardaba los trazos de su primera infancia, comprendiese perfectamente el dolor de estos ni\u00f1os.<\/p>\n<p style=\"text-align: justify\">Sus bi\u00f3grafos nos dejaron, como queda dicho anteriormente, una estampa convencional de Santa Luisa por la melancol\u00eda de su temperamento, influido por las tristezas de la ni\u00f1ez. Digamos m\u00e1s bien que el Dios providente, que la hab\u00eda destinado desde la eternidad a una misi\u00f3n caritativa junto a los hu\u00e9rfanos, hab\u00eda querido prepararla para tan hermosa tarea con un contenido precioso de amor hacia un estado del que conoc\u00eda la soledad, el abandono, el deseo de calor de la madre a quien nadie en el mundo puede sustituir, salvo el amor de Dios, cuando se hace visible por la caridad.<br \/>\nMadre por naturaleza, aunque hab\u00eda sobrenaturalizado este amor, que pod\u00eda ser tierno y natural hacia su hijo, y madre de las Hijas de la Caridad, una tercera maternidad le aguardaba en la persona de estos pobres ni\u00f1os. La caridad de Jesucristo hab\u00eda venido a sustituir a la beneficencia humana, pobre, desfigurada por las conveniencias sociales. Luisa de Marillac, que hab\u00eda sublimado ya en Dios sus m\u00e1s grandes amores, se inclinaba ante la cuna de estos peque\u00f1uelos para darles, sola y puramente por amor de Dios, de una vez para siempre en el transcurso de los siglos, unas madres abnegadas en las Hijas de la Caridad.<\/p>\n<p style=\"text-align: justify\">Como en todas las obras emprendidas con un fin caritativo, en \u00e9sta no bastaban los entusiasmos del coraz\u00f3n, porque, lejos de solucionar favorablemente la situaci\u00f3n haci\u00e9ndola estable y fecunda, hubieran pasado pronto, como otros muchos proyectos del mundo. Tras la resoluci\u00f3n de recoger a los ni\u00f1os vino la necesidad de organizar la caridad hacia ellos, el rescatar, dig\u00e1moslo as\u00ed, del infecto lugar de \u00abLa Cuna\u00bb al mayor n\u00famero de ellos, conforme a las posibilidades que se tuvieran para atenderlos decorosamente. En 1638 se abre una casa para ellos en I barrio de San V\u00edctor.<br \/>\nA pesar de la gran simpat\u00eda que despert\u00f3 la obra entre las Damas de la Caridad, \u00e9stas apenas allegaban m\u00e1s recursos que los que primitivamente hab\u00edan asignado para el cuidado de los hu\u00e9rfanos. Eran \u00e9stos doce, que puntualmente se sustitu\u00edan por otros, si mor\u00edan. Pero Luisa, llevada por su ardiente caridad, sufr\u00eda al ver que la muerte segu\u00eda arrebatando a los peque\u00f1os, aunque ahora regenerados por el santo bautismo. Por eso decidi\u00f3, con Vicente, hacer una asamblea general (le las Damas, para poner ante ellas el doliente espect\u00e1culo de los ni\u00f1os exp\u00f3sitos. A ella acudieron las m\u00e1s dignas damas de la aristocracia, pie, conmovidas por las palabras ardientes de Vicente de. Pa\u00fal, decidieron darse por completo a la obra de los ni\u00f1os abandonados.<\/p>\n<p style=\"text-align: justify\">En 1640, y gracias a la caridad comunicativa del santo sacerdote, las damas retornaron a su cargo a todos los infantes de \u00abLa Cuna\u00bb. Grande fue la alegr\u00eda de Luisa, que estaba ausente de Par\u00eds, al saber la resoluci\u00f3n tomada por las Damas, toda vez que \u00e9sta era la se\u00f1al que esperaba de la Providencia para lanzarse a la redenci\u00f3n de los peque\u00f1uelos.<\/p>\n<p style=\"text-align: justify\">Se habilitaron nuevas casas para albergar a los ni\u00f1os. Algunos fueron acogidos en La Chapelle, cerca de Par\u00eds. Tom\u00f3 algunas nodrizas para aquella casa, y as\u00ed asegur\u00f3 la vida de los peque\u00f1os. A otros los mand\u00f3 a provincias, porque muchas de estas mujeres no quer\u00edan trasladarse a Par\u00eds. Esto representaba un nuevo inconveniente para ella, puesto que tendr\u00eda que ampliar sus visitas, mas, aun as\u00ed, instal\u00f3 el n\u00famero m\u00e1s crecido de ni\u00f1os en los alrededores de Par\u00eds.<\/p>\n<p style=\"text-align: justify\">La experiencia de los sufrimientos que estos peque\u00f1os hab\u00edan padecido en \u00abLa Cuna\u00bb le hac\u00eda ver en todos sus detalles la amplitud de la obra que hab\u00eda tomado a su cargo. Por ello, usando de m\u00e9todos que hoy nos asombran por su modernidad, dej\u00f3 a los ni\u00f1os en poder de las nodrizas que les hab\u00eda buscado, pero siempre con el vigilante cuidado de escoger, entre ellas, aquellas que gozaban de buena salud que garantizara la sana crianza de los peque\u00f1os y que a la vez tuvieran fama de moralidad intachable.<\/p>\n<p style=\"text-align: justify\">Para ello se vali\u00f3 de encuestas, certificados, visado de las autoridades eclesi\u00e1sticas del lugar donde resid\u00edan las nodrizas, y otros requisitos que no escaparon a su caridad. Las mujeres hab\u00edan de garantizar los extremos que interesaban para que el buen cuidado de los ni\u00f1os quedase asegurado. La Compa\u00f1\u00eda de las Hijas de la Caridad guarda como un precioso tesoro en sus archivos algunas de estas encuestas que se hac\u00edan a las primeras nodrizas de los hu\u00e9rfanos, en las que se adivina la mano de Luisa de Marillac, previsora y caritativa, juntamente con algunos datos anotados por Vicente de Pa\u00fal, lo cual nos hace ver la estrecha colaboraci\u00f3n de estos dos santos en la obra magna de los ni\u00f1os exp\u00f3sitos.<\/p>\n<p style=\"text-align: justify\">La visita de las Caridades se hac\u00eda cada vez m\u00e1s apremiante. Luisa confi\u00f3 a las Damas la visita de las de Par\u00eds, y ella se dedic\u00f3 a hacerla en las de provincias. Asimismo, algunas Damas que ten\u00edan posibilidad de dejar sus hogares por alg\u00fan tiempo iban tambi\u00e9n a los lugares alejados de la capital. En 1642 una Hija de la Caridad acompa\u00f1a a una de las Damas para visitar a los ni\u00f1os que se hallaban en algunas localidades de Normand\u00eda. Luisa, en vista de que las Hijas de la Caridad empezaban a ser designadas para la visita de los ni\u00f1os exp\u00f3sitos, ensanch\u00f3 los campos de su caridad para darlas una instrucci\u00f3n s\u00f3lida sobre el cuidado de los ni\u00f1os y hacer de ellas unas nuevas madres para los que carec\u00edan de ella.<\/p>\n<p style=\"text-align: justify\">Pocos a\u00f1os despu\u00e9s, en 1653, los recursos de las cunas se hallaban en crisis. Las deudas se multiplicaban. Las Damas de la Caridad, agobiadas por otros grav\u00e1menes que la sociedad les impon\u00eda, apenas pod\u00edan aumentar los recursos que ten\u00edan destinados al cuidado de los ni\u00f1os. Las nodrizas amenazaban con dejarlos abandonados. En este caos de confusi\u00f3n, que hubiese desalentado a otras almas de poca fe, Vicente de Pa\u00fal y Luisa de Marillac ten\u00edan toda su confianza puesta en Dios, a quien pertenec\u00eda velar por las vidas de los hu\u00e9rfanos. Luisa, que ya hab\u00eda visitado a los grandes de la corte para exponerles la ne-cesidad en que se hallaban, estaba fatigada ante las negativas, pues ni siquiera del mismo canciller del rey, a quien hab\u00eda ido a pedir socorro urgente para cien de aquellos ni\u00f1os que se hallaban sin lo m\u00e1s indispensable para su alimentaci\u00f3n, hab\u00eda obtenido lo m\u00e1s m\u00ednimo.<\/p>\n<p style=\"text-align: justify\">Se trataba de recurrir de nuevo a las Damas de la Caridad para mover a compasi\u00f3n aquellos nobles corazones, sin cuya colaboraci\u00f3n la obra de los ni\u00f1os hu\u00e9rfanos se hubiera reducido a la nada. Algunos de ellos hubieran podido retenerse; pero los dem\u00e1s enviados al Hospital General, fuera de un ambiente que les era propio, hubieran encontrado grandes dificultades para vivir.<\/p>\n<p style=\"text-align: justify\">Mas no bastaba el socorro personal de las Damas para cubrir totalmente las necesidades de los ni\u00f1os. Luisa, a fin de satisfacer algunas deudas que ya gravitaban sobre la Compa\u00f1\u00eda, hizo que en la casa de las Hijas de la Caridad se disminuyese la alimentaci\u00f3n hasta tal punto que qued\u00f3 reducida a lo m\u00e1s indispensable, con una sola comida al d\u00eda, compuesta de alimentos groseros y comunes. Luisa, sin consultar las reglas de la prudencia humana ni las leyes de la naturaleza, segu\u00eda \u00fanicamente los impulsos de su celo, que la atra\u00eda a las m\u00e1s heroicas acciones de caridad.<\/p>\n<p style=\"text-align: justify\">Ante la carencia de recursos y la negativa de las Damas de la Caridad, Luisa de Marillac procur\u00f3 contrarrestar aquella situaci\u00f3n con la doble abnegaci\u00f3n de sus Hijas, las Siervas de los Pobres. Luisa, que hab\u00eda aprendido el amor de Dios en la escuela del sacrificio, sab\u00eda perfectamente que el Se\u00f1or obra milagros de providencia en favor de aquellos que se acuerdan de los desvalidos. Por eso procur\u00f3 formar a sus hijas reciamente en el cuidado de los hu\u00e9rfanos, y no escogi\u00f3 a cualquiera de ellas para esta misi\u00f3n, sino que seleccion\u00f3 con gran cuidado a aquellas que iban a ser las madres de los hu\u00e9rfanos.<\/p>\n<p style=\"text-align: justify\">La obra de los ni\u00f1os abandonados pasaba por un trance amargo, del que iba a surgir con una pujanza definitiva. En tales circunstancias, las lijas de la Caridad que eran destinadas a las Cunas recib\u00edan de labios de Vicente de Pa\u00fal el aliento divino que hab\u00eda de preparar sus cora-zones. De este modo el trabajo agotador junto a los pobres ni\u00f1os, la falta de recursos, la mala alimentaci\u00f3n, los disgustos que pod\u00eda traer el cuidado de estas criaturas, quedaban altamente contrarrestados con la inefable palabra de Vicente, que les hac\u00eda volver la mirada hacia horizontes m\u00e1s elevados, a trav\u00e9s de la miseria real de aquellos ni\u00f1os. Cuanto m\u00e1s abandono sufr\u00edan los peque\u00f1os de parte del mundo tanto m\u00e1s se representaba a Vicente la se\u00f1al inequ\u00edvoca de que la misi\u00f3n de las Hermanas entre ellos era una misi\u00f3n divina:<\/p>\n<p style=\"text-align: justify\">\u00abDesde toda la eternidad Dios os ha escogido, hijas m\u00edas, para su servicio. \u00a1Qu\u00e9 honor para vosotras! Si las personas del mundo se tienen por honradas cuando se les designa para servir a los hijos de los grandes, \u00a1cu\u00e1nto m\u00e1s os hab\u00e9is de sentir vosotras, que hab\u00e9is sido llamadas a servir a los hijos de Dios.\u00bb<\/p>\n<p style=\"text-align: justify\">Y les pon\u00eda delante el ejemplo que hab\u00edan de dar a los peque\u00f1os, no escandaliz\u00e1ndolos, antes bien mostr\u00e1ndose siempre como madres suyas, dispuestas a servirlos a todos con el mismo afecto y cari\u00f1o.<\/p>\n<p style=\"text-align: justify\">Luisa de Marillac las animaba en el mismo sentido. Lo atestigua su correspondencia, en la que se\u00f1ala con toda evidencia que las Hijas de la Caridad tienen en sus manos, con sus cuidados, la vida y el porvenir moral de los ni\u00f1os de \u00abLa Cuna\u00bb. Solicita de ellas una pervisi\u00f3n vigilante y aquellas hermosas cualidades que reflejaran un amor que, siendo completamente sobrenatural, creara el ambiente de amor maternal que esas criaturas necesitaban. De ah\u00ed que, en tarea tan delicada, les hiciera presente que su ejemplo era definitivo para los ni\u00f1os, y que cualquier negligencia en el servicio de los mismos ser\u00eda altamente perjudicial. En palabras de Vicente:<\/p>\n<p style=\"text-align: justify\">\u00abSi la se\u00f1orita hubiera podido disponer de \u00e1ngeles, a ellos debiera haber encomendado el servicio de los ni\u00f1os exp\u00f3sitos.\u00bb<\/p>\n<p style=\"text-align: justify\">Luisa, que hab\u00eda previsto con sabios reglamentos la asistencia a los enfermos a domicilio y en los hospitales, extendi\u00f3 tambi\u00e9n los objetivos de la caridad a la formaci\u00f3n de las Hermanas que hab\u00edan de cuidar de los exp\u00f3sitos y al m\u00e9todo de vida que hab\u00eda de seguirse en las Cunas. Estos reglamentos, fruto de la colaboraci\u00f3n de los dos santos, est\u00e1n llenos de detalles que dejan adivinar la mano de una mujer; una mano no s\u00f3lo guiada por un coraz\u00f3n ardiente, sino por una inteligencia pr\u00e1ctica poco coman. En ella puede verse, no s\u00f3lo a la santa que se extas\u00eda al contemplar a Dios en un ni\u00f1o abandonado, sino que, soberanamente compasiva, asegura a Cristo, ni\u00f1o en los ni\u00f1os, la solidez de la caridad bienhechora.<\/p>\n<p style=\"text-align: justify\">En dicho reglamento est\u00e1n sabiamente se\u00f1aladas las prescripciones higi\u00e9nicas, las reglas morales que habr\u00edan de asegurar la buena salud de cuerpo y alma a los peque\u00f1os hu\u00e9rfanos. En \u00e9l est\u00e1n previstos, junto a los m\u00ednimos detalles de la higiene rudimentaria entonces en uso, la manera de imponer castigos a las naturalezas que podr\u00edan empezar a rebelarse.<\/p>\n<p style=\"text-align: justify\">\u00abSi se ha de castigar a los peque\u00f1os&#8211;dice\u2014, sea con peque\u00f1as mortificaciones o, todav\u00eda mejor, con decirles algunas palabras amables, que les hagan cobrar alientos para dirigirse en lo sucesivo por el camino del bien.\u00bb<\/p>\n<p style=\"text-align: justify\">Aconseja a las Siervas de los Pobres que no corrijan nunca a los ni\u00f1os en un momento de pasi\u00f3n. Este bello conjunto, armon\u00eda de cuerpo y esp\u00edritu, es la base de todo un mundo pedag\u00f3gico muy superior al de la \u00e9poca.<\/p>\n<p style=\"text-align: justify\">Adem\u00e1s, previendo que estos pobres ni\u00f1os habr\u00edan de enfrentarse con la vida en \u00e9poca no lejana, menos de lo que su edad requer\u00eda, Luisa no descuida el inculcar a sus hijas que deben asegurar a estos ni\u00f1os un aprendizaje que empiece desde la cuna, para que despu\u00e9s hallen m\u00e1s f\u00e1cil acceso a cualquier empleo u oficio. Sus cartas a este res-pecto son la mejor lecci\u00f3n de econom\u00eda previsora. Una peque\u00f1a escuela de oficios, donde cada uno de los peque\u00f1os se considera pieza indispensable en el peque\u00f1o mundo en que vive, y comprenda desde los primeros d\u00edas de su infancia que debe ser el elemento consciente de una sociedad que ser\u00e1 su \u00fanica y dilatada familia.<\/p>\n<p style=\"text-align: justify\">Esta previsi\u00f3n, que preludia la organizaci\u00f3n compleja de los modernos establecimientos de caridad, est\u00e1 cimentada tambi\u00e9n en el orden. Ninguno de los peque\u00f1os habitantes de las cunas pod\u00eda ser ingresado sin las requisitorias previas que estaban reglamentadas para el caso. Luisa, ardiente en su caridad, sabe que la mejor garant\u00eda de mantener las obras es una perfecta organizaci\u00f3n, tan lejos del celo indiscreto como de la indiferencia.<\/p>\n<p style=\"text-align: justify\">Semejantes ejemplos por parte de la Santa Fundadora deb\u00edan encender en el coraz\u00f3n de las Hijas de la Caridad un fuego ardiente capaz de alimentar en sus almas el deseo de darse continuamente al servicio de estos peque\u00f1os, toda vez que viv\u00edan en el hermoso panorama de lo divino.<\/p>\n<p style=\"text-align: justify\">Quedan testimonios fidedignos de que aquellas abnegadas Hermanas recog\u00edan con todo amor a los peque\u00f1os que se les presentaban en el Hospital General por parte de los administradores, en cualquier tiempo y a todas las horas, muy especialmente durante la noche. Ellas mismas los trasladaban a la casa que hab\u00edan habilitado para ellos en 1 barrio de San L\u00e1zaro. Para evitar a los peque\u00f1os, a veces de salud muy deficiente, el ajetreo que supon\u00eda el trasladarlos en un coche mil acondicionado, lo cual hubiera sido grave para las pobres criaturas, ellas mismas los llevaban en los brazos. Una de las hermanas, an\u00f3nima hero\u00edna de la caridad, como otras muchas que pasaron, ten\u00eda verdadero cari\u00f1o a esta ocupaci\u00f3n en bien de los ni\u00f1os exp\u00f3sitos, y la ejercit\u00f3 hasta bien avanzada su edad. No era extra\u00f1o verla por los suburbios de Par\u00eds con el cesto de provisiones para sus pobres en un brazo, y llevando en el otro, como preciosa carga, uno de estos peque\u00f1os abandonados, que llevaba a la Cuna de San L\u00e1zaro.<\/p>\n<p style=\"text-align: justify\">La administraci\u00f3n de esta obra ben\u00e9fica estaba completamente a cargo de Luisa de Marillac, que multiplicaba las posibilidades hasta lo insospechado para no rechazar a ninguno de los hu\u00e9rfanos abandonados a la caridad p\u00fablica.<\/p>\n<p style=\"text-align: justify\">Sus continuas insistencias ante los personajes de la corte hicieron que en 1642 el rey Luis XIII les asignara una renta de 4.000 libras anuales, y que Ana de Austria, la reina regente, la aumentara con otra donaci\u00f3n real de 8.000. En 1643 la duquesa de Aiguillon y madame de Miramion aportan cantidades considerables. Pero los gastos aumentaban en la Caridad, lo cual causaba verdaderas defecciones en el \u00e1nimo de aquellas heroicas mujeres. A mil doscientos se elevaba el n\u00famero de los acogidos en las Cunas desde 1638. Las cargas pecuniarias para hacer frente a los gastos hab\u00edan llegado a hacerse insostenibles. Vicente hizo una \u00faltima llamada a las Damas de la Caridad para que vinieran en ayuda de La Cuna. Son notables las palabras que les dirigi\u00f3 con tal motivo, inflamadas en la caridad de su coraz\u00f3n. A esta asamblea acudieron las m\u00e1s nobles damas de la aristocracia, que re-solvieron darse por completo a la obra de los hu\u00e9rfanos. El santo sacerdote supo llegar al coraz\u00f3n de aquellas se\u00f1oras present\u00e1ndoles, con el peso de eternidad que daba a sus palabras, la suerte que corr\u00edan las vidas de aquellos ni\u00f1os, que morir\u00edan abandonados si ellas no daban sus riquezas para auxiliarlos. \u00abEllos ser\u00e1n vuestros jueces en el tribunal de Dios\u2014les dec\u00eda\u2014, porque, pudiendo ser sus madres, los hab\u00e9is abandonado.\u00bb<\/p>\n<p style=\"text-align: justify\">Estas hermosas palabras concluyeron por dar el triunfo a los ni\u00f1os exp\u00f3sitos, y las Damas prometieron a Vicente que por nada abandonar\u00edan la hermosa obra que hab\u00edan comenzado. En lugar de aminorar los socorros que hab\u00edan asignado a los ni\u00f1os, las Damas adquirieron el castillo de Bicetre, que pusieron a disposici\u00f3n de Luisa de Marillac y de sus hijas para que instalaran all\u00ed a los hu\u00e9rfanos. La guerra de la Fronda, desencadenada en 1652, no fue obst\u00e1culo que hiciera abandonar aquella residencia, aunque estaba situada en una zona cas-tigada; antes bien, la caridad de Luisa y de sus hijas, las Siervas de los Pobres, se extendi\u00f3 en socorro de los combatientes que tomaron parte de las luchas en frentes cercanos a la nueva Casa de los hu\u00e9rfanos. De este modo aseguraron el alimento de las personas que, a causa de la guerra civil, hab\u00edan quedado sin amparo. M\u00e1s tarde este socorro se extendi\u00f3 a todos los necesitados de Par\u00eds que hab\u00edan sufrido los desastres y se acogieron a la llamada \u00absopa popular\u00bb distribuida por las Hijas de la Caridad. Luisa hace constar en una de sus notas dirigidas a Vicente de Pa\u00fal: \u00abHay parroquias en las cuales se socorre a cinco mil pobres con la sopa popular. En la nuestra se les da a dos mil, sin contar a los enfermos, a quienes asistimos cotidianamente\u00bb.<\/p>\n<p style=\"text-align: justify\">Volvamos a considerar la obra de las Cunas. Por su amplitud, por su significado y por su pervivencia, podr\u00eda llam\u00e1rsela \u00abla epopeya de la caridad\u00bb. De aquella primera \u00abCuna\u00bb que cost\u00f3 tantas privaciones a Luisa de Marillac y tantos sacrificios a sus heroicas hijas hab\u00edan de salir las florecientes \u00abCasas Cuna\u00bb de nuestros d\u00edas, de las que todos los pa\u00edses civilizados se glor\u00edan como de uno de los t\u00edtulos m\u00e1s eminentes de su beneficencia y de su altura moral. En lugar de desatender el cuidado de las criaturas venidas al mundo en condiciones poco favorables las hacen entrar en la sociedad con las mejores garant\u00edas para vivir una vida plenamente humana en las condiciones normales a todo ambiente civilizado.<\/p>\n<p style=\"text-align: justify\">Estas grandes organizaciones, que se superan continuamente en toda clase de adelantos pedag\u00f3gicos, amables hogares donde los ni\u00f1os encuentran, junto a su cuna, la mirada maternal de una religiosa que los ama tanto m\u00e1s intensa cuanto m\u00e1s sobrenaturalmente, son la herencia de aquella primera \u00abCuna\u00bb donde Luisa contempl\u00f3 a Cristo tras las apariencias de un ni\u00f1o abandonado.<\/p>\n<p>No es dif\u00edcil ver a los santos fundadores de las Hijas de la Caridad representados en im\u00e1genes o pinturas llevando a un ni\u00f1o en los brazos, al que amparan cari\u00f1osamente. La devoci\u00f3n art\u00edstica o popular ha podido rendir as\u00ed un elogio c\u00e1lido a San Vicente y a Santa Luisa para testimoniar el amor ardiente que tuvieron hacia la infancia desamparada. Sin embargo, esto no pasa de ser un tierno simbolismo que refleja la amorosa solicitud con que acogieron siempre a los ni\u00f1os abandonados. Para ser m\u00e1s exactos en la representaci\u00f3n, esos ni\u00f1os deber\u00edan ir puestos, no en los brazos, sino en el coraz\u00f3n de ambos santos, donde hallaron el verdadero fuego de la caridad, al que ellos, pobres ni\u00f1os desvalidos, debieron la vida temporal y los horizontes de la eterna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No es Efra\u00edm para Mi el hijo querido, el ni\u00f1o que yo he criado con ternura? Por eso tendr\u00e9 con \u00e9l entra\u00f1as de misericordia, dice el Se\u00f1or. (Jerem\u00edas, XXXI.) Otra de las obras emprendidas por &#8230; <a href=\"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":140652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[152,143],"class_list":["post-130366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luisa-de-marillac","tag-duquesa-de-aiguillon","tag-san-lazaro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un perfil heroico: santa Luisa de Marillac (14) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un perfil heroico: santa Luisa de Marillac (14) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"No es Efra\u00edm para Mi el hijo querido, el ni\u00f1o que yo he criado con ternura? Por eso tendr\u00e9 con \u00e9l entra\u00f1as de misericordia, dice el Se\u00f1or. (Jerem\u00edas, XXXI.) Otra de las obras emprendidas por ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-08T21:19:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T15:27:20+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"23 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Un perfil heroico: santa Luisa de Marillac (14)\",\"datePublished\":\"2015-03-08T21:19:36+00:00\",\"dateModified\":\"2016-07-26T15:27:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/\"},\"wordCount\":4673,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Duquesa de Aiguillon\",\"San L\u00e1zaro\"],\"articleSection\":[\"Luisa de Marillac\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/\",\"name\":\"Un perfil heroico: santa Luisa de Marillac (14) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-03-08T21:19:36+00:00\",\"dateModified\":\"2016-07-26T15:27:20+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un perfil heroico: santa Luisa de Marillac (14)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un perfil heroico: santa Luisa de Marillac (14) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/","og_locale":"es_ES","og_type":"article","og_title":"Un perfil heroico: santa Luisa de Marillac (14) - Somos Vicencianos","og_description":"No es Efra\u00edm para Mi el hijo querido, el ni\u00f1o que yo he criado con ternura? Por eso tendr\u00e9 con \u00e9l entra\u00f1as de misericordia, dice el Se\u00f1or. (Jerem\u00edas, XXXI.) Otra de las obras emprendidas por ... Read More","og_url":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-03-08T21:19:36+00:00","article_modified_time":"2016-07-26T15:27:20+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"23 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Un perfil heroico: santa Luisa de Marillac (14)","datePublished":"2015-03-08T21:19:36+00:00","dateModified":"2016-07-26T15:27:20+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/"},"wordCount":4673,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/#primaryimage"},"thumbnailUrl":"","keywords":["Duquesa de Aiguillon","San L\u00e1zaro"],"articleSection":["Luisa de Marillac"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/","url":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/","name":"Un perfil heroico: santa Luisa de Marillac (14) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-03-08T21:19:36+00:00","dateModified":"2016-07-26T15:27:20+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Un perfil heroico: santa Luisa de Marillac (14)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-xUG","jetpack-related-posts":[{"id":127068,"url":"http:\/\/vincentians.com\/es\/ante-la-infancia-abandonada-v\/","url_meta":{"origin":130366,"position":0},"title":"Ante la infancia abandonada (V)","author":"Mitxel Olabu\u00e9naga","date":"09\/08\/2024","format":false,"excerpt":"Servicio ordenado Luisa insiste siempre en la necesidad de controlar el di\u00adnero que pasa por las hermanas \"para ponerlo exactamente cn las manos de la dama destinada a este efecto\". Igual\u00admente hace hincapi\u00e9 en que las hermanas obedezcan fiel\u00admente las leyes establecidas para mantener un buen orden en el servicio.\u2026","rel":"","context":"En \u00abHistoria de las Hijas de la Caridad\u00bb","block_context":{"text":"Historia de las Hijas de la Caridad","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-las-hijas-de-la-caridad\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":130529,"url":"http:\/\/vincentians.com\/es\/santa-luisa-ante-la-infancia-abandonada-iii\/","url_meta":{"origin":130366,"position":1},"title":"Santa Luisa: ante la infancia abandonada (III)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/05\/2014","format":false,"excerpt":"Dificultades: ...Sin dinero El enfriamiento de la caridad y el agotamiento de los recursos de la obra hac\u00edan de la direcci\u00f3n del personal de los ni\u00f1os abandonados un peso aplastante para la se\u00f1orita Le Gras. Desde el primer a\u00f1o de la guerra civil, las privaciones en la obra fueron extremas.\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"Hijas-de-la-Caridad-18-Luisa","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/05\/Hijas-de-la-Caridad-18-Luisa.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":130531,"url":"http:\/\/vincentians.com\/es\/santa-luisa-ane-la-infancia-abandonada-iv\/","url_meta":{"origin":130366,"position":2},"title":"Santa Luisa: ante la infancia abandonada (IV)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"28\/05\/2014","format":false,"excerpt":"Dedicaci\u00f3n de las hermanas Bajo la direcci\u00f3n conjunta de los dos santos, no es sorprendente que sus hijas hayan comprendido tan bien las lecciones recibidas. Su aplicaci\u00f3n no estaba falta de fatiga, pero este cansancio incluso les era tanto m\u00e1s dulce en cuanto que estaba acompa\u00f1ado de grandes consuelos que\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"Hijas-de-la-Caridad-18-Luisa","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/05\/Hijas-de-la-Caridad-18-Luisa.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":119748,"url":"http:\/\/vincentians.com\/es\/el-senor-vicente-relee-su-vida-los-ninos-abandonados\/","url_meta":{"origin":130366,"position":3},"title":"El Se\u00f1or Vicente relee su vida: Los ni\u00f1os abandonados","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/05\/2013","format":false,"excerpt":"Par\u00eds sufr\u00eda tambi\u00e9n con otra plaga cruel: los ni\u00f1os abandonados. Uno al d\u00eda de media, de tres a cuatrocientos al a\u00f1o\u2026 \"La Couche\", instituci\u00f3n fundada en tiempos atr\u00e1s por la ciudad, era inadaptada. Sent\u00eda presiones para hacer algo. El a\u00f1o de 1637 transcurri\u00f3 reflexionando, y el 1\u00ba de enero de\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":123943,"url":"http:\/\/vincentians.com\/es\/el-senor-vicente-relee-su-vida-los-ninos-abandonados-2\/","url_meta":{"origin":130366,"position":4},"title":"El Se\u00f1or Vicente relee su vida: Los ni\u00f1os abandonados","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/05\/2013","format":false,"excerpt":"Par\u00eds sufr\u00eda tambi\u00e9n con otra plaga cruel: los ni\u00f1os abandonados. Uno al d\u00eda de media, de tres a cuatrocientos al a\u00f1o\u2026 \"La Couche\", instituci\u00f3n fundada en tiempos atr\u00e1s por la ciudad, era inadaptada. Sent\u00eda presiones para hacer algo. El a\u00f1o de 1637 transcurri\u00f3 reflexionando, y el 1\u00ba de enero de\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":127066,"url":"http:\/\/vincentians.com\/es\/ante-la-infancia-abandonada-iv\/","url_meta":{"origin":130366,"position":5},"title":"Ante la infancia abandonada (IV)","author":"Mitxel Olabu\u00e9naga","date":"07\/08\/2024","format":false,"excerpt":"...Se intenta apiadar a las damas Acaba sin embargo por mostrar en una carta a la se\u00f1o\u00adrita de Lamoignon, la necesidad urgente de una asamblea de damas y la necesidad de cuestaciones suplementarias para sostener la empresa una vez m\u00e1s. Parecidos gritos de angustia sobre la suerte de las pobres\u2026","rel":"","context":"En \u00abHistoria de las Hijas de la Caridad\u00bb","block_context":{"text":"Historia de las Hijas de la Caridad","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-las-hijas-de-la-caridad\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/130366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=130366"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/130366\/revisions"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=130366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=130366"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=130366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}