{"id":130270,"date":"2015-03-05T08:55:55","date_gmt":"2015-03-05T07:55:55","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=130270"},"modified":"2016-07-26T17:27:21","modified_gmt":"2016-07-26T15:27:21","slug":"un-perfil-heroico-santa-luisa-de-marillac-11","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/","title":{"rendered":"Un perfil heroico: santa Luisa de Marillac (11)"},"content":{"rendered":"<p>SED fervorosos de esp\u00edritu, acord\u00e1ndoos de que<br \/>\nes al Se\u00f1or a quien serv\u00eds.<br \/>\nAlegraos con la esperanza del premio.<br \/>\n(Ep. a los romanos, XII.)<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/04\/louise-marillac.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-140652\" src=\"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/04\/louise-marillac-300x248.jpg?resize=300%2C248\" alt=\"OLYMPUS DIGITAL CAMERA\" width=\"300\" height=\"248\" \/><\/a>EN la campi\u00f1a que rodea la humilde villa de Suresnes se divisa la gr\u00e1cil figura de una joven pastora que cuida de su ganado. Los vestidos son pobres; el aire agita sus cabellos bajo la hu\u00admilde cofia que apenas los sujeta. De vez en vez, por la carretera que bordea los prados rientes, se adivina la figura de un cami\u00adnante que hace su jornada a pie o montado en su mula. Hombres y mu\u00adjeres que pasan al mercado y charlan animadamente para alejar la mo\u00adnoton\u00eda del camino.<\/p>\n<p>Al divisar a algunos hombres de rasgos menos toscos que los de un simple campesino la pastora se aparta de su peque\u00f1o reba\u00f1o y se acer\u00adca decidida y respetuosa al caminante. Sostiene en sus manos un li\u00adbro, y lo muestra al viajero, abierto por una de sus p\u00e1ginas: \u00abSe\u00f1or, \u00bfquisierais decirme c\u00f3mo se lee esta palabra?\u00bb Y satisfecha de la res\u00adpuesta, dando las gracias con una alegre sonrisa, la joven pastora se aparta del camino y regresa junto a su reba\u00f1o, fijos los ojos en el libro de lectura, queriendo desentra\u00f1ar, con toda constancia, los signos que all\u00ed hay escritos.<\/p>\n<p>La misma escena se repite varias veces en la tarde apacible, hasta que el sol, al despedirse, besa las cumbres de los montes cercanos. Ano\u00adchece. La joven pastora gu\u00eda con diligencia sus reba\u00f1os hasta la aldea.<\/p>\n<p>\u00bfQu\u00e9 significa esta actitud, repetida d\u00eda tras d\u00eda en las praderas cer\u00adcanas al peque\u00f1o poblado? La raz\u00f3n puede d\u00e1rnosla la misma joven que contemplamos, si seguimos su jornada de trabajo.<\/p>\n<p>Ha entregado el ganado a sus due\u00f1os, y ha ido a cobijarse en su peque\u00f1o albergue. El hogar, completamente apagado. Pobres viandas para la comida de aquella joven, que, no obstante, muestra una sonrisa amable siempre. Poco a poco se re\u00fanen en torno a ella otras jovencitas; algunos ni\u00f1os, que quedan rezagados en el grupo, oyen las lecturas que hace la improvisada maestra para ense\u00f1ar a las dem\u00e1s.<\/p>\n<p>Este sencillo cuadro puede reconstruirse todas las noches. Otras ve\u00adces la joven abandona Suresnes para dirigirse al vecino poblado de Villepreux, donde hace lo mismo con las j\u00f3venes que en \u00e9l viven. Cabe pensar si se trata de una maestra rural que quiere instruir a sus veci\u00adnas y compa\u00f1eras, gan\u00e1ndose as\u00ed el sustento. No es \u00e9se el motivo. La joven pastora ha sentido interiormente una extrema caridad hacia la ignorancia de sus hermanos y quiere combatirla con los medios que tiene a su alcance. Pobres medios de una pastora de aldea, que se har\u00e1n po\u00adderosos en un coraz\u00f3n de mujer que ha lanzado la mirada a su alrededor para buscar a su pr\u00f3jimo. La pastora de Suresnes busca la redenci\u00f3n del alma de sus hermanos y quiere combatir la ignorancia, no por un mo\u00adtivo natural, sino para que las aldeanas puedan instruirse conveniente\u00admente en el catecismo y amar con m\u00e1s solidez a su Dios.<\/p>\n<p>Este proceder no pod\u00eda por menos de acarrearle la admiraci\u00f3n de algunos y la cr\u00edtica de muchos. Una muchacha que en la juventud se traslada de aldea en aldea, con el fin, desconocido hasta entonces, de ense\u00f1ar gratuitamente las letras, y a la vez instruir en el catecismo a las j\u00f3venes y a los ni\u00f1os, puede ser una santa o una ilusa. Y como quie\u00adra que la opini\u00f3n popular es siempre dada a buscar lo menos favorable, Margarita Naseau, que \u00e9ste es el nombre de la pastora, siente que la garra de la calumnia viene a hacer presa en su persona.<\/p>\n<p>No obstante, dotada de un coraz\u00f3n magn\u00e1nimo, atra\u00edda irresistible\u00admente por una vocaci\u00f3n especial que la llama a ayudar al pr\u00f3jimo, deja pasar la nube tormentosa que pod\u00eda anegar las ilusiones de su esp\u00edritu y sigue infatigable la senda que se ha trazado.<\/p>\n<p>Su alimentaci\u00f3n, sobria y escasa, consiste la mayor\u00eda de las noches en un pedazo de pan. Lo dem\u00e1s lo ha dado como limosna a los pobres. Le basta un duro jerg\u00f3n para el lecho y un sencillo vestido para pre\u00adservarse del fr\u00edo. Su coraz\u00f3n late cada vez m\u00e1s apresuradamente al rit\u00admo de la caridad.<\/p>\n<p>Vicente de Pa\u00fal va a predicar una misi\u00f3n a los alrededores de Su\u00adresnes. Margarita Naseau, alma vibrante, va a consultar al santo sacer\u00addote sus proyectos, sus afanes, lo que constituye la ilusi\u00f3n de su vida: el deseo de instruir a las pobres hijas del campo. Vicente aplaude su proyecto, considera pausadamente los tesoros que Dios ha puesto en esta alma, y la anima a seguir viviendo su hermoso ideal de caridad.<\/p>\n<p>Vicente de Pa\u00fal ha encontrado en Margarita un alma que vibra al un\u00edsono con la suya. Nada detiene el impetuoso r\u00edo de caridad que va de coraz\u00f3n a coraz\u00f3n. Vicente, con su mirada sagaz, conoce perfecta\u00admente a la joven aldeana y espera la respuesta de Dios.<\/p>\n<p>M\u00e1s tarde la joven Margarita, enterada de que las Caridades fun\u00adcionaban en las parroquias de Par\u00eds, se pone a disposici\u00f3n de Vicente de Pa\u00fal, por si puede serle \u00fatil en el servicio de los pobres y de los enfermos. Vicente sonr\u00ede. Experimentado en el trato de las almas, sabe hasta qu\u00e9 punto es heroica la resoluci\u00f3n de Margarita. Precisamente le encanta la entusiasta simplicidad con que brinda toda su vida al ser\u00advicio de los desgraciados.<\/p>\n<p>El rostro de Vicente de Pa\u00fal se ilumina. Providente, siervo de la Pro\u00advidencia, mira el panorama de las Caridades parroquiales y piensa que Margarita puede ser un auxiliar valioso de las damas que visitan a los pobres. La invita a ir a Par\u00eds, la pone bajo la direcci\u00f3n de Luisa de Marillac, y la joven aldeana recorre las calles de la capital visitando los m\u00edseros tugurios de los pobres, no solamente para depositar en ellos el socorro material que hab\u00eda ido a buscar a las casas de las damas, sino haciendo entrar con ella un rayo de consuelo y esperanza.<\/p>\n<p>La estancia del pobre se ilumina con la presencia ang\u00e9lica de Mar\u00adgarita. La diferencia que hay entre las damas y Margarita es que las primeras dan su socorro material y algo de su tiempo y de su afecto; la segunda se ha dado toda, ha dado su vida entera al servicio de los pobres.<\/p>\n<p>A esta joven vienen a unirse en pocos meses otras tres, procedentes de Montdidier y de Beauvais. Todas ellas, aplicadas desde un principio al servicio de las Caridades, reciben de Vicente de Pa\u00fal el sencillo nom\u00adbre de Siervas de los Pobres. Nombre simb\u00f3lico que deb\u00eda entra\u00f1ar una realidad en ellas. Precisamente \u00e9l, el hombre que m\u00e1s ha amado a Cristo en los pobres, quiso que estas j\u00f3venes no llevasen otro t\u00edtulo que el de Siervas, que era el que deb\u00eda convenir a su quehacer coti\u00addianamente caritativo con los menesterosos. No estaban junto a ellos para acompa\u00f1arlos simplemente, sino para ser sus siervas, para plegarse a las menudas exigencias de sus amos y se\u00f1ores.<\/p>\n<p>Humildes comienzos de una peque\u00f1a empresa que iba a ser gigantesca en el correr de los siglos. La alabanza que Vicente de Pa\u00fal prodig\u00f3 a estas primeras hermanas que se dedicaron a servir a los enfermos tiene ecos de eternidad. El santo, parco siempre en palabras, vuelca todo el entusiasmo de su coraz\u00f3n cuando nos habla del proceder heroico de estas j\u00f3venes para con los enfermos, compar\u00e1ndolas a las v\u00edrgenes m\u00e1r\u00adtires que adornaron la Iglesia con la p\u00farpura de su sangre, si bien las her\u00admanas lo hicieron con un martirio lento y costoso en el quehacer de la caridad.<\/p>\n<p>Y, efectivamente, adem\u00e1s del martirio de sangre existe otro menos bri\u00adllante, aunque pleno de hermosura. La abnegada Margarita Naseau, pri\u00admera Hija de la Caridad, iba a padecerlo y a dar su vida en completo holocausto por el servicio de los desgraciados. Compadecida de una po\u00adbre mujer atacada de la peste, la conduce a su propio aposento y la hace acostar en el pobre lecho. \u00bfIgnorancia del mal? No, ciertamente, puesto que en aquella \u00e9poca las epidemias diezmaban las ciudades, causando estragos mortales bien conocidos de todos. Rasgo heroico de caridad, que le vali\u00f3 indudablemente un premio eterno. Atacada ella misma del terrible mal, pidi\u00f3 ser llevada al hospital de San Luis para morir como una de tantas pobres y alcanzar la bienaventuranza que a ellos est\u00e1 prometida.<\/p>\n<p>Hermoso rasgo de un alma que, en su c\u00e1ndida sencillez, hab\u00eda penetra\u00addo los secretos de Dios y sab\u00eda que los latidos del coraz\u00f3n de Cristo se compadecen de los gemidos y de los dolores de los pobres. Margarita Naseau, como primera Hija de la Caridad, cumpli\u00f3 en su persona el mo\u00addelo perfecto que Dios hab\u00eda forjado en su mente divina. Llevada por su caridad, sirvi\u00f3 a los pobres con todo el amor de su coraz\u00f3n virginal que les consagr\u00f3 por completo, pasando alegre y confiada por entre las miserias, alegrando con su sonrisa candorosa los pobres tugurios donde gem\u00eda de dolor.<\/p>\n<p>Esto no era suficiente para su coraz\u00f3n lleno de generosidad, y dio su vida en aras de su ideal. Y para asemejarse m\u00e1s a Cristo pobre, su di\u00advino modelo, quiso morir como los pobres, en el lecho de un hospital; humildemente se abandon\u00f3 a los cuidados de otras manos misericordio\u00adsas, que recogieran su \u00faltimo suspiro de virgen y de m\u00e1rtir de la caridad.<\/p>\n<p>Vicente y Luisa guardaron siempre un recuerdo cari\u00f1oso de esta hija privilegiada que el cielo les hab\u00eda dado. Su figura luminosa, recor\u00adtada de entre las verdes campi\u00f1as para internarse en los m\u00edseros tugu\u00adrios de Par\u00eds; su gesto sonriente, su profunda piedad, todo era para los Santos Fundadores un recuerdo grato. Vicente sol\u00eda decir de Margarita Nassau: \u00abTodo el mundo la amaba, porque todo en ella era amable.\u00bb Y uno de los primeros bi\u00f3grafos de Santa Luisa, al esbozar la figura en\u00adcantadora de la pastora de Suresnes, hab\u00eda dicho:<\/p>\n<p>\u00abDios, que ha puesto la encina entera en el germen de la bellota, hab\u00eda puesto ya a la Hija de la Caridad entera en esta obrera de los primeros tiempos de la Compa\u00f1\u00eda.\u00bb<\/p>\n<p>\u00bfQu\u00e9 acci\u00f3n cupo a Santa Luisa en torno a esta primera promoci\u00f3n de hermanas que ven\u00edan a ser las auxiliares de las Damas de la Caridad? Hay que pensar en que San Vicente, una vez que las hubo admitido como tales, viendo la sencilla y recta voluntad de estas j\u00f3venes, las puso bajo la custodia de la se\u00f1orita, que las form\u00f3 en sus nuevas obli\u00adgaciones. Recordemos que, en un principio, estas j\u00f3venes proven\u00edan de las aldeas y estaban poco acostumbradas a la vida de Par\u00eds, carentes casi por completo de trato social, aunque llenas de buena voluntad. No se les ocultaba a los Santos Fundadores que esto encerraba un peligro para las almas j\u00f3venes, que, lanzadas a la calle con su cesto bien abastecido de provisiones y con sus remedios medicinales, deb\u00edan tener una gran forta\u00adleza para imponerse en sus nuevas tareas y sobrellevar el servicio de los pobres con toda perfecci\u00f3n.<\/p>\n<p>A cargo de Vicente de Pa\u00fal estaba la formaci\u00f3n espiritual y sobre\u00adnatural de estas sencillas hijas del campo. Algo m\u00e1s tarde se les unieron j\u00f3venes de las ciudades, principalmente de Par\u00eds, que proven\u00edan de la clase burguesa y de la buena sociedad.<\/p>\n<p>Todas vinieron siguiendo las huellas de Margarita Naseau, pero no todas ten\u00edan sus bellas disposiciones para el trabajo que se les propo\u00adn\u00eda. Tarea urgente de Luisa era adiestrar a estas Siervas de los Po\u00adbres en los mil modos de preparar el servicio de los enfermos, de hacerles todo cuanto necesitaran, de presentarse en casa de las damas a recoger la pesada marmita donde llevaban los alimentos, y en disponer el esp\u00edritu prontamente al mayor desprendimiento de todas las cosas, como lo exig\u00eda su nuevo g\u00e9nero de vida.<\/p>\n<p>As\u00ed naci\u00f3 humildemente, sencillamente, la Compa\u00f1\u00eda de las Hijas de la Caridad en 29 de noviembre de 1633. La fundaci\u00f3n de esta Compa\u00f1\u00eda, que de peque\u00f1o grano de mostaza iba a transformarse en \u00e1rbol frondo\u00ads\u00edsimo que cobijar\u00eda bajo sus ramas todas las obras de misericordia, no fue preconcebida en el \u00e1nimo de Vicente de Pa\u00fal y de Luisa de Marillac.<\/p>\n<p>\u00abVed, Hermanas\u2014dec\u00eda Vicente a\u00f1os m\u00e1s tarde de la fun\u00addaci\u00f3n\u2014, c\u00f3mo hemos llegado hasta aqu\u00ed. Una pobre joven, Mar\u00adgarita Naseau, se present\u00f3 a la se\u00f1orita Legras, que le pregunt\u00f3 lo que sab\u00eda, de d\u00f3nde ven\u00eda y si quer\u00eda servir a los pobres. Acep\u00adt\u00f3 voluntariamente. Vino, pues,. a la parroquia de San Salva\u00addor, se le ense\u00f1\u00f3 a dar los remedios y a prestar todos los ser\u00advicios necesarios, y ella lo cumpli\u00f3 todo a maravilla. Nadie ha\u00adb\u00eda pensado en esto. As\u00ed es corno comienzan las obras de Dios. Se hacen sin que previamente se haya pensado en ellas; he aqu\u00ed, mis queridas hermanas, c\u00f3mo Dios ha hecho esta obra. La se\u00f1o\u00adrita no hab\u00eda pensado en ello, yo tampoco, y mucho menos esta pobre muchacha. Por tanto, es una regla dada por San Agust\u00edn la de que, cuando no se ve el autor de una obra, es Dios mismo el que la ha hecho.\u00bb<\/p>\n<p>Alguien podr\u00eda objetar ciertos reparos a estos comienzos humildes, dado que algunos fundadores de \u00d3rdenes religiosas batallan incansable\u00admente para establecerlas en la Iglesia de Dios y apenas pueden conse\u00adguir sus intentos. Es un poco desconcertante, para los que no conocen a fondo el esp\u00edritu vicenciano, que es el mismo que el de su santa cola\u00adboradora, la prudente espera de acontecimientos que Vicente de Pa\u00fal tuvo en todas las grandes obras que emprendi\u00f3.<\/p>\n<p>Hermoso ejemplo de un verdadero siervo del Se\u00f1or, que no quiso nunca anticiparse a la divina voluntad y aguard\u00f3 de ella las se\u00f1ales inequ\u00edvocas por las cuales se manifiesta.<\/p>\n<p>Este esp\u00edritu, aut\u00e9ntico esp\u00edritu de fe, a salvo de todas las defec\u00adciones, era el mismo de Luisa. Acogidas aquellas j\u00f3venes bajo la tutela espiritual de ambos, ella, con viril coraz\u00f3n, dio a la obra divina un em\u00adpuje poderoso; pero nunca entr\u00f3 en sus c\u00e1lculos el hacer una gran cosa. Deja obrar a la Providencia, pero, sinti\u00e9ndose enviada por ella, tra\u00adbaja con gran amor en la peque\u00f1a porci\u00f3n de Cristo.<\/p>\n<p>\u00abLas j\u00f3venes que la ayudaban en las Cofrad\u00edas de la Cari\u00addad\u2014dec\u00eda el cardenal Pacelli\u2014, a pesar de sus turbaciones de esp\u00edritu, le hac\u00edan entrever una visi\u00f3n m\u00e1s bella. Como un astro rasga las nubes y deshace las tinieblas, as\u00ed eran a sus ojos, y a los de Vicente de Pa\u00fal, estas j\u00f3venes, un cortejo de \u00e1ngeles que iban y ven\u00edan subiendo y bajando a los cuchitriles y a los refugios de la miseria, como en la escala que Jacob vio elevarse al cielo durante la noche que pas\u00f3 en Bethel. Estos \u00e1ngeles ten\u00edan aspecto de hijas del pueblo, no descend\u00edan del cielo, ven\u00edan de los campos donde crecen el lirio de los valles y las rosas de Jeric\u00f3; sal\u00edan, en la ciudad, de las casas de la burgues\u00eda y de los palacios de la nobleza.\u00bb<\/p>\n<p>Una de las coronas m\u00e1s bellas que circundar\u00e1n a Santa Luisa en el cielo ha de ser lo que su esp\u00edritu trabaj\u00f3 en la formaci\u00f3n de estas sen\u00adcillas j\u00f3venes, hasta convertirlas en dechado perfecto de siervas del Se\u00f1or.<\/p>\n<p>En aquellos siglos alguien pudo tachar de osados a los santos fun\u00addadores, que, instalando su peque\u00f1a familia religiosa en el barrio de San V\u00edctor, lanzaban a la calle a unas j\u00f3venes que, en fuerza de su misi\u00f3n, deb\u00edan estar dotadas de una gran formaci\u00f3n sobrenatural, ha\u00adbida cuenta de que lo que se deseaba de ellas no era solamente una prestaci\u00f3n caritativa, sino su donaci\u00f3n en holocausto al Dios de ca\u00adridad.<\/p>\n<p>Por eso Vicente no se recataba de inculcarles un gran &#8216;respeto a las religiosas; pero, sin embargo, les impon\u00eda una regla formidable en estas palabras:<\/p>\n<p>\u00abSi las religiosas, para ser perfectas, necesitan un grado de virtud, vosotras, hijas m\u00edas, necesit\u00e1is dos para vivir en el ser\u00advicio de los pobres.\u00bb<\/p>\n<p>\u00bf Secundaron las primeras hermanas el celo ardiente de los santos fundadores? No puede dudarse, en cuanto que sus obras son el testimo\u00adnio m\u00e1s elocuente de aquellos primeros tiempos de caridad. Pero es preciso dejar bien sentado que aquellas j\u00f3venes no ven\u00edan a la Caridad como simples empleadas o subordinadas de las se\u00f1oras, abandonando la vida de los campos para instalarse en Par\u00eds, cambiando el aspecto risue\u00f1o de sus hogares por las l\u00f3bregas estancias de los pobres. No eran asala\u00adriadas que buscaran la sonrisa pr\u00f3diga de los grandes, ni siquiera el agradecimiento de los humildes. Fueron sencillamente, \u00edntegramente, al\u00admas dadas a Dios, que \u00c9l mismo suscit\u00f3 de donde le plugo, para enri\u00adquecer a su Iglesia con una nueva porci\u00f3n escogida.<\/p>\n<p>Es indudable que algunas llegaron con toda su rudeza a la Caridad; pero una nueva gloria de Luisa fue transformar esas toscas maneras en los sencillos ademanes que encantaban a los que las ve\u00edan ir y venir en\u00adtregadas por completo a sus caritativas empresas. Precisamente el servir\u00adse de ellas fue la se\u00f1al que esperaban los santos fundadores en el mo\u00admento en que las Caridades empezaban a decaer en manos de las Damas.<\/p>\n<p>El coraz\u00f3n de aquellas primeras Hijas de la Caridad, forjado en el de Santa Luisa, no pod\u00eda ser sino aut\u00e9ntico relicario de un santo amor ha\u00adcia los pobres. Un buen d\u00eda la sobrina del cardenal Richelieu, futura duquesa de Aiguillon, llena de admiraci\u00f3n por estas Siervas de los Po\u00adbres, solicit\u00f3 de Vicente de Pa\u00fal el favor de instalar a una de ellas en su palacio del Peque\u00f1o Luxemburgo, situado cerca de la iglesia de San Sulpicio. Quer\u00eda emplearla, no solamente en su servicio, sino en el de los pobres de su parroquia, que ella visitaba en calidad de Dama.<\/p>\n<p>Vicente de Pa\u00fal, pensando que no deb\u00eda excusar esta solicitud, se lo propone a una de las hermanas, invit\u00e1ndola a ir a morar en el palacio de la duquesa. \u00ab\u00a1 Oh Se\u00f1or\u2014contesta la hermana\u2014, si yo he dejado a mis padres ha sido para darme por completo al servicio de los pobres, por el amor de Dios solamente. Ruego a vuestra caridad que me perdo\u00adne, pero yo no puedo cambiar mi ideal para ir a servir a una gran dama.\u00bb<\/p>\n<p>Vicente de Pa\u00fal llama a otra segunda, sor B\u00e1rbara Angiboust. La en\u00adv\u00eda sin ninguna explicaci\u00f3n al palacio de la sobrina de Richelieu; \u00e9l mismo la ir\u00e1 a buscar cuando deba regresar a la Caridad. Llega y en\u00adcuentra a B\u00e1rbara un poco inquieta, mas le dice que debe quedar all\u00ed, al servicio de aquella gran dama, y, bajo su protecci\u00f3n, al servicio de los pobres de la barriada. B\u00e1rbara llora, pero cree mejor obedecer sin razonar. A los pocos d\u00edas se presenta de nuevo ante Vicente, y le dice que se encuentra totalmente desalentada en aquel palacio, en aquella gran corte donde no sabe vivir; suplica a Vicente que la retire de all\u00ed: \u00abNuestro Se\u00f1or me ha dado a los pobres; por tanto, le ruego que me env\u00ede directamente a su servicio para siempre\u00bb. El abad de Loiacq, que hab\u00eda presenciado esta escena, reconoci\u00f3 en esta sencilla joven un gran desprecio de las riquezas del mundo.<\/p>\n<p>Estos bellos rasgos apenas extra\u00f1aban a Vicente; conoc\u00eda demasiado la formaci\u00f3n que recib\u00edan por parte de la se\u00f1orita Legras, y su cora\u00adz\u00f3n, en lugar de ensombrecerse, se regocijaba en Dios ante tales testi\u00admonios de la m\u00e1s pura caridad.<\/p>\n<p>Estos humildes comienzos, que iban a ser el germen de una gran expansi\u00f3n, deben su esp\u00edritu conjuntamente a las almas de Vicente y Luisa, que vibran al un\u00edsono en este concierto de la caridad. Desde 1633 Luisa no vive m\u00e1s que para las Hijas de la Caridad. A ellas van dirigidos todos sus avisos, sus pensamientos, sus palabras, y todo cuanto ella se propone en su acci\u00f3n apost\u00f3lica y en la organizaci\u00f3n de las obras. Ellas no lo han olvidado y han guardado fielmente, celosamente, esas tradiciones maternas como un tesoro de familia.<\/p>\n<p>\u00abLas hero\u00ednas de los siglos precedentes\u2014dice el cardenal Pacelli en su paneg\u00edrico\u2014no hab\u00edan tenido la menor idea de lo que hab\u00eda sido santificarse en las obras de caridad. Luisa de Marillac no dice a las v\u00edrgenes claustradas: \u00abSalid de vuestro re\u00adtiro, id por esos caminos, subid a la morada de los indigentes y de los abandonados, entrad a las salas de los hospitales&#8230;\u00bb, pero indica a las j\u00f3venes hermanas y a las se\u00f1oritas de la villa la ruta que ella hab\u00eda inaugurado hacia un claustro abierto a los cuatro costados, teniendo ventanas que miran al mundo, pero tan fuertemente amurallada contra las tempestades a pesar de la carencia de rejas, que el coraz\u00f3n y la virtud deb\u00edan ser all\u00ed m\u00e1s fuertes que una torre. Luisa de Marillac, ampliando el c\u00f3\u00addigo de la vida religiosa en el inundo, lleva consigo una gran victoria, y avanza, como un rayo de sol, a trav\u00e9s del fango y la miseria humanas y reparte a los ojos de los hombres su mara\u00advillosa luz, a fin de que ellos vean sus buenas obras y glorifi\u00adquen al Padre, que est\u00e1 en los cielos.\u00bb<\/p>\n<p>Su hermosa vida es fecunda en todos los estados por que atraviesa. Madre, viuda, fundadora, educadora, enfermera a domicilio en una \u00e9po\u00adca en que esta hermosa pr\u00e1ctica caritativa era desconocida, Dama de la Caridad que no se desde\u00f1a en asemejar su vida a la de las j\u00f3venes Siervas de los Pobres, mujer de acci\u00f3n que lleva dentro de s\u00ed las her\u00admosas virtudes de un alma consagrada, Luisa de Marillac, figura de gran relieve en todos los tiempos, lo es mucho m\u00e1s en los nuestros, en los que llega a mayor altura el apostolado de los laicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SED fervorosos de esp\u00edritu, acord\u00e1ndoos de que es al Se\u00f1or a quien serv\u00eds. Alegraos con la esperanza del premio. (Ep. a los romanos, XII.) EN la campi\u00f1a que rodea la humilde villa de Suresnes se &#8230; <a href=\"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":140652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[130,152,140,135],"class_list":["post-130270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luisa-de-marillac","tag-beauvais","tag-duquesa-de-aiguillon","tag-san-sulpicio","tag-villepreux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un perfil heroico: santa Luisa de Marillac (11) - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un perfil heroico: santa Luisa de Marillac (11) - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"SED fervorosos de esp\u00edritu, acord\u00e1ndoos de que es al Se\u00f1or a quien serv\u00eds. Alegraos con la esperanza del premio. (Ep. a los romanos, XII.) EN la campi\u00f1a que rodea la humilde villa de Suresnes se ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-05T07:55:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-26T15:27:21+00:00\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Un perfil heroico: santa Luisa de Marillac (11)\",\"datePublished\":\"2015-03-05T07:55:55+00:00\",\"dateModified\":\"2016-07-26T15:27:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/\"},\"wordCount\":3920,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Beauvais\",\"Duquesa de Aiguillon\",\"San Sulpicio\",\"Villepreux\"],\"articleSection\":[\"Luisa de Marillac\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/\",\"name\":\"Un perfil heroico: santa Luisa de Marillac (11) - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-03-05T07:55:55+00:00\",\"dateModified\":\"2016-07-26T15:27:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/un-perfil-heroico-santa-luisa-de-marillac-11\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un perfil heroico: santa Luisa de Marillac (11)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un perfil heroico: santa Luisa de Marillac (11) - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/","og_locale":"es_ES","og_type":"article","og_title":"Un perfil heroico: santa Luisa de Marillac (11) - Somos Vicencianos","og_description":"SED fervorosos de esp\u00edritu, acord\u00e1ndoos de que es al Se\u00f1or a quien serv\u00eds. Alegraos con la esperanza del premio. (Ep. a los romanos, XII.) EN la campi\u00f1a que rodea la humilde villa de Suresnes se ... Read More","og_url":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2015-03-05T07:55:55+00:00","article_modified_time":"2016-07-26T15:27:21+00:00","author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/#article","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Un perfil heroico: santa Luisa de Marillac (11)","datePublished":"2015-03-05T07:55:55+00:00","dateModified":"2016-07-26T15:27:21+00:00","mainEntityOfPage":{"@id":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/"},"wordCount":3920,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/#primaryimage"},"thumbnailUrl":"","keywords":["Beauvais","Duquesa de Aiguillon","San Sulpicio","Villepreux"],"articleSection":["Luisa de Marillac"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/","url":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/","name":"Un perfil heroico: santa Luisa de Marillac (11) - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/#primaryimage"},"image":{"@id":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-03-05T07:55:55+00:00","dateModified":"2016-07-26T15:27:21+00:00","breadcrumb":{"@id":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-11\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Un perfil heroico: santa Luisa de Marillac (11)"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-xT8","jetpack-related-posts":[{"id":130257,"url":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-05\/","url_meta":{"origin":130270,"position":0},"title":"Un perfil heroico: santa Luisa de Marillac (05)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/02\/2015","format":false,"excerpt":"PARA que sepas d\u00f3nde est\u00e1 la vida y la luz de tus ojos, y la paz. (Baruc, III.) \"...se me asegur\u00f3 que deb\u00eda reposar en la idea de que Dios me dar\u00eda un director que me hiciera ver clara la situaci\u00f3n de mi alma; sin embargo, me parec\u00eda que este\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"OLYMPUS DIGITAL CAMERA","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/04\/louise-marillac-300x248.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":124199,"url":"http:\/\/vincentians.com\/es\/vicente-de-paul-espiritu-y-formacion\/","url_meta":{"origin":130270,"position":1},"title":"Vicente de Pa\u00fal: Esp\u00edritu y formaci\u00f3n","author":"Francisco Javier Fern\u00e1ndez Chento","date":"09\/03\/2023","format":false,"excerpt":"De todos los carismas del P. Vicente, el m\u00e1s importante era su capacidad de promover el crecimiento espiritual de los dem\u00e1s, de dirigirles y de aconsejarles usando su gran capacidad de escuchar atentamente. Adquiri\u00f3 la destreza en la direcci\u00f3n de esp\u00edritus por experiencia de su propia direcci\u00f3n, con gu\u00edas tales\u2026","rel":"","context":"En \u00abVicente de Pa\u00fal\u00bb","block_context":{"text":"Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/hijas-caridaqd.jpg?fit=1200%2C675&resize=1050%2C600 3x"},"classes":[]},{"id":130253,"url":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-03\/","url_meta":{"origin":130270,"position":2},"title":"Un perfil heroico: santa Luisa de Marillac (03)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"25\/02\/2015","format":false,"excerpt":"CONTIGO ha hablado mi coraz\u00f3n; en busca de Ti han andado mis ojos. \u00a1Oh. Se\u00f1or, Tu rostro es lo que yo deseo contemplar! (Salmo 26, 8.) HAY almas que, determinadas a seguir la voz de la gracia divina que se insin\u00faa en su coraz\u00f3n, van directamente, sin titubeos, ha\u00adcia el\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"OLYMPUS DIGITAL CAMERA","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/04\/louise-marillac-300x248.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":130259,"url":"http:\/\/vincentians.com\/es\/un-perfil-heroico-santa-luisa-de-marillac-06\/","url_meta":{"origin":130270,"position":3},"title":"Un perfil heroico: santa Luisa de Marillac (06)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"28\/02\/2015","format":false,"excerpt":"ESOS que est\u00e1n cubiertos de blancas vestiduras, \u00bfqui\u00e9nes son y de d\u00f3nde han venido? (Apocalipsis, VII.) VICENTE de Pa\u00fal ha sido uno de los mayores dones que la ca\u00adridad y la misericordiosa de Dios han concedido al mundo. Su santidad personal es tan atrayente, tan humana, tan digna de imitaci\u00f3n\u2026","rel":"","context":"En \u00abLuisa de Marillac\u00bb","block_context":{"text":"Luisa de Marillac","link":"http:\/\/vincentians.com\/es\/category\/la-familia-vicenciana\/fundadores\/luisa-de-marillac\/"},"img":{"alt_text":"OLYMPUS DIGITAL CAMERA","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2014\/04\/louise-marillac-300x248.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":129357,"url":"http:\/\/vincentians.com\/es\/vicente-de-paul-carta-1222luisa-de-marillac-a-san-vicente\/","url_meta":{"origin":130270,"position":4},"title":"Vicente de Pa\u00fal, Carta 1222: Luisa De Marillac A San Vicente","author":"Francisco Javier Fern\u00e1ndez Chento","date":"05\/02\/2014","format":false,"excerpt":"20 diciembre [1649] Padre: Me han asegurado que el cargo pertenece a los que disponen de \u00e9l y que nadie puede adquirirlo sin consentimiento suyo. Nuestro asunto sigue adelante. Vi a la persona de lo que le habl\u00e9 ayer muy tranquilizada, y ha hecho esta ma\u00f1ana lo que ten\u00eda que\u2026","rel":"","context":"En \u00abEscritos de Vicente de Pa\u00fal\u00bb","block_context":{"text":"Escritos de Vicente de Pa\u00fal","link":"http:\/\/vincentians.com\/es\/category\/escritos\/escritos-de-vicente-de-paul\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/escritos-vicente-de-paul.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":119624,"url":"http:\/\/vincentians.com\/es\/mirada-de-fe-del-itinerario-espiritual-de-luisa-de-marillac\/","url_meta":{"origin":130270,"position":5},"title":"Mirada de fe del itinerario espiritual de Luisa de Marillac","author":"Francisco Javier Fern\u00e1ndez Chento","date":"12\/04\/2013","format":false,"excerpt":"Introducci\u00f3n La mirada de fe es un hecho humano fundamental que nos orienta hacia Dios y nos invita a vivir de su Esp\u00edritu. La presencia de los Santos es un recuerdo continuo de las cosas del cielo. La Iglesia nos ense\u00f1a que los santos son inseparables de la plenitud de\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"Luisa de Marillac","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/2011\/02\/luisa_marillac-181x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/130270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=130270"}],"version-history":[{"count":0,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/130270\/revisions"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=130270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=130270"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=130270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}