{"id":109333,"date":"2022-11-27T11:55:34","date_gmt":"2022-11-27T10:55:34","guid":{"rendered":"http:\/\/somos.vicencianos.org\/?p=109333"},"modified":"2022-11-27T11:53:56","modified_gmt":"2022-11-27T10:53:56","slug":"mision-historica-de-la-milagrosa","status":"publish","type":"post","link":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/","title":{"rendered":"Misi\u00f3n hist\u00f3rica de La Milagrosa"},"content":{"rendered":"<p>Amadas Hermanas, se\u00f1ores y amados sacerdotes:<\/p>\n<p>El t\u00edtulo de la conferencia quiz\u00e1 pueda parecer a algunos ex\u00adcesivamente ambicioso: LA MISION HISTORICA DE LA MILA\u00adGROSA. En realidad a m\u00ed tambi\u00e9n me lo parece, sobre todo una vez que lo vi estampado en letras de molde; porque mi prop\u00f3sito es muy sencillo. Se trata de preguntarnos, a estas alturas de 1973, a los ciento cuarenta y tres a\u00f1os de las apariciones de la Virgen a Santa Catalina, por el papel hist\u00f3rico que ha desempe\u00f1ado la Milagrosa, en su triple proyecci\u00f3n: apariciones, medalla, mensaje, el papel hist\u00f3rico que ha representado en la vida de la Iglesia; qu\u00e9 funci\u00f3n ha cumplido; qu\u00e9 ha significado como realidad ac\u00adtuante y presente en la Iglesia; qu\u00e9 obras, qu\u00e9 transformaciones se le deben. Un breve haz de preguntas, f\u00e1cilmente ampliable, a las que quisiera contestar hoy de manera medianamente al me\u00adnos satisfactoria.<\/p>\n<p>Busquemos un punto de partida que sea a la vez firme y s\u00f3\u00adlido. Y \u00e9ste no es otro que el hecho de las apariciones, el hecho hist\u00f3rico de las apariciones.<\/p>\n<p>Ni me voy a meter en cr\u00edtica hist\u00f3rica, ni voy a hacer tam\u00adpoco mucho menos\u2014 an\u00e1lisis del car\u00e1cter teol\u00f3gico-espiritual de las apariciones. Voy simplemente a afirmarme en ese suelo, para arrancar de ah\u00ed.<\/p>\n<p>El hecho de las apariciones est\u00e1 atestiguado y a m\u00ed, para los prop\u00f3sitos de esta conferencia, me basta con ello por un proceso can\u00f3nico realizado en 1836, con las m\u00e1ximas garant\u00edas de objetividad y de seriedad, en diecinueve sesiones\u201e haciendo compa\u00adrecer pr\u00e1cticamente a todos los testigos que se hab\u00edan relacionado con las apariciones, excepto a la propia vidente, cosa t\u00edpica de las apariciones de la Milagrosa: yo creo que es la \u00fanica aparici\u00f3n apro\u00adbada por la Iglesia, en la que la vidente no comparece a dar su testimonio, y en una \u00e9poca y en un pa\u00eds en el que son rechazadas otras muchas pretendidas apariciones. Y la encuesta de este pro\u00adceso can\u00f3nico conclu\u00eda: \u00abQue parece evidente que la visi\u00f3n no es obra de una imaginaci\u00f3n loca y desarreglada, o extravagante y exaltada; que todo es real; que nada es fant\u00e1stico, y que todo, en este acontecimiento sobrenatural, parece merecer confianza\u00bb.<\/p>\n<p>A esta conclusi\u00f3n, tan ponderada, de la encuesta can\u00f3nica, ha\u00adcen comentario y en este caso comentario luminoso\u2014 m\u00e1s de setenta documentos de la Santa Sede, que hacen referencia di\u00adrecta o indirecta a las apariciones: veintis\u00e9is Breves, veinte Res\u00adcriptos, catorce Decretos, seis Indultos, innumerables alocuciones y discursos de los Papas. Entre ellos quiero destacar el Decreto del 23 de julio de 1894, por el que se autoriza la celebraci\u00f3n de la Solemnidad de la Manifestaci\u00f3n de la Inmaculada Virgen Mar\u00eda de la Sagrada Medalla. Lo quiero destacar, porque es curioso que en la petici\u00f3n de esta fiesta no se hab\u00eda nombrado para nada a las apariciones: se hab\u00eda solicitado simplemente una fiesta de la Inma\u00adculada el d\u00eda 27 de noviembre. Y es la Santa Seda la que, al con\u00adceder la fiesta, quiere que se titule: \u00abSolemnidad de la Manifes\u00adtaci\u00f3n de la Inmaculada Virgen de la Medalla Milagrosa\u00bb, ha\u00adciendo ella alusi\u00f3n a las apariciones.<\/p>\n<p>Pero quiz\u00e1 m\u00e1s importantes que los documentos son los hechos. Son nueve Papas, innumerables obispos\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 porque ser\u00eda in\u00fatil ponerse a contarlos, los que han puesto en la Medalla la misma fe y la misma confianza que cualquier enfermo de un hospital perdido o cualquier ni\u00f1a de la Asociaci\u00f3n de Hijas de Mar\u00eda.<\/p>\n<p>Y los santos, los santos de nuestro tiempo, pr\u00e1cticamente to\u00addos los santos canonizados que han vivido despu\u00e9s de las apari\u00adciones, que han obtenido la medalla, o la han repetido, o se han consagrado a la Virgen bajo la advocaci\u00f3n de Milagrosa, o ante la imagen de la Milagrosa, que la han declarado protectora de sus parroquias, de sus congregaciones religiosas, de las almas confia\u00addas a ellos, de sus di\u00f3cesis; que le han levantado altares, iglesias, im\u00e1genes&#8230; Ser\u00eda muy largo contar todos los santos que han ac\u00adtuado. Quisiera escoger simplemente algunos.<\/p>\n<p>Ustedes recordar\u00e1n, por ejemplo, a San Juan Mar\u00eda Vianney, el cura p\u00e1rroco de Ars, que es el que encarga la primera imagen de la Milagrosa que se conoce, y la coloca en su iglesia, y que hace grabar en el reverso de las puertas del sagrario de su iglesia el reverso de la Medalla Milagrosa, y que es un repartidor infa\u00adtigable tle medallas&#8230;<\/p>\n<p>La Madre Sacramento, Santa Mar\u00eda Micaela del Sant\u00edsimo Sa\u00adcramento, la Vizcondesa de Jorbal\u00e1n, fundadora de las Adoratri\u00adces, que visita, a los pocos a\u00f1os, a los poqu\u00edsimos a\u00f1os de las apariciones, la capilla de las apariciones, y que vuelve de Par\u00eds con una maleta llena de medallas, que pinta ella un cuadro de la imagen de la Milagrosa, que traduce la primera traducci\u00f3n o la segunda, porque es dudoso cu\u00e1l de las dos aparece primero, pero, en fin, es una de las primeras traductoras del libro que da noticia de la Medalla Milagrosa, y que durante el mes de mayo lee, en este libro traducido por ella, cada d\u00eda una p\u00e1gina de la historia o de los favores de la Milagrosa&#8230;<\/p>\n<p>San Juan Bosco, que reparte las medallas, que cuenta a sus chicos por la noche las historias de las apariciones&#8230;<\/p>\n<p>Y, el \u00faltimo, Maximiliano Kolbe, reci\u00e9n canonizado, que ha pasado a la historia por el rasgo \u00faltimo de su vida, ese rasgo he\u00adroico de ofrecerse en el campo de concentraci\u00f3n de Auschwitz para ser ejecutado en lugar de un padre de familia, y que ha sido glorificado por ello. Pero una muerte as\u00ed no se improvisa: una muerte as\u00ed es el fruto de una vida de santidad. Y Maximiliano Kolbe ahora destaca por su muerte. A medida que se vaya pene\u00adtrando tambi\u00e9n en su vida y en su mensaje, destacar\u00e1, sobre todo, por su obra de fundador de la Milicia de la Virgen Mar\u00eda, las milicias de Mar\u00eda, que dice textualmente, en el proyecto de fundaci\u00f3n, que se pone bajo el patrocinio de la Inmaculada Virgen Mar\u00eda de la Medalla Milagrosa y que obliga a todos los miem\u00adbros de la milicia a llevar la Medalla Milagrosa, y que, con un humor propio de su pa\u00eds y de la \u00e9poca dif\u00edcil, luchadora, en que le toca vivir, dice que la Medalla Milagrosa, las medallas milagrosas son sus cartuchos&#8230;<\/p>\n<p>Y el hecho definitivo: la canonizaci\u00f3n de Santa Catalina.<\/p>\n<p>Todos sabemos que una canonizaci\u00f3n no es una aprobaci\u00f3n de las visiones del santo. Sin embargo, es interesante volver a leer ahora algunos p\u00e1rrafos del decreto de canonizaci\u00f3n. \u00abA esta ve\u00adnerable sierva de Dios, seg\u00fan se dice, se le apareci\u00f3 benign\u00edsima\u00admente la Inmaculada Virgen Mar\u00eda y le confi\u00f3 el encargo de acu\u00ad\u00f1ar una medalla que presentara en el anverso la imagen de la mism\u00e1 Madre de Dios aplastando su virginal pie la cabeza de una serpiente e iluminando el orbe de la tierra con los rayos de sus manos extendidas, teniendo a su derredor las palabras: \u00abOh Ma\u00adr\u00eda sin pecado concebida, rogad por nosotros que recurrimos a Vos\u00bb, y en el reverso, el santo nombre de Mar\u00eda, con el signo de la cruz encima, y debajo dos corazones, el uno coronado de espi\u00adnas y el otro traspasado por una espada. Es admirable a nuestros ojos la propagaci\u00f3n de esta milagrosa medalla\u00bb.<\/p>\n<p>Y el Papa P\u00edo XII, en la homil\u00eda pronunciada en la misa de la canonizaci\u00f3n, repet\u00eda pr\u00e1cticamente, aunque en otros t\u00e9rminos, las palabras del decreto: \u00abEs ciertamente digno de admiraci\u00f3n suma el que la augusta Madre de Dios, seg\u00fan se dice, se dejara ver de una humilde joven, que hablara con ella palabras miste\u00adriosas, y que le manifestara, radiante ante sus ojos, una milagrosa medalla que hab\u00eda de propagar por todos los medios, no sin una abundante efusi\u00f3n de gracias celestiales\u00bb.<\/p>\n<p>Hemos dicho que la Iglesia al canonizar un santo no canoniza sus visiones. Es m\u00e1s: la Iglesia propiamente nunca aprueba una aparici\u00f3n en el sentido de decir que aquello se ha producido. Sim\u00adplemente lo que hace es decir: que no hay nada que pruebe lo contrario, y no hay nada que se oponga a la fe en ello.<\/p>\n<p>Ahora bien, estas palabras del decreto, y estas palabras de P\u00edo XII, aun conservando esa f\u00f3rmula precautoria de la autoridad de la Santa Sede, \u00abseg\u00fan se dice\u00bb, parecen, desde luego, ir m\u00e1s all\u00e1 de una mera no obstaculizaci\u00f3n a la difusi\u00f3n del culto y de la medalla.<\/p>\n<p>Lo cierto es que, a partir de aquella tarde de 1830, aquella tarde en que una Hija de la Caridad, novicia todav\u00eda, desconocida totalmente, ve en la capilla del Seminario interno, ve la imagen de Mar\u00eda, se puso en marcha un movimiento vigoroso que iba a tener unas repercusiones imprevistas e important\u00edsimas.<\/p>\n<p>Esas repercusiones, lo que ha significado, lo que ha hecho la Milagrosa, a partir del momento de sus apariciones, es lo que yo quisiera analizar hoy.<\/p>\n<p>Pero, antes de entrar en este an\u00e1lisis, vamos a hacernos cargo de la situaci\u00f3n hist\u00f3rica en que se producen los hechos.<\/p>\n<p>Ante todo, las fechas.<\/p>\n<p>Sabemos \u2014lo hemos dicho varias veces ya\u2014 que las visiones de Santa Catalina empiezan a producirse en abril de 1830 y se prolongan a lo largo de todo el noviciado de la Santa.<\/p>\n<p>No olvidemos tampoco que la noticia m\u00e1s antigua que se con\u00adserva de las apariciones es un documento escrito en espa\u00f1ol, por una mano desconocida, fechado en Par\u00eds el 5 de agosto de 1833, y descubierto, o redescubierto, en 1934, en el Hospital de Incu\u00adrables de Madrid. Se trata de una carta dirigida probablemente a las Hermanas de aquella casa para informarles de las recientes apariciones y de los primeros milagros atribuidos a la medalla. La carta lleva una posdata, que, \u00e9sa s\u00ed, va firmada por el Padre Lam\u00adboley, que era, junto con el Padre Aladel, confesor de Santa Ca\u00adtalina.<\/p>\n<p>Bien; pues las fechas de las visiones son las primeras visiones referentes ya de una manera m\u00e1s o menos directa a la gran ma\u00adnifestaci\u00f3n de la medalla: 25 de abril al 3 de mayo de 1830, las visiones del coraz\u00f3n de San Vicente durante la novena de la tras\u00adlaci\u00f3n de las reliquias; el 6 de junio, el d\u00eda de la fiesta de la Sant\u00ed\u00adsima Trinidad, durante la misa, en el Evangelio, la visi\u00f3n de Cristo; en la noche del 18 al 19 de julio del mismo a\u00f1o, la visi\u00f3n de la Virgen de la silla, el coloquio y las profec\u00edas; y el 27 de noviembre, el s\u00e1bado anterior al primer domingo de adviento, la visi\u00f3n fundamental que todos conocemos: la Medalla, que se re\u00adpite varias veces \u2014esto est\u00e1 atestiguado tanto en el proceso como en otra serie de documentos\u2014, se repite varias. veces hasta los primeros meses de 1831. A veces se habla de tres apariciones. En realidad son bastantes m\u00e1s de tres; son, al menos, unas siete apa\u00adriciones, en que se repite la aparici\u00f3n y el encargo de acu\u00f1ar la medalla, sin duda para vencer la resistencia sobre todo del con\u00adfesor, que se niega a dar cr\u00e9dito en los primeros instantes a las apariciones.<\/p>\n<p>Bien: \u00bfqu\u00e9 ocurre, qu\u00e9 estaba pasando en el mundo, en la Iglesia, en la familia espiritual de Santa Catalina en esos mo\u00admentos de las apariciones?<\/p>\n<p>\u00bfQu\u00e9 estaba pasando en el mundo?<\/p>\n<p>Se puede decir con dos palabras: se est\u00e1 en plena \u00e9poca revo\u00adlucionaria.<\/p>\n<p>Ha pasado la Gran Revoluci\u00f3n, que ha sido derrotada con Napole\u00f3n en Waterloo, y que ha sido reprimida durante quince a\u00f1os por la Restauraci\u00f3n y la Santa Alianza. Pero est\u00e1 a punto de empezar; m\u00e1s bien, es inminente la segunda oleada revolucio\u00adnaria, que acabar\u00e1 triunfando: la Revoluci\u00f3n de 1830. Acabar\u00e1 triunfando, aunque, hasta cierto punto, habr\u00e1 sido rectificada; en cierta medida habr\u00e1 sido domesticada; desde luego, despojada ya de la virulencia terrorista y antieclesi\u00e1stica de la primera Revolu\u00adci\u00f3n Francesa.<\/p>\n<p>Cuando Santa Catalina tiene las primeras visiones, abril de 1830, reina todav\u00eda en Francia Carlos, el hombre por excelencia de la Restauraci\u00f3n. Carlos X y su nuera,<sup>*<\/sup> la duquesa viuda de Berry, madre del Delf\u00edn, han visitado en la iglesia de los Padres Pa\u00fales, en la iglesia de San L\u00e1zaro, las reliquias de San Vicente, y hab\u00edan sido recibidos con todos los honores por el Superior Ge\u00adneral de la Congregaci\u00f3n de la Misi\u00f3n y de las Hijas de la Caridad.<\/p>\n<p>Poco despu\u00e9s de las primeras visiones la . Restauraci\u00f3n ha te\u00adnido su gran \u00e9xito exterior: la conquista de Argelia \u2014el desem\u00adbarco es el 14 de junio; la toma de Argel es el 5 de julio\u2014, que no le servir\u00e1 para afianzarse, porque se vive un clima prerrevo\u00adlucionario. Ha habido un cambio de Gobierno en Francia; ha entrado a gobernar lo que hoy se llamar\u00eda la facci\u00f3n menos aper\u00adturista, la facci\u00f3n m\u00e1s cerrada, ha provocado las iras populares \u2014sobre todo la publicaci\u00f3n de unas ordenanzas que restringen la libertad de prensa\u2014, y en efecto, el 27, el 28 y el 29 de julio de 1830 se producen lo que se llama las Tres Gloriosas Jornadas, el estallido revolucionario que pone fin al reinado de Carlos X y pro\u00adclama a Luis Felipe de Orle\u00e1ns Rey de Francia el 8 de agosto de este mismo a\u00f1o.<\/p>\n<p>Esta revoluci\u00f3n, que va a tomar un d\u00eda diversos vestidos a lo largo de lo que queda de siglo: Monarqu\u00eda burguesa de Luis Fe\u00adlipe, revoluci\u00f3n de 1848, Segundo Imperio, Comuna, Tercera Re\u00adp\u00fablica&#8230;, es ya irreversible, y va a ser europea. Tres a\u00f1os m\u00e1s tarde se producir\u00e1 en Espa\u00f1a, en 1833, precisamente cuando lle\u00adgaba a Madrid la noticia de las apariciones, con la muerte de Fernando VII. En Suiza, en B\u00e9lgica, los brotes revolucionarios de Italia, con la joven Italia y la joven Europa de Mazzini, en Ale\u00admania, en Polonia&#8230;, pr\u00e1cticamente en todo el mundo.<\/p>\n<p><strong>\u00bfQu\u00e9 les pasa a los cat\u00f3licos?<\/strong><\/p>\n<p>Los cat\u00f3licos, hablando en t\u00e9rminos generales, est\u00e1n amedren\u00adtados. La revoluci\u00f3n significa para ellos el triunfo de la impiedad. No podemos reproch\u00e1rselo, porque ellos carecen de la perspecti\u00adva nuestra: ellos no saben que va a surgir, que est\u00e1 surgiendo un mundo nuevo, y que en ese mundo nuevo la Iglesia y el Cristianismo tendr\u00e1 una nueva primavera y otra manera de estar en el mundo; pero ellos no lo saben. La mayor\u00eda de ellos no tienen otro recuerdo que las sangrientas jornadas del terror, y entonces es l\u00f3gico que est\u00e9n amedrentados. Est\u00e1 amedrentada, por supues\u00adto, Santa Catalina Labour\u00e9. Ella es de familia campesina, donde se conserva todav\u00eda el culto y la veneraci\u00f3n al Rey. Su padre era un realista ferviente, y el sacerdote que la dirigi\u00f3 durante su ado\u00adlescencia en el pueblo era uno de los antiguos sacerdotes no jura\u00admentados en la Revoluci\u00f3n. Esto puede explicar algunos de los aspectos de las visiones, sobre todo de la visi\u00f3n del 18 al 19 de julio, pero precisamente los aspectos m\u00e1s marginales y los menos contrastables. Es curioso que en ning\u00fan documento eclesi\u00e1stico se aluda para nada a la visi\u00f3n del 18 al 19 de julio, ni siquiera en el primer proceso can\u00f3nico. La visi\u00f3n que se toma en cuenta es la del 27 de noviembre.<\/p>\n<p>Ahora bien, ni siquiera en esas visiones, y tampoco, por su\u00adpuesto, de ninguna manera en la medalla, hay nada que vincule el futuro de la devoci\u00f3n ni de la religi\u00f3n al antiguo r\u00e9gimen; y en realidad va a servir m\u00e1s bien para lo contrario, para hacer que los cat\u00f3licos se apoyen en s\u00ed mismos, sin dependencia de la situa\u00adci\u00f3n pol\u00edtica. La Milagrosa, lo vamos a ver, les va a dar fe. Lo que pasa es, como tantas veces, que ellos creen una cosa, y la Providencia prepara otra.<\/p>\n<p>\u00bfY en la Iglesia, qu\u00e9 est\u00e1 sucediendo en la Iglesia en el mo\u00admento de las apariciones de la Milagrosa?<\/p>\n<p>El siglo XIX est\u00e1 ya suficientemente claro para la historia de la Iglesia. Se le puede resumir tambi\u00e9n en dos palabras: destruc\u00adci\u00f3n y reconstrucci\u00f3n.<\/p>\n<p>Destrucci\u00f3n: Se ha producido una descristianizaci\u00f3n; est\u00e1 en marcha un proceso de descristianizaci\u00f3n, que ha sido muy amplio durante los a\u00f1os de la Primera Revoluci\u00f3n, como resultado de la revoluci\u00f3n misma, de sus antecedentes ideol\u00f3gicos, la Ilustraci\u00f3n, del Positivismo, del Racionalismo. Esto es un hecho. En Francia de una manera especial se palpa que se est\u00e1 descristianizando el pueblo, y la Iglesia siente una especie de terror o de miedo al menos de la p\u00e9rdida de tantas almas; y se inicia, o se va a iniciar, una \u00e9poca de reconstrucci\u00f3n, reconstrucci\u00f3n sobre nuevas bases que acabar\u00e1 por ser, en un terreno, la aceptaci\u00f3n de hecho del nuevo orden pol\u00edtico-social, que ser\u00e1 el impulso religioso de uno de los movimientos que constituyen el Romanticismo, el nuevo pensamiento cat\u00f3lico&#8230; Es la \u00e9poca, por no citar m\u00e1s, de New\u00adman en Inglaterra y de Lacordaire en Francia. La expansi\u00f3n mi\u00adsionera, el catolicismo social, que est\u00e1 a la vuelta de la esquina, y que se va a iniciar por un hombre vinculado a la herencia doc\u00adtrinal de San Vicente, por Federico Ozanam, y que culminar\u00e1, ese movimiento de reconstrucci\u00f3n, en la unidad en torno al Papa.<\/p>\n<p>\u00bfY en la doble familia espiritual de la Santa, en la Congrega\u00adci\u00f3n de la Misi\u00f3n y en las Hijas de la Caridad, qu\u00e9 est\u00e1 pasando en estos a\u00f1os?<\/p>\n<p>Tambi\u00e9n aqu\u00ed son a\u00f1os de renacimiento, de reconstrucci\u00f3n, casi dir\u00edamos de nueva creaci\u00f3n. Porque las dos Congregaciones, primeramente en Francia, y sucesivamente en el resto de Europa, han sido pr\u00e1cticamente destruidas. Ha sido una de las primeras medidas de la Revoluci\u00f3n, de la primera Revoluci\u00f3n Francesa: el 18 de agosto de 1792 han sido suprimidas las dos, y despu\u00e9s la tempestad revolucionaria las ha dispersado, o ha causado innu\u00admerables martirios: m\u00e1s de cuarenta sacerdotes de la Congregaci\u00f3n de la Misi\u00f3n, casi otras tantas, aunque menos, Hijas de la Cari\u00addad. Han tenido una precaria restauraci\u00f3n bajo el r\u00e9gimen de Na\u00adpole\u00f3n, tan precaria, que no se ha logrado la unidad de las dos Congregaciones, sino que las dos Congregaciones han atravesado, desde 1800, en que muere el \u00faltimo Superior General elegido antes de la Revoluci\u00f3n, el Padre Cayla de la Garde, hasta 1827, una \u00e9poca en que hay pr\u00e1cticamente dos Superiores generales, dos Vicarios generales: uno en Par\u00eds y otro en Roma. La Congregaci\u00f3n est\u00e1 destruida y deshecha. Es muy poco antes de las apariciones, el 16 de noviembre de 1827, cuando el Papa, todav\u00eda procedi\u00admiento extraordinario, nombra un Superior General de la doble familia, el Padre De Wailly, y es en v\u00edsperas casi de las apariciones, el 18 de mayo de 1829, cuando, por fin, se elige un Superior General, el Padre Salhorgne. Pero en este mismo a\u00f1o, y a los pocos d\u00edas de haber ingresado Santa Catalina en el Seminario in\u00adterno, se produce la Novena de la traslaci\u00f3n de las reliquias de San Vicente. Y la traslaci\u00f3n de las reliquias de San Vicente es un acontecimiento que es como una puesta en marcha de nuevo: ah\u00ed se empieza otra vez, tanto para las Hijas de la Caridad como para la Congregaci\u00f3n de la Misi\u00f3n. En otros pa\u00edses, ya he dicho que suceder\u00e1 quiz\u00e1 un poco m\u00e1s tarde; pero en todos se dar\u00e1 el mismo proceso: de destrucci\u00f3n y de \u00e9poca de reconstrucci\u00f3n.<\/p>\n<p>En ese panorama, por lo tanto, sombr\u00edo, desde luego, para la doble familia de San Vicente, temeroso para la Iglesia, inseguro para el orden pol\u00edtico y social, aparece la medalla, o m\u00e1s amplia\u00admente, aparece la Milagrosa. \u00bfQu\u00e9 iba a representar la Milagrosa para esos cat\u00f3licos, para esos hijos de San Vicente, amedrenta\u00addos, temerosos, apesadumbrados? \u00bfQu\u00e9 iba a darles?<\/p>\n<p>Vamos a empezar por una afirmaci\u00f3n sencill\u00edsima de los he\u00adchos: la rapid\u00edsima difusi\u00f3n de la medalla y de la noticia de las apariciones.<\/p>\n<p>Seg\u00fan la encuesta can\u00f3nica del Arzobispado de Par\u00eds, en los cuatro a\u00f1os transcurridos desde la acu\u00f1aci\u00f3n de las primeras me\u00addallas en junio de 1832 y la fecha de la encuesta, 1836, se hab\u00edan acu\u00f1ado unos doce millones de medallas, m\u00e1s de doce millones de medallas&#8230; Y en los dos a\u00f1os de la edici\u00f3n del librito con la his\u00adtoria de las apariciones se hab\u00edan editado al menos 117.695 ejem\u00adplares. En 1833, como hemos visto ya, ya hab\u00eda llegado a Espa\u00f1a.<\/p>\n<p>Hab\u00eda, pues, en el ambiente una avidez de noticia mariana, de ayuda sobrenatural, de protecci\u00f3n, de apoyo para un esfuerzo de recuperaci\u00f3n cristiana de la sociedad.<\/p>\n<p>Pues bien, esa triple avidez era la que iba a saciar la Mila\u00adgrosa.<\/p>\n<p>Hay una cosa evidente, y es que la Milagrosa el primer papel que cumple, que basta un simple an\u00e1lisis de los hechos para con\u00advencerse de ello, es el de reanimar el movimiento mariano de la Iglesia: reanimarlo primero por el contenido, el mensaje, el con\u00adtenido doctrinal de la medalla, en el cual yo no me voy a exten\u00adder, porque todos lo conocemos, que condensa en un s\u00edmbolo toda la especulaci\u00f3n teol\u00f3gica en torno a Mar\u00eda Sant\u00edsima; en segundo lugar, porque desencadena, pone en marcha en el siglo XIX el movimiento en favor de la proclamaci\u00f3n del dogma de la -Inma\u00adculada. No hay historiador de la Iglesia, pr\u00e1cticamente no hay ning\u00fan historiador de la Iglesia que, al hacer la historia de la proclamaci\u00f3n del dogma de la Inmaculada, no diga que el origen del movimiento en el siglo XIX hay que encontrarlo en las apari\u00adciones de la Rue du Bac. Lo mismo que Garc\u00eda Villoslada, pr\u00e1c\u00adticamente en todos, incluso en el Diccionario de la Teolog\u00eda Ca\u00adt\u00f3lica. Y es que es un hecho claro. La doctrina de la Inmaculada no se descubre en el siglo XIX, era muy antigua en la Iglesia. Pero cuando resurge la fe, y cuando resurge el deseo del pueblo cristia\u00adno de ver proclamado este dogma, es a partir de las apariciones. Porque, claro est\u00e1, la Medalla, las apariciones reafirman de una manera solemne, casi descarada, la doctrina de la Inmaculada Concepci\u00f3n. Ah\u00ed est\u00e1, grabada en s\u00edmbolo, pisando con su pie la cabeza de la serpiente, y ah\u00ed est\u00e1 dicho expresamente en letra: \u00abOh Mar\u00eda concebida sin pecado&#8230;\u00bb. Y entonces, claro, se produ\u00adce el movimiento que va ganando amplitud. Las s\u00faplicas que se dirigen a la Santa Sede \u2014este estudio no est\u00e1 hecho, y a m\u00ed, claro est\u00e1, tampoco me ha sido posible hacerlo, \u00a0pero, por lo menos, s\u00e9 de bastantes de ellas, que las s\u00faplicas que dirigen los obispos, son bastantes los obispos, y no s\u00f3lo franceses, que al suplicar la definici\u00f3n dogm\u00e1tica de la Inmaculada aducen el hecho de las apariciones de la Virgen Milagrosa en la calle de Bac a Santa. Ca\u00adtalina Labour\u00e9, o a una Hermanita de la Caridad. En este sentido podemos decir que es responsable la Milagrosa \u2014las apariciones de la Milagrosa\u2014 de la definici\u00f3n de 1854.<\/p>\n<p>Y un tercer aspecto: la devoci\u00f3n mariana que suscita. Inicia una nueva era de devoci\u00f3n mariana la Milagrosa. Surgen las asociaciones marianas. En Nuestra Se\u00f1ora de las Victorias, en Par\u00eds, que ya sabemos que la Asociaci\u00f3n de Nuestra Se\u00f1ora de las Victorias surge, porque el p\u00e1rroco, el que era p\u00e1rroco precisa\u00admente del territorio donde est\u00e1 la casa de las Hijas de la Caridad hab\u00eda sido trasladado, despu\u00e9s de las apariciones, a Nuestra Se\u00ad\u00f1ora de las Victorias, y entonces \u00e9l tiene la idea de poner en Nuestra Se\u00f1ora de las Victorias una imagen de estas recientes apariciones, y se hace la asociaci\u00f3n, que en realidad es una aso\u00adciaci\u00f3n de la Milagrosa.<\/p>\n<p>En Madrid esto es en 1836\u2014, en Madrid, a partir de 1840, y despu\u00e9s ya confirmada en 1845, y establecida de una manera definitiva en 1847, la asociaci\u00f3n, en un tiempo tan famosa y tan numerosa, de la parroquia de San Gin\u00e9s, que fue la primera asociaci\u00f3n. Y luego ya, lo que todos conocemos, la Asociaci\u00f3n de Hijos e Hijas de Mar\u00eda, la Asociaci\u00f3n de la Medalla, la Legi\u00f3n de Mar\u00eda, que se re\u00fane siempre en torno \u00fc una imagen de la Mila\u00adgrosa, y, por supuesto \u2014ya las he citado , las Milicias de Mar\u00eda del Padre Kolbe.<\/p>\n<p>No son los \u00fanicos movimientos; habr\u00eda que hablar de otros muchos. Lo que quiero es simplemente hacer ver c\u00f3mo quiz\u00e1 la primera funci\u00f3n, la primera misi\u00f3n hist\u00f3rica cumplida por la Milagrosa es esta reanimaci\u00f3n de la devoci\u00f3n a Mar\u00eda en una \u00e9poca que necesita una nueva espiritualidad, una nueva manera de ver a Mar\u00eda; quiz\u00e1 en una \u00e9poca rom\u00e1ntica, fervorosa, tierna aparece la imagen de la medalla.<\/p>\n<p>M\u00e1s ampliamente cumple una segunda misi\u00f3n la Medalla Mi\u00adlagrosa. Porque a ella se debe, en parte, el inicio de un movi\u00admiento de recuperaci\u00f3n en la Iglesia, de nuevas bases para un cristianismo de nuestro tiempo.<\/p>\n<p>Empecemos por los milagros: es lo m\u00e1s llamativo de la Mila\u00adgrosa; por eso se llama as\u00ed. \u00bfQu\u00e9 son los milagros? \u00bfQu\u00e9 repre\u00adsentan los milagros, esos milagros que prodiga la Virgen a trav\u00e9s de la Medalla?&#8230; Pero son decenas, son cientos de milagros obrados en diversas partes del mundo, continuamente: es una es\u00adpecie de lluvia&#8230;<\/p>\n<p>Desde luego, hay que atenerse a los hechos. Son innegables. Est\u00e1n, en muchos casos, atestiguados m\u00e1s all\u00e1 de toda duda ra\u00adzonable. Est\u00e1n muchos de ellos reconocidos por la Iglesia. Son admirables, extraordinarios. Son de todas clases: curaciones ma\u00adteriales, conversiones, etc. \u00bfPara qu\u00e9 o por qu\u00e9 los milagros? \u00bfTienen una raz\u00f3n de ser estos milagros obrados en pleno si\u00adglo XIX?&#8230;<\/p>\n<p>Los milagros, no lo olvidemos, son signos \u2014as\u00ed los llama siem\u00adpre el Evangelio de San Juan\u2014, son signos de la presencia con\u00adsoladora de Dios. Y as\u00ed es como los interpreta la Iglesia, el pue\u00adblo cristiano en el siglo XIX los milagros de la Milagrosa. Es decir, que se toma conciencia de que Dios est\u00e1 presente en esos tiempos, que ellos creen tan duros, tan calamitosos, tan -negros para la Iglesia; de que Dios no ha abandonado a la Iglesia. Die\u00adron a los cristianos de la \u00e9poca la seguridad de la protecci\u00f3n ce\u00adleste, de la ayuda de Dios a trav\u00e9s de su Madre. Ese es, en cuanto nosotros podemos alcanzarlo, el por qu\u00e9 de los milagros.<\/p>\n<p>Las apariciones de la Milagrosa les da tambi\u00e9n a los cristianos de la \u00e9poca un distintivo. Los cristianos se reconocen, se agrupan. La Medalla les da una bandera, y m\u00e1s la Inmaculada, cuando la Medalla haya cumplido su primera gran misi\u00f3n: hacer que se pro\u00adclame el dogma de la Inmaculada; y una plegaria, la jaculatoria, tan f\u00e1cil de repetir en una \u00e9poca de civilizaci\u00f3n de aglomeraciones, que empieza, y de prisa, con tan poco espacio y tan poco tiem\u00adpo para la oraci\u00f3n sosegada.<\/p>\n<p>Y as\u00ed empieza el despegue, la recuperaci\u00f3n de la Iglesia a par\u00adtir de 1830.<\/p>\n<p>Al a\u00f1o siguiente es elegido Gregorio XVI, el 2 de febrero de 1831. Gregorio XVI es ya todo lo contrario de los Papas pusi\u00adl\u00e1nimes del siglo XVIII, estos Papas que estaban como totalmente desbordados por la marea del racionalismo de la Ilustraci\u00f3n; es\u00adtos Papas que se dejan llevar incluso \u2014quiz\u00e1 no tendr\u00edan otro re\u00admedio, \u00bfno?; no se trata de juzgarlos\u2014, se dejan llevar incluso a la supresi\u00f3n de la Compa\u00f1\u00eda de Jes\u00fas.<\/p>\n<p>Gregorio XVI inicia un nuevo estilo de pontificado. Es el Papa de la reacci\u00f3n cat\u00f3lica. Puede hoy parecernos esa reacci\u00f3n destemplada; puede parecernos, en el caso de su sucesor, excesi\u00adva; puede parecernos incomprensiva del mundo que tiene delan\u00adte; es el Syllabus. Pero lo cierto es que esa actitud de Grego\u00adrio XVI y de P\u00edo IX tienen la virtualidad de dar fortaleza a los cat\u00f3licos en unas nuevas circunstancias. Y no olvidemos: P\u00edo IX es el Papa que proclama el dogma de la Inmaculada. Y es hacia 1830 cuando surgen una serie de iniciativas carism\u00e1ticas: el gran esfuerzo misioneros: el Africa, la India, China; el renacimiento lit\u00fargico rom\u00e1ntico, con Dom Gu\u00e9ranger; las nuevas congregacio\u00adnes religiosas, muchas de las cuales introducen en su h\u00e1bito la Medalla Milagrosa; las dem\u00e1s apariciones, que ser\u00e1n como un eco de la de 1830: Lourdes&#8230; Se inicia el catolicismo social por obra de Ozanam&#8230;<\/p>\n<p>No quiero decir que todo este movimiento haya sido produ\u00adcido por la Medalla; pero lo que s\u00ed es claro es que la Medalla est\u00e1 ah\u00ed presente, la Milagrosa est\u00e1 ah\u00ed presente, y es una parte de ese gran despegue cat\u00f3lico, que nos va a llevar al catolicismo de nuestros d\u00edas, a un catolicismo presente en el mundo real en que est\u00e1 insertado, y que, desde luego, en muchos casos es la fuerza impulsora.<\/p>\n<p>Y una tercera misi\u00f3n hist\u00f3rica de la Medalla Milagrosa, de la Milagrosa, en general: es el instrumento de la reconstrucci\u00f3n de la doble familia vicenciana; ante todo, de la reconstrucci\u00f3n ins\u00adtitucional, que llega en el momento preciso. Ya he dicho antes, cuando con el reciente nombramiento del primer superior general, y la m\u00e1s reciente elecci\u00f3n del segundo, despu\u00e9s de la revoluci\u00f3n, ambas congregaciones reanudan su vida corporativa, y est\u00e1n ame\u00adnazadas de nuevos peligros, est\u00e1 unida la fecha de las apariciones a la traslaci\u00f3n de las reliquias, que es sentida \u2014os lo indicaba ya antes\u2014 como una vuelta del fundador, y que realmente vuelve para poner en marcha su obra. Ahora se est\u00e1 todav\u00eda, a la altura de 1830, en una restauraci\u00f3n de ambas congregaciones que es pu\u00adramente una vuelta al pasado, y esto va a durar pr\u00e1cticamente hasta 1843. Se quiere reconstruir la doble familia, y naturalmente, como siempre ocurre en esos casos, no se encuentra m\u00e1s que volver a hacer lo que hab\u00eda, volver a poner lo que hab\u00eda. Pues es curioso que el hombre que va a iniciar la restauraci\u00f3n de otra ma\u00adnera, restauraci\u00f3n como recreaci\u00f3n, casi como nueva construc\u00adci\u00f3n, el Padre Juan Bautista Etienne, est\u00e1 presente desde el pri\u00admer momento en las apariciones, es testigo, con el Padre Aladel, en el proceso; solicitar\u00e1 \u00e9l el que se conceda el decir \u00abet Imma\u00adculatam\u00bb en el prefario de la Virgen, y el \u00abRegina sine labe con\u00adcepta\u00bb en la letan\u00eda; ser\u00e1 \u00e9l quien funde los Hijos de Mar\u00eda; escribir\u00e1 la primera circular sobre la Medalla&#8230; Pues bien, ya les digo, Etienne, como Superior General de la Congregaci\u00f3n de la Misi\u00f3n y de las Hijas de la Caridad, ser\u00e1 el impulsor de la restau\u00adraci\u00f3n, equivalente casi a una nueva fundaci\u00f3n. Sin duda, la figura es discutible desde otros muchos puntos de vista; pero el hecho en s\u00ed de la grandeza de este hombre, que vuelve a hacer marchar un organismo muerto, es innegable.<\/p>\n<p>Y la reconstrucci\u00f3n espiritual, m\u00e1s importante, que era, y se\u00adguir\u00e1 siendo despu\u00e9s, muy necesaria. Figur\u00e9monos en 1830 la can\u00adtidad de Misioneros e Hijas de la Caridad que han estado ausen\u00adtes durante a\u00f1os de la vida de comunidad, una vida de comuni\u00addad perdida, ausencia por completo de lectura, de la tradici\u00f3n de la propia espiritualidad&#8230; Ha sido un corte realmente grave.<\/p>\n<p>Y la Milagrosa va a volver a poner en marcha esa espiritua\u00adlidad. En primer lugar, porque hay unas recomendaciones con\u00adcretas para ambas familias, pero que quiz\u00e1 son lo de menos; lo que pasa principalmente es que tanto las Hijas de la Caridad como los Padres Pa\u00fales toman conciencia de que se les ha dispensado una distinci\u00f3n en cierto sentido, recobran personalidad\u2014; de que se les ha confiado una misi\u00f3n; de que se les ha dado una medalla como signo: los milagros&#8230; Todo esto despierta el fervor y le confiere intrepidez a la doble Congregaci\u00f3n. Quiz\u00e1, quiz\u00e1 todas las consecuencias que se derivan de la Medalla no todas son favora\u00adbles. Se ha dicho \u2014aunque yo lo creo muy discutible\u2014 que la Mi\u00adlagrosa desfigura, hasta cierto punto, por los extremos o los exce\u00adsos a que se llega, la espiritualidad propiamente vicenciana de ambas comunidades. Puede que haya algo de verdad en eso; pero esto no puede hacernos olvidar que, sin embargo, es la Milagrosa la que vuelve a hacer posible en absoluto una espiritualidad vicenciana. Y m\u00e1s importante todav\u00eda, la Milagrosa confiere a ambas familias la proyecci\u00f3n apost\u00f3lica. Las apariciones dotan a las Hijas de la Caridad y a los Padres Pa\u00fales de un instrumento de influencia apost\u00f3lica, que no ten\u00edan, que no hab\u00edan tenido, sobre la juven\u00adtud: los Hijos y las Hijas de Mar\u00eda, en una \u00e9poca en que las Hijas de la Caridad se iban a proyectar mucho m\u00e1s que antes sobre la juventud por medio de los colegios y orfanatos. Nunca se valorar\u00e1 bien lo que las congregaciones marianas han signifi\u00adcado como instrumento de apostolado de los Padres Pa\u00fales y de las Hijas de la Caridad. Y \u00e9ste se debe a la Milagrosa. Les provee de un instrumento, y de un instrumento propio para la \u00e9poca; de un instrumento de apostolado para con los enfermos y heri\u00addos&#8230; En los hospitales, en los frentes de combate, las Hermanas, sobre todo, han cre\u00eddo en la Medalla, y la han usado, quiz\u00e1 in\u00adcluso han abusado de ella; pero lo cierto es que ha sido el medio que ten\u00eda a mano de una manera f\u00e1cil la Hermana de hacer apos\u00adtolado, y que en muchos casos este apostolado ha sido muy aut\u00e9n\u00adtico objetivamente, y muy eficaz objetivamente.<\/p>\n<p>Lo mismo para los Padres Pa\u00fales la Milagrosa ha sido tam\u00adbi\u00e9n instrumento de apostolado en las misiones, en las misiones del siglo XIX y del siglo XX; y el confesonario&#8230; Han adquirido un nuevo matiz. Y ha dado, yo dir\u00eda, valent\u00eda a unos hombres que, en el momento, sobre todo, en que aparece la Milagrosa, se encuentran como un poco desbordados.<\/p>\n<p>En la homil\u00eda que P\u00edo XII pronunci\u00f3, y a la que ya he aludido, el d\u00eda de la canonizaci\u00f3n de Santa Catalina, el Papa declaraba, refiri\u00e9ndose a la vidente de la Milagrosa: \u00abSe le conf\u00eda una misi\u00f3n que ha de ser no solamente transmitida, sino que ha de tener cum\u00adplimiento en su d\u00eda: reanimar el fervor entibiado de la doble fami\u00adlia del Santo de la Caridad, sumergir el mundo entero en un dilu\u00advio de peque\u00f1as medallas portadoras de todas las misericordias espirituales y corporales de la Inmaculada, y suscitar una asociaci\u00f3n piadosa de Hijas de Mar\u00eda para salvaguarda y santificaci\u00f3n de las j\u00f3venes\u00bb.<\/p>\n<p>Yo tengo que confesar que esas palabras del Papa P\u00edo XII, le\u00ed\u00addas en mi juventud quiz\u00e1 un poco precipitadamente, y rele\u00eddas despu\u00e9s varias veces con \u00e1nimo de reflexi\u00f3n, se encuentra con\u00addensadamente el germen de esta exposici\u00f3n m\u00eda, que no ha que\u00adrido ser sino un comentario documentado de las afirmaciones del Papa. Ojal\u00e1 que haya acertado a hacerlo con un m\u00ednimo de rigor y de fuerza probatoria.<\/p>\n<p>Gracias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amadas Hermanas, se\u00f1ores y amados sacerdotes: El t\u00edtulo de la conferencia quiz\u00e1 pueda parecer a algunos ex\u00adcesivamente ambicioso: LA MISION HISTORICA DE LA MILA\u00adGROSA. En realidad a m\u00ed tambi\u00e9n me lo parece, sobre todo una &#8230; <a href=\"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":402653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[168,161,190,143],"class_list":["post-109333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-virgen-maria","tag-argel","tag-etienne","tag-rue-du-bac","tag-san-lazaro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Misi\u00f3n hist\u00f3rica de La Milagrosa - Somos Vicencianos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Misi\u00f3n hist\u00f3rica de La Milagrosa - Somos Vicencianos\" \/>\n<meta property=\"og:description\" content=\"Amadas Hermanas, se\u00f1ores y amados sacerdotes: El t\u00edtulo de la conferencia quiz\u00e1 pueda parecer a algunos ex\u00adcesivamente ambicioso: LA MISION HISTORICA DE LA MILA\u00adGROSA. En realidad a m\u00ed tambi\u00e9n me lo parece, sobre todo una ... Read More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Somos Vicencianos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeAreVincentians\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/JavierChento\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-27T10:55:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2018\/11\/La-milagrosa3.jpg?fit=670%2C430\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/javierchento\" \/>\n<meta name=\"twitter:site\" content=\"@WeVincentians\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Javier Fern\u00e1ndez Chento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"26 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/\"},\"author\":{\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\"},\"headline\":\"Misi\u00f3n hist\u00f3rica de La Milagrosa\",\"datePublished\":\"2022-11-27T10:55:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/\"},\"wordCount\":6174,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2018\\\/11\\\/La-milagrosa3.jpg?fit=670%2C430\",\"keywords\":[\"Argel\",\"Etienne\",\"Rue du Bac\",\"San L\u00e1zaro\"],\"articleSection\":[\"Virgen Mar\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/\",\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/\",\"name\":\"Misi\u00f3n hist\u00f3rica de La Milagrosa - Somos Vicencianos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2018\\\/11\\\/La-milagrosa3.jpg?fit=670%2C430\",\"datePublished\":\"2022-11-27T10:55:34+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2018\\\/11\\\/La-milagrosa3.jpg?fit=670%2C430\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2018\\\/11\\\/La-milagrosa3.jpg?fit=670%2C430\",\"width\":670,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vincentians.com\\\/es\\\/mision-historica-de-la-milagrosa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Misi\u00f3n hist\u00f3rica de La Milagrosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"name\":\"Somos Vicencianos\",\"description\":\"Know more to serve more\",\"publisher\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vincentians.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#organization\",\"name\":\"The Vincentian Network\",\"url\":\"https:\\\/\\\/vincentians.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vincentians.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/06\\\/Vincentian-Network-logo-big.png?fit=778%2C778\",\"width\":778,\"height\":778,\"caption\":\"The Vincentian Network\"},\"image\":{\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeAreVincentians\\\/\",\"https:\\\/\\\/x.com\\\/WeVincentians\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vincentians.com\\\/es\\\/#\\\/schema\\\/person\\\/9623ef4d9aa3b2dfb8c061f1499288f2\",\"name\":\"Francisco Javier Fern\u00e1ndez Chento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g\",\"caption\":\"Francisco Javier Fern\u00e1ndez Chento\"},\"description\":\"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\\\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.\",\"sameAs\":[\"http:\\\/\\\/chento.org\",\"https:\\\/\\\/www.facebook.com\\\/JavierChento\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/javierchento\"],\"url\":\"http:\\\/\\\/vincentians.com\\\/es\\\/author\\\/chento\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Misi\u00f3n hist\u00f3rica de La Milagrosa - Somos Vicencianos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/","og_locale":"es_ES","og_type":"article","og_title":"Misi\u00f3n hist\u00f3rica de La Milagrosa - Somos Vicencianos","og_description":"Amadas Hermanas, se\u00f1ores y amados sacerdotes: El t\u00edtulo de la conferencia quiz\u00e1 pueda parecer a algunos ex\u00adcesivamente ambicioso: LA MISION HISTORICA DE LA MILA\u00adGROSA. En realidad a m\u00ed tambi\u00e9n me lo parece, sobre todo una ... Read More","og_url":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/","og_site_name":"Somos Vicencianos","article_publisher":"https:\/\/www.facebook.com\/WeAreVincentians\/","article_author":"https:\/\/www.facebook.com\/JavierChento","article_published_time":"2022-11-27T10:55:34+00:00","og_image":[{"width":670,"height":430,"url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2018\/11\/La-milagrosa3.jpg?fit=670%2C430","type":"image\/jpeg"}],"author":"Francisco Javier Fern\u00e1ndez Chento","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/javierchento","twitter_site":"@WeVincentians","twitter_misc":{"Escrito por":"Francisco Javier Fern\u00e1ndez Chento","Tiempo de lectura":"26 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/#article","isPartOf":{"@id":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/"},"author":{"name":"Francisco Javier Fern\u00e1ndez Chento","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2"},"headline":"Misi\u00f3n hist\u00f3rica de La Milagrosa","datePublished":"2022-11-27T10:55:34+00:00","mainEntityOfPage":{"@id":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/"},"wordCount":6174,"commentCount":0,"publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"image":{"@id":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2018\/11\/La-milagrosa3.jpg?fit=670%2C430","keywords":["Argel","Etienne","Rue du Bac","San L\u00e1zaro"],"articleSection":["Virgen Mar\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/","url":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/","name":"Misi\u00f3n hist\u00f3rica de La Milagrosa - Somos Vicencianos","isPartOf":{"@id":"https:\/\/vincentians.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/#primaryimage"},"image":{"@id":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2018\/11\/La-milagrosa3.jpg?fit=670%2C430","datePublished":"2022-11-27T10:55:34+00:00","breadcrumb":{"@id":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/#primaryimage","url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2018\/11\/La-milagrosa3.jpg?fit=670%2C430","contentUrl":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2018\/11\/La-milagrosa3.jpg?fit=670%2C430","width":670,"height":430},{"@type":"BreadcrumbList","@id":"http:\/\/vincentians.com\/es\/mision-historica-de-la-milagrosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vincentians.com\/es\/"},{"@type":"ListItem","position":2,"name":"Misi\u00f3n hist\u00f3rica de La Milagrosa"}]},{"@type":"WebSite","@id":"https:\/\/vincentians.com\/es\/#website","url":"https:\/\/vincentians.com\/es\/","name":"Somos Vicencianos","description":"Know more to serve more","publisher":{"@id":"https:\/\/vincentians.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vincentians.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vincentians.com\/es\/#organization","name":"The Vincentian Network","url":"https:\/\/vincentians.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","contentUrl":"https:\/\/i1.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/06\/Vincentian-Network-logo-big.png?fit=778%2C778","width":778,"height":778,"caption":"The Vincentian Network"},"image":{"@id":"https:\/\/vincentians.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WeAreVincentians\/","https:\/\/x.com\/WeVincentians"]},{"@type":"Person","@id":"https:\/\/vincentians.com\/es\/#\/schema\/person\/9623ef4d9aa3b2dfb8c061f1499288f2","name":"Francisco Javier Fern\u00e1ndez Chento","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/497d5cde87b4c3d097d0315953521681ba2cd523ee66e5077c3711f7021e65de?s=96&d=mm&r=g","caption":"Francisco Javier Fern\u00e1ndez Chento"},"description":"Director General y cofundador de La Red de Formaci\u00f3n Vicenciana. Javier es laico vicenciano, afiliado a la Congregaci\u00f3n de la Misi\u00f3n y miembro del Equipo de Misiones Populares de la provincia can\u00f3nica de Zaragoza (Espa\u00f1a) de la Congregaci\u00f3n de la Misi\u00f3n. Graduado en la Universidad Oberta de Catalunya con cuatro grados (Asistente de direcci\u00f3n, Gesti\u00f3n Administrativa, Recursos Humanos y Contabilidad Avanzada). Bil\u00edng\u00fce Espa\u00f1ol\/Ingl\u00e9s. gestiona y mantiene varias p\u00e1ginas web cristianas y vicencianas, incluida including La Red de Formaci\u00f3n Vicenciana, de la que es cofundador. Actualmente es responsable del \u00e1rea de Espa\u00f1ol de .famvin, la Red de Noticias de la Familia Vicenciana. Tambi\u00e9n es m\u00fasico cat\u00f3lico y ha editado varios discos. Es Director General y cofundador de Trovador, una reconocida compa\u00f1\u00eda discogr\u00e1fica critiana de Espa\u00f1a. Trabaja en las Tecnolog\u00edas de la Informaci\u00f3n, ofreciendo servicios de alojamiento, dise\u00f1o y mantenimiento Web, as\u00ed como asesoramiento, formaci\u00f3n y soluciones inform\u00e1ticas, gesti\u00f3n documental y digitalizaci\u00f3n de textos, edici\u00f3n y maquetaci\u00f3n de libros, revistas, flyers, etc.","sameAs":["http:\/\/chento.org","https:\/\/www.facebook.com\/JavierChento","https:\/\/x.com\/https:\/\/twitter.com\/javierchento"],"url":"http:\/\/vincentians.com\/es\/author\/chento\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2018\/11\/La-milagrosa3.jpg?fit=670%2C430","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7ETMF-srr","jetpack-related-posts":[{"id":117065,"url":"http:\/\/vincentians.com\/es\/la-basilica-de-la-milagrosa-madrid-tiene-larga-historia\/","url_meta":{"origin":109333,"position":0},"title":"La Bas\u00edlica de La Milagrosa en Madrid tiene larga historia","author":"Mitxel Olabu\u00e9naga","date":"03\/08\/2021","format":false,"excerpt":"Con motivo de sus Bodas de Oro vocacionales, el P. Eladio Ar\u00adn\u00e1iz hizo un viaje a Roma, y durante su estancia en la ciudad, el Papa P\u00edo X le recibi\u00f3 en audiencia. Luego, a su regreso a Espa\u00f1a, como Director de las Hijas de la Caridad de la entonces enorme\u2026","rel":"","context":"En \u00abHistoria de la Congregaci\u00f3n de la Misi\u00f3n en Espa\u00f1a\u00bb","block_context":{"text":"Historia de la Congregaci\u00f3n de la Misi\u00f3n en Espa\u00f1a","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-la-congregacion-de-la-mision-en-espana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/09\/enviados-evangelizar-pobres.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":387068,"url":"http:\/\/vincentians.com\/es\/la-basilica-parroquia-de-la-milagrosa-madrid\/","url_meta":{"origin":109333,"position":1},"title":"La Bas\u00edlica-Parroquia de La Milagrosa (Madrid)","author":"Mitxel Olabu\u00e9naga","date":"11\/02\/2016","format":false,"excerpt":"Una Iglesia dedicada a San Vicente de Paul Una vez terminada la casa de Garc\u00eda de Paredes, 45, la Comunidad de Misioneros Paules, cada d\u00eda m\u00e1s numerosa, echaba en falta una iglesia capaz para celebrar el culto divino. Se decidieron a edificar un templo en honor de San Vicente de\u2026","rel":"","context":"En \u00abHistoria de la Congregaci\u00f3n de la Misi\u00f3n en Espa\u00f1a\u00bb","block_context":{"text":"Historia de la Congregaci\u00f3n de la Misi\u00f3n en Espa\u00f1a","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-la-congregacion-de-la-mision-en-espana\/"},"img":{"alt_text":"msoFDCDE","src":"https:\/\/i0.wp.com\/vicencianos.org\/wp-content\/uploads\/2016\/02\/msoFDCDE-210x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":41796,"url":"http:\/\/vincentians.com\/es\/espiritualidad-vicenciana-milagrosa\/","url_meta":{"origin":109333,"position":2},"title":"Espiritualidad vicenciana: Milagrosa","author":"Francisco Javier Fern\u00e1ndez Chento","date":"28\/11\/2020","format":false,"excerpt":"Durante el tiempo de su seminario interno, que dur\u00f3 del 21 de abril de 1830 al 31 de enero de 1831, una Hija de la Caridad llamada Catalina Labour\u00e9 tuvo visiones del coraz\u00f3n de san Vicen\u00adte de Pa\u00fal, visiones del Se\u00f1or en la Eucarist\u00eda y visiones de la Virgen Sant\u00edsima.\u2026","rel":"","context":"En \u00abEspiritualidad vicenciana\u00bb","block_context":{"text":"Espiritualidad vicenciana","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/espiritualidad-vicenciana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/espiritualidad-vicenciana.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/espiritualidad-vicenciana.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/espiritualidad-vicenciana.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/espiritualidad-vicenciana.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/07\/espiritualidad-vicenciana.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":53290,"url":"http:\/\/vincentians.com\/es\/el-mensaje-de-rue-du-bac-vii-la-manifestacion-y-la-revelacion\/","url_meta":{"origin":109333,"position":3},"title":"El mensaje de Rue du Bac (VII. La manifestaci\u00f3n y la revelaci\u00f3n)","author":"Francisco Javier Fern\u00e1ndez Chento","date":"11\/11\/2023","format":false,"excerpt":"La existencia de las revelaciones privadas no puede ponerse en duda. La Sagrada Escritura, la Tradici\u00f3n y la Historia de la Iglesia cuentan casos claros de revelaciones privadas. Fue en el siglo xv cuando los te\u00f3logos, ante el problema de la canonizaci\u00f3n de los santos, sintieron la necesidad de elaborar\u2026","rel":"","context":"En \u00abVirgen Mar\u00eda\u00bb","block_context":{"text":"Virgen Mar\u00eda","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/virgen-maria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2022\/08\/imagen-1-2.jpg?fit=350%2C349&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":115978,"url":"http:\/\/vincentians.com\/es\/familia-vicenciana-y-medalla-milagrosa\/","url_meta":{"origin":109333,"position":4},"title":"Familia Vicenciana y Medalla Milagrosa","author":"Francisco Javier Fern\u00e1ndez Chento","date":"27\/11\/2022","format":false,"excerpt":"Lo que ha sido este legado desde 1830 El testimonio de la Historia nos dice que, si bien la Virgen se aparece a Santa Catalina Labour\u00e9, \u00e9sta, cumpliendo los deseos manifestados por la Madre de Dios, permanece oculta, desconocida, en el silencio m\u00e1s incomprensible; un silencio que a veces se\u2026","rel":"","context":"En \u00abVirgen Mar\u00eda\u00bb","block_context":{"text":"Virgen Mar\u00eda","link":"http:\/\/vincentians.com\/es\/category\/espiritualidad\/virgen-maria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&resize=700%2C400 2x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2016\/08\/hijas-caridad.jpg?fit=1200%2C630&resize=1050%2C600 3x"},"classes":[]},{"id":123811,"url":"http:\/\/vincentians.com\/es\/historia-de-los-paules-en-cuba-capitulo-ix-d\/","url_meta":{"origin":109333,"position":5},"title":"Historia de los PA\u00daLES en Cuba: Cap\u00edtulo IX (D)","author":"Mitxel Olabu\u00e9naga","date":"09\/10\/2022","format":false,"excerpt":"4. 1956. La Parroquia de la Milagrosa de Matanzas. Ya hemos le\u00eddo en p\u00e1rrafos anteriores que el Se\u00f1or Obispo hab\u00eda propuesto y dado permiso para construir una Iglesia y que la convertir\u00eda en Parroquia Ad nutun Santae Sedis (hasta que la Santa Sede lo cambie). Despu\u00e9s de las obras de\u2026","rel":"","context":"En \u00abHistoria de la Congregaci\u00f3n de la Misi\u00f3n\u00bb","block_context":{"text":"Historia de la Congregaci\u00f3n de la Misi\u00f3n","link":"http:\/\/vincentians.com\/es\/category\/historia-de-la-familia-vicenciana\/historia-de-la-congregacion-de-la-mision\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/Entorno-de-San-Vicente-6-Berceau.jpg?fit=640%2C421&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/Entorno-de-San-Vicente-6-Berceau.jpg?fit=640%2C421&resize=350%2C200 1x, https:\/\/i0.wp.com\/vincentians.com\/es\/wp-content\/uploads\/sites\/11\/2013\/04\/Entorno-de-San-Vicente-6-Berceau.jpg?fit=640%2C421&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/109333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/comments?post=109333"}],"version-history":[{"count":2,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/109333\/revisions"}],"predecessor-version":[{"id":402654,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/posts\/109333\/revisions\/402654"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media\/402653"}],"wp:attachment":[{"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/media?parent=109333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/categories?post=109333"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vincentians.com\/es\/wp-json\/wp\/v2\/tags?post=109333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}